{"id":41126,"date":"2015-04-05T12:56:47","date_gmt":"2015-04-05T16:56:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n.jpg"},"modified":"2015-04-05T12:56:47","modified_gmt":"2015-04-05T16:56:47","slug":"11130294_10153227752620645_7303672741367015676_n","status":"inherit","type":"attachment","link":"https:\/\/sosuaonline.net\/inicio\/desaprensivos-incendian-neumaticos-en-el-vertedero-de-sosua\/11130294_10153227752620645_7303672741367015676_n\/","title":{"rendered":"11130294_10153227752620645_7303672741367015676_n"},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-41126","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"300\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n-224x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n-224x300.jpg 224w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n-56x75.jpg 56w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n.jpg 403w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":403,"height":539,"file":"2015\/04\/11130294_10153227752620645_7303672741367015676_n.jpg","sizes":{"thumbnail":{"file":"11130294_10153227752620645_7303672741367015676_n-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n-150x150.jpg"},"medium":{"file":"11130294_10153227752620645_7303672741367015676_n-224x300.jpg","width":224,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n-224x300.jpg"},"wc-dynamic-gallery-thumb":{"file":"11130294_10153227752620645_7303672741367015676_n-56x75.jpg","width":56,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n-56x75.jpg"},"yarpp-thumbnail":{"file":"11130294_10153227752620645_7303672741367015676_n-120x120.jpg","width":120,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n-120x120.jpg"},"full":{"file":"11130294_10153227752620645_7303672741367015676_n.jpg","width":403,"height":539,"mime_type":"image\/jpeg","source_url":"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":41104,"source_url":"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/04\/11130294_10153227752620645_7303672741367015676_n.jpg","filename":"11130294_10153227752620645_7303672741367015676_n.jpg","filesize":42190,"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/41126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=41126"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":41104,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/41104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}