{"id":100079,"date":"2024-11-08T07:06:28","date_gmt":"2024-11-08T11:06:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100079"},"modified":"2024-11-08T07:06:39","modified_gmt":"2024-11-08T11:06:39","slug":"mao-detienen-en-la-rd-a-otros-22-haitianos-indocumentados","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/mao-detienen-en-la-rd-a-otros-22-haitianos-indocumentados\/","title":{"rendered":"MAO: Detienen en la RD a otros 22 haitianos indocumentados"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"182\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/13f16316-6ca8-4771-a36a-766eeb2f9c6d-e1730986156749-300x182-1.jpg\" alt=\"\" class=\"wp-image-100080\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">MAO, Rep\u00fablica Dominicana.- El Ej\u00e9rcito de Rep\u00fablica Dominicana detuvo dos veh\u00edculos que transportaban 22 haitianos indocumentados en la comunidad Pe\u00f1uelas, del municipio Esperanza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los extranjeros eran trasladados en una Toyota Highlander, franqueada por un carro Hyundai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los conductores abandonaron los veh\u00edculos y huyeron cuando se percataron de la presencia de los militares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los veh\u00edculos fueron llevados a la sede de la Cuarta Brigada de Infanter\u00eda del Ej\u00e9rcito y los extranjeros entregados a la Direcci\u00f3n General de Migraci\u00f3n (DGM).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MAO, Rep\u00fablica Dominicana.- El Ej\u00e9rcito de Rep\u00fablica Dominicana detuvo dos veh\u00edculos que transportaban 22 haitianos indocumentados en la comunidad Pe\u00f1uelas, del municipio Esperanza. Los extranjeros eran trasladados en una Toyota Highlander, franqueada por un carro Hyundai. Los conductores abandonaron los veh\u00edculos y huyeron cuando se percataron de la presencia de los militares. Los veh\u00edculos fueron llevados a la sede de la Cuarta Brigada de Infanter\u00eda del Ej\u00e9rcito y los extranjeros entregados a la Direcci\u00f3n General de Migraci\u00f3n (DGM).<\/p>\n","protected":false},"author":9,"featured_media":100080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-100079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100079"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100079\/revisions"}],"predecessor-version":[{"id":100081,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100079\/revisions\/100081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100080"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}