{"id":100101,"date":"2024-11-09T07:12:32","date_gmt":"2024-11-09T11:12:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100101"},"modified":"2024-11-09T07:12:34","modified_gmt":"2024-11-09T11:12:34","slug":"abinader-inaugurara-obras-este-sabado-maria-trinidad-sanchez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/abinader-inaugurara-obras-este-sabado-maria-trinidad-sanchez\/","title":{"rendered":"Abinader inaugurar\u00e1 obras este s\u00e1bado Mar\u00eda Trinidad S\u00e1nchez"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-10-11-at-2.24.04-PM-e1728739868944.jpeg\" alt=\"\" class=\"wp-image-100102\" width=\"247\" height=\"178\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-10-11-at-2.24.04-PM-e1728739868944.jpeg 700w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-10-11-at-2.24.04-PM-e1728739868944-300x216.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-10-11-at-2.24.04-PM-e1728739868944-600x432.jpeg 600w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El presidente dominicano, Luis Abinader, inaugurar\u00e1 varias obras este s\u00e1bado en la provincia Mar\u00eda Trinidad S\u00e1nchez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La agenda del gobernante iniciar\u00e1 el s\u00e1bado a las 11:00 de la ma\u00f1ana con la supervisi\u00f3n del avance de los trabajos en el malec\u00f3n de Nagua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con posterioridad, encabezar\u00e1 la inauguraci\u00f3n del polideportivo en La Capitalista y luego presidir\u00e1 la apertura de las oficinas del Banco de Reservas en el centro de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>REUNION CON REPRESENTANTE SOCIEDAD CIVIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s adelante, el dignatario dialogar\u00e1 con representantes de la comunidad y de la sociedad civil de la provincia, en la Universidad Aut\u00f3noma de Santo Domingo (UASD).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, inaugurar\u00e1 el remozamiento del Hospital Municipal Dr. Virgilio A. Garc\u00eda de Cabrera y la remodelaci\u00f3n de la Laguna Gri Gri en R\u00edo San Juan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para culminar su agenda en esta provincia, dejar\u00e1 en funcionamiento una Guarder\u00eda Infantil Tipo A.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DOMINGO EN ESPAILLAT<br \/><\/strong><br \/>El domingo, el jefe de Estado se trasladar\u00e1 a la provincia Espaillat, donde encabezar\u00e1 el acto de graduaci\u00f3n del curso b\u00e1sico de formaci\u00f3n policial en el municipio de Gaspar Hern\u00e1ndez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El presidente dominicano, Luis Abinader, inaugurar\u00e1 varias obras este s\u00e1bado en la provincia Mar\u00eda Trinidad S\u00e1nchez. La agenda del gobernante iniciar\u00e1 el s\u00e1bado a las 11:00 de la ma\u00f1ana con la supervisi\u00f3n del avance de los trabajos en el malec\u00f3n de Nagua. Con posterioridad, encabezar\u00e1 la inauguraci\u00f3n del polideportivo en La Capitalista y luego presidir\u00e1 la apertura de las oficinas del Banco de Reservas en el centro de la ciudad. REUNION CON REPRESENTANTE SOCIEDAD CIVIL M\u00e1s adelante, el dignatario dialogar\u00e1 con representantes de la comunidad y de la sociedad civil de la provincia, en la Universidad Aut\u00f3noma de Santo Domingo (UASD). Asimismo, inaugurar\u00e1 el remozamiento del Hospital Municipal Dr. Virgilio A. Garc\u00eda de Cabrera y la remodelaci\u00f3n de la Laguna Gri Gri en R\u00edo San Juan. Para culminar su agenda en esta provincia, dejar\u00e1 en funcionamiento una Guarder\u00eda Infantil Tipo A. DOMINGO EN ESPAILLATEl domingo, el jefe de Estado se trasladar\u00e1 a la provincia Espaillat, donde encabezar\u00e1 el acto de graduaci\u00f3n del curso b\u00e1sico de formaci\u00f3n policial en el municipio de Gaspar Hern\u00e1ndez.<\/p>\n","protected":false},"author":9,"featured_media":100102,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-100101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100101"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100101\/revisions"}],"predecessor-version":[{"id":100103,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100101\/revisions\/100103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100102"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}