{"id":100105,"date":"2024-11-10T06:44:41","date_gmt":"2024-11-10T10:44:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100105"},"modified":"2024-11-10T06:44:57","modified_gmt":"2024-11-10T10:44:57","slug":"rubby-perez-estrena-album-vivo-bajo-direccion-de-manuel-tejada","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/rubby-perez-estrena-album-vivo-bajo-direccion-de-manuel-tejada\/","title":{"rendered":"Rubby P\u00e9rez estrena \u00e1lbum vivo bajo direcci\u00f3n de Manuel Tejada"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/rubb-300x169-1.png\" alt=\"\" class=\"wp-image-100106\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El ic\u00f3nico merenguero dominicano Rubby P\u00e9rez vuelve a sorprender a sus seguidores con el estreno de su m\u00e1s reciente \u00e1lbum en vivo \u201cMerengue Jazz Sessions Vol. 1\u201d, dirigido por el prestigioso maestro Manuel Tejada, quien ofrece un enfoque novedoso y refrescante en la carrera del artista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este material, de larga duraci\u00f3n que fusiona los ritmos del merengue con toques de jazz en una propuesta que promete redefinir el g\u00e9nero, presenta una combinaci\u00f3n \u00fanica que resalta la autenticidad y el virtuosismo de \u201cLa Voz M\u00e1s Alta del Merengue\u201d como se le conoce a Rubby, consolidando su capacidad de reinventarse mientras mantiene su esencia inconfundible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los seguidores ya pueden disfrutar de algunos temas del \u00e1lbum, mientras que los audiovisuales estar\u00e1n disponibles en los pr\u00f3ximos d\u00edas, permitiendo a los fans experimentar de cerca la energ\u00eda y emotividad de sus presentaciones en vivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de tres exitosas presentaciones internacionales bajo el concepto \u201cFree Cover\u201d en Houston, Hollywood y Orlando, el artista ha llevado su m\u00fasica a nuevos niveles de innovaci\u00f3n, ofreciendo una versi\u00f3n del merengue que resalta su capacidad vocal y el talento instrumental de su equipo, bajo la batuta de Tejada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas actuaciones han sido aclamadas por el p\u00fablico y han mantenido el \u00e9xito de su formato en vivo, reafirmando su versatilidad y su conexi\u00f3n con audiencias internacionales. Entre los temas destacados de este \u00e1lbum, \u201cY No Voy a Llorar\u201d ha capturado la atenci\u00f3n del p\u00fablico, posicion\u00e1ndose en el puesto 61 del top 100 de las canciones m\u00e1s escuchadas en YouTube esta semana. La profunda interpretaci\u00f3n de P\u00e9rez ha sido aplaudida en redes sociales, reflejando la vigencia de su arte y su inquebrantable v\u00ednculo con sus seguidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, como parte de los homenajes a su carrera, P\u00e9rez ser\u00e1 exaltado en la Galer\u00eda del Merengue de DINAFOLK del Ministerio de Cultura, a prop\u00f3sito de la celebraci\u00f3n del D\u00eda Nacional del Merengue, el pr\u00f3ximo 26 de noviembre. Este reconocimiento subraya su invaluable aporte a la m\u00fasica dominicana y su rol como referente indiscutible del merengue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este nuevo \u00e1lbum en vivo, bajo la direcci\u00f3n de Manuel Tejada, representa no solo una celebraci\u00f3n de la trayectoria de Rubby, sino tambi\u00e9n una invitaci\u00f3n a explorar nuevos caminos en el merengue, ampliando los horizontes del g\u00e9nero en un contexto moderno y vanguardista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El ic\u00f3nico merenguero dominicano Rubby P\u00e9rez vuelve a sorprender a sus seguidores con el estreno de su m\u00e1s reciente \u00e1lbum en vivo \u201cMerengue Jazz Sessions Vol. 1\u201d, dirigido por el prestigioso maestro Manuel Tejada, quien ofrece un enfoque novedoso y refrescante en la carrera del artista. Este material, de larga duraci\u00f3n que fusiona los ritmos del merengue con toques de jazz en una propuesta que promete redefinir el g\u00e9nero, presenta una combinaci\u00f3n \u00fanica que resalta la autenticidad y el virtuosismo de \u201cLa Voz M\u00e1s Alta del Merengue\u201d como se le conoce a Rubby, consolidando su capacidad de reinventarse mientras mantiene su esencia inconfundible. Los seguidores ya pueden disfrutar de algunos temas del \u00e1lbum, mientras que los audiovisuales estar\u00e1n disponibles en los pr\u00f3ximos d\u00edas, permitiendo a los fans experimentar de cerca la energ\u00eda y emotividad de sus presentaciones en vivo. A trav\u00e9s de tres exitosas presentaciones internacionales bajo el concepto \u201cFree Cover\u201d en Houston, Hollywood y Orlando, el artista ha llevado su m\u00fasica a nuevos niveles de innovaci\u00f3n, ofreciendo una versi\u00f3n del merengue que resalta su capacidad vocal y el talento instrumental de su equipo, bajo la batuta de Tejada. Estas actuaciones han sido aclamadas por el p\u00fablico y han mantenido el \u00e9xito de su formato en vivo, reafirmando su versatilidad y su conexi\u00f3n con audiencias internacionales. Entre los temas destacados de este \u00e1lbum, \u201cY No Voy a Llorar\u201d ha capturado la atenci\u00f3n del p\u00fablico, posicion\u00e1ndose en el puesto 61 del top 100 de las canciones m\u00e1s escuchadas en YouTube esta semana. La profunda interpretaci\u00f3n de P\u00e9rez ha sido aplaudida en redes sociales, reflejando la vigencia de su arte y su inquebrantable v\u00ednculo con sus seguidores. Adem\u00e1s, como parte de los homenajes a su carrera, P\u00e9rez ser\u00e1 exaltado en la Galer\u00eda del Merengue de DINAFOLK del Ministerio de Cultura, a prop\u00f3sito de la celebraci\u00f3n del D\u00eda Nacional del Merengue, el pr\u00f3ximo 26 de noviembre. Este reconocimiento subraya su invaluable aporte a la m\u00fasica dominicana y su rol como referente indiscutible del merengue. Este nuevo \u00e1lbum en vivo, bajo la direcci\u00f3n de Manuel Tejada, representa no solo una celebraci\u00f3n de la trayectoria de Rubby, sino tambi\u00e9n una invitaci\u00f3n a explorar nuevos caminos en el merengue, ampliando los horizontes del g\u00e9nero en un contexto moderno y vanguardista.<\/p>\n","protected":false},"author":9,"featured_media":100106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-100105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100105"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100105\/revisions"}],"predecessor-version":[{"id":100107,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100105\/revisions\/100107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100106"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}