{"id":100124,"date":"2024-11-11T07:58:27","date_gmt":"2024-11-11T11:58:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100124"},"modified":"2024-11-11T07:58:39","modified_gmt":"2024-11-11T11:58:39","slug":"destituyen-primer-ministro-haiti-bandas-anuncian-dias-de-terror","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/destituyen-primer-ministro-haiti-bandas-anuncian-dias-de-terror\/","title":{"rendered":"Destituyen Primer Ministro Hait\u00ed; bandas anuncian \u201cd\u00edas de terror\u201d"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/fsoeu33k-1024x621.png\" alt=\"\" class=\"wp-image-100125\" width=\"238\" height=\"144\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/fsoeu33k-1024x621.png 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/fsoeu33k-300x182.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/fsoeu33k-768x466.png 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/fsoeu33k-600x364.png 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/fsoeu33k-500x300.png 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/fsoeu33k.png 1920w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Puerto Pr\u00edncipe (EFE).- El Consejo Presidencial de Transici\u00f3n de Hait\u00ed (CPT) destituy\u00f3 al primer ministro, Garry Conille, y nombr\u00f3 en su lugar al empresario, Alix Didier Fils-Aime.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo hizo en medio de acusaciones de corrupci\u00f3n, disputas sobre la legalidad del proceso y el cuestionamiento de Conille sobre la legitimidad de la decisi\u00f3n que, a su parecer, contradice la Constituci\u00f3n de Hait\u00ed Conille.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conflicto en la Polic\u00eda<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un documento hecho p\u00fablico este domingo, Garry Conille orden\u00f3 a la entidad encargada de publicar las decisiones oficiales, Presses nationales, que no notificara la resoluci\u00f3n del Consejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es un conflicto significativo en la pol\u00edtica de Hait\u00ed.&nbsp; Conille afirm\u00f3 que esta resoluci\u00f3n est\u00e1 \u201ctomada fuera de todo marco legal y constitucional\u201d, y suscita \u201cserias dudas sobre su legitimidad y sus repercusiones en el futuro del pa\u00eds\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rechaza su salida<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su opini\u00f3n, esta decisi\u00f3n va en contra no s\u00f3lo de&nbsp; la Constituci\u00f3n del pa\u00eds, sino tambi\u00e9n de los textos que rigen el per\u00edodo de transici\u00f3n de Hait\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo Presidencial \u201cno puede en ning\u00fan caso, ni siquiera en el marco de sus funciones transitorias, suplantar al Parlamento o ejercer un poder que no le haya sido atribuido\u201d, reza el documento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1ala que, aunque el Consejo Presidencial tiene la prerrogativa de nombrar al primer ministro, ning\u00fan texto legal le da el poder de destituirlo. Esto refleja las complejidades legales en la situaci\u00f3n de Hait\u00ed Conille.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>Abuso de poder\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan esto, la decisi\u00f3n del CPT, \u201ctomada fuera de este marco, constituye un abuso de poder y una parodia que atenta contra los principios fundamentales de la democracia\u201d, prosigue la nota de Conille.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde hace varios meses, existe un conflicto entre Conille y los miembros del Consejo Presidencial de Transici\u00f3n.La resoluci\u00f3n, firmada por 8 de los 9 miembros del Consejo reunidos en el Palacio Nacional el pasado viernes, designa como primer ministro a Alix Didier Fils-Aime. El \u00fanico miembro del CPT que no firm\u00f3 fue Edgard Leblanc<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las bandas armadas anunciaron este domingo nuevos d\u00edas de terror en el \u00e1rea metropolitana de Puerto Pr\u00edncipe a partir de ma\u00f1ana mismo, por lo que pidieron a la poblaci\u00f3n que no salga a la calle si no es necesario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un mensaje difundido en las redes sociales, el l\u00edder de la coalici\u00f3n armada conocida como Vivre Ensemble (Vivir Juntos), Jimmy Cherizier, alias \u2018Barbecue\u2019, dice que \u201cla batalla empezar\u00e1 de nuevo\u201d, por lo que, a\u00f1ade, \u201csi no lo necesitas, no tienes por qu\u00e9 salir a la calle\u201d.\u00e7\u00e7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201dEl tiempo de observaci\u00f3n (de la situaci\u00f3n por parte) de las bandas de Vivre Ensemble ha llegado a su fin (\u2026) Nos sentamos y observamos para que la gente no dijera que fuimos nosotros quienes impedimos que las escuelas abrieran sus puertas\u201d, se\u00f1ala \u2018Barbecue\u2019, un antiguo polic\u00eda convertido en poderoso jefe de los grupos armados.En su opini\u00f3n, \u201clas bandas de Vive Ensemble deben actuar\u201d y \u201cha llegado el momento, como est\u00e1is acostumbrados a hacer, de tomar el destino de este pa\u00eds en vuestras manos\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se espera que el decreto por el que se designa al nuevo primer ministro se publique este lunes en el diario oficial del pa\u00eds, Le Moniteur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El empresario Alix Didier Fils-Aime es un antiguo candidato al Senado bajo la bandera del partido pol\u00edtico Verite. Su toma de posesi\u00f3n est\u00e1 prevista para hoy, seg\u00fan la prensa local. Un d\u00eda despu\u00e9s de la investidura, se formar\u00e1 el nuevo Gobierno en Hait\u00ed Conille.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al parecer, seg\u00fan informaciones de medios de Hait\u00ed, el origen de esta situaci\u00f3n est\u00e1 en la presencia en el CPT de tres miembros del Consejo que han sido acusados de supuesta corrupci\u00f3n en Hait\u00ed, pero tambi\u00e9n se menciona la negativa del primer ministro de llevar a cabo una reestructuraci\u00f3n ministerial exigida por el CPT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puerto Pr\u00edncipe (EFE).- El Consejo Presidencial de Transici\u00f3n de Hait\u00ed (CPT) destituy\u00f3 al primer ministro, Garry Conille, y nombr\u00f3 en su lugar al empresario, Alix Didier Fils-Aime. Lo hizo en medio de acusaciones de corrupci\u00f3n, disputas sobre la legalidad del proceso y el cuestionamiento de Conille sobre la legitimidad de la decisi\u00f3n que, a su parecer, contradice la Constituci\u00f3n de Hait\u00ed Conille. Conflicto en la Polic\u00eda En un documento hecho p\u00fablico este domingo, Garry Conille orden\u00f3 a la entidad encargada de publicar las decisiones oficiales, Presses nationales, que no notificara la resoluci\u00f3n del Consejo. Este es un conflicto significativo en la pol\u00edtica de Hait\u00ed.&nbsp; Conille afirm\u00f3 que esta resoluci\u00f3n est\u00e1 \u201ctomada fuera de todo marco legal y constitucional\u201d, y suscita \u201cserias dudas sobre su legitimidad y sus repercusiones en el futuro del pa\u00eds\u201d. Rechaza su salida En su opini\u00f3n, esta decisi\u00f3n va en contra no s\u00f3lo de&nbsp; la Constituci\u00f3n del pa\u00eds, sino tambi\u00e9n de los textos que rigen el per\u00edodo de transici\u00f3n de Hait\u00ed. El Consejo Presidencial \u201cno puede en ning\u00fan caso, ni siquiera en el marco de sus funciones transitorias, suplantar al Parlamento o ejercer un poder que no le haya sido atribuido\u201d, reza el documento. Se\u00f1ala que, aunque el Consejo Presidencial tiene la prerrogativa de nombrar al primer ministro, ning\u00fan texto legal le da el poder de destituirlo. Esto refleja las complejidades legales en la situaci\u00f3n de Hait\u00ed Conille. \u201cAbuso de poder\u201d Seg\u00fan esto, la decisi\u00f3n del CPT, \u201ctomada fuera de este marco, constituye un abuso de poder y una parodia que atenta contra los principios fundamentales de la democracia\u201d, prosigue la nota de Conille. Desde hace varios meses, existe un conflicto entre Conille y los miembros del Consejo Presidencial de Transici\u00f3n.La resoluci\u00f3n, firmada por 8 de los 9 miembros del Consejo reunidos en el Palacio Nacional el pasado viernes, designa como primer ministro a Alix Didier Fils-Aime. El \u00fanico miembro del CPT que no firm\u00f3 fue Edgard Leblanc Las bandas armadas anunciaron este domingo nuevos d\u00edas de terror en el \u00e1rea metropolitana de Puerto Pr\u00edncipe a partir de ma\u00f1ana mismo, por lo que pidieron a la poblaci\u00f3n que no salga a la calle si no es necesario. En un mensaje difundido en las redes sociales, el l\u00edder de la coalici\u00f3n armada conocida como Vivre Ensemble (Vivir Juntos), Jimmy Cherizier, alias \u2018Barbecue\u2019, dice que \u201cla batalla empezar\u00e1 de nuevo\u201d, por lo que, a\u00f1ade, \u201csi no lo necesitas, no tienes por qu\u00e9 salir a la calle\u201d.\u00e7\u00e7 \u201dEl tiempo de observaci\u00f3n (de la situaci\u00f3n por parte) de las bandas de Vivre Ensemble ha llegado a su fin (\u2026) Nos sentamos y observamos para que la gente no dijera que fuimos nosotros quienes impedimos que las escuelas abrieran sus puertas\u201d, se\u00f1ala \u2018Barbecue\u2019, un antiguo polic\u00eda convertido en poderoso jefe de los grupos armados.En su opini\u00f3n, \u201clas bandas de Vive Ensemble deben actuar\u201d y \u201cha llegado el momento, como est\u00e1is acostumbrados a hacer, de tomar el destino de este pa\u00eds en vuestras manos\u2019. Se espera que el decreto por el que se designa al nuevo primer ministro se publique este lunes en el diario oficial del pa\u00eds, Le Moniteur. El empresario Alix Didier Fils-Aime es un antiguo candidato al Senado bajo la bandera del partido pol\u00edtico Verite. Su toma de posesi\u00f3n est\u00e1 prevista para hoy, seg\u00fan la prensa local. Un d\u00eda despu\u00e9s de la investidura, se formar\u00e1 el nuevo Gobierno en Hait\u00ed Conille. Al parecer, seg\u00fan informaciones de medios de Hait\u00ed, el origen de esta situaci\u00f3n est\u00e1 en la presencia en el CPT de tres miembros del Consejo que han sido acusados de supuesta corrupci\u00f3n en Hait\u00ed, pero tambi\u00e9n se menciona la negativa del primer ministro de llevar a cabo una reestructuraci\u00f3n ministerial exigida por el CPT.<\/p>\n","protected":false},"author":9,"featured_media":100125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-100124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100124"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100124\/revisions"}],"predecessor-version":[{"id":100126,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100124\/revisions\/100126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100125"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}