{"id":100148,"date":"2024-11-12T08:12:12","date_gmt":"2024-11-12T12:12:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100148"},"modified":"2024-11-12T08:12:34","modified_gmt":"2024-11-12T12:12:34","slug":"laboratorios-amadita-celebra-65-anos-contribuyendo-con-la-salud","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/laboratorios-amadita-celebra-65-anos-contribuyendo-con-la-salud\/","title":{"rendered":"Laboratorios Amadita celebra 65 a\u00f1os contribuyendo con la salud"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/JACQUELINE-GONZALEZ-P.-PILAR-GONZALEZ-P.-ALBERTO-BERGES-GONZALEZ-OCTAVIO-GONZALEZ-PATRICIA-GONZALEZ-P.-Y-AIMEE-GONZALEZ-P-300x200-1.jpg\" alt=\"\" class=\"wp-image-100149\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>SANTO DOMINGO<\/strong><\/em>.- Amadita Laboratorio celebr\u00f3 su 65 aniversario con una misa de acci\u00f3n de gracias en la Catedral Primada de Am\u00e9rica, oficiada por el reverendo padre Jorge William Hern\u00e1ndez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la instituci\u00f3n, Alberto Berg\u00e9s Gonz\u00e1lez, destac\u00f3 esta ocasi\u00f3n como un momento para reflexionar sobre el legado y los logros de la organizaci\u00f3n desde su fundaci\u00f3n en 1959.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Berg\u00e9s Gonz\u00e1lez subray\u00f3 que Amadita se ha consolidado como un pilar en la salud de los dominicanos, con m\u00e1s de 70 sucursales distribuidas por todo territorio nacional y un compromiso firme con la calidad en sus servicios de anal\u00edticas cl\u00ednicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201c<\/strong>Es oportuno hacer una mirada en retrospectiva, desde el legado que Do\u00f1a Amada Pittaluga de Gonz\u00e1lez construy\u00f3, siempre acompa\u00f1ada de manera incondicional por su esposo, el doctor Octavio Gonz\u00e1lez Nivar. Un legado marcado de servicio, vocaci\u00f3n, entrega, amor, innovaci\u00f3n, vanguardia, \u00e9tica y sobre todo humildad. Legado que el resto de la familia hemos abrazado como estandarte para honrarlo y seguir haci\u00e9ndolo crecer\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Compromiso con el Desarrollo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La trayectoria de Amadita Laboratorio Cl\u00ednico representa una contribuci\u00f3n significativa al desarrollo econ\u00f3mico y social del pa\u00eds, siendo fuente de empleo para miles y un aliado estrat\u00e9gico en la salud p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa ha reafirmado su compromiso con la innovaci\u00f3n y el desarrollo, buscando fortalecer y modernizar sus servicios para mantenerse como l\u00edder en el sector salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mirando Hacia el futuro<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Berg\u00e9s Gonz\u00e1lez tambi\u00e9n enfatiz\u00f3 la importancia de continuar innovando y diversificando servicios, incorporando tecnolog\u00eda avanzada y desarrollando su recurso humano para enfrentar futuros desaf\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradeci\u00f3 a los colaboradores, pacientes e instituciones aliadas por su apoyo continuo en la misi\u00f3n de transformar experiencias en soluciones de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento cont\u00f3 con la presencia de autoridades gubernamentales, colaboradores y figuras destacadas del sector salud y social del pa\u00eds, reflejando el impacto y reconocimiento que Amadita ha logrado a lo largo de sus 65 a\u00f1os de servicio ininterrumpido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Amadita Laboratorio celebr\u00f3 su 65 aniversario con una misa de acci\u00f3n de gracias en la Catedral Primada de Am\u00e9rica, oficiada por el reverendo padre Jorge William Hern\u00e1ndez. El presidente de la instituci\u00f3n, Alberto Berg\u00e9s Gonz\u00e1lez, destac\u00f3 esta ocasi\u00f3n como un momento para reflexionar sobre el legado y los logros de la organizaci\u00f3n desde su fundaci\u00f3n en 1959. Berg\u00e9s Gonz\u00e1lez subray\u00f3 que Amadita se ha consolidado como un pilar en la salud de los dominicanos, con m\u00e1s de 70 sucursales distribuidas por todo territorio nacional y un compromiso firme con la calidad en sus servicios de anal\u00edticas cl\u00ednicas. \u201cEs oportuno hacer una mirada en retrospectiva, desde el legado que Do\u00f1a Amada Pittaluga de Gonz\u00e1lez construy\u00f3, siempre acompa\u00f1ada de manera incondicional por su esposo, el doctor Octavio Gonz\u00e1lez Nivar. Un legado marcado de servicio, vocaci\u00f3n, entrega, amor, innovaci\u00f3n, vanguardia, \u00e9tica y sobre todo humildad. Legado que el resto de la familia hemos abrazado como estandarte para honrarlo y seguir haci\u00e9ndolo crecer\u201d, expres\u00f3. Compromiso con el Desarrollo La trayectoria de Amadita Laboratorio Cl\u00ednico representa una contribuci\u00f3n significativa al desarrollo econ\u00f3mico y social del pa\u00eds, siendo fuente de empleo para miles y un aliado estrat\u00e9gico en la salud p\u00fablica. La empresa ha reafirmado su compromiso con la innovaci\u00f3n y el desarrollo, buscando fortalecer y modernizar sus servicios para mantenerse como l\u00edder en el sector salud. Mirando Hacia el futuro Berg\u00e9s Gonz\u00e1lez tambi\u00e9n enfatiz\u00f3 la importancia de continuar innovando y diversificando servicios, incorporando tecnolog\u00eda avanzada y desarrollando su recurso humano para enfrentar futuros desaf\u00edos. Agradeci\u00f3 a los colaboradores, pacientes e instituciones aliadas por su apoyo continuo en la misi\u00f3n de transformar experiencias en soluciones de vida. El evento cont\u00f3 con la presencia de autoridades gubernamentales, colaboradores y figuras destacadas del sector salud y social del pa\u00eds, reflejando el impacto y reconocimiento que Amadita ha logrado a lo largo de sus 65 a\u00f1os de servicio ininterrumpido.<\/p>\n","protected":false},"author":9,"featured_media":100149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-100148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100148"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100148\/revisions"}],"predecessor-version":[{"id":100150,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100148\/revisions\/100150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100149"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}