{"id":100168,"date":"2024-11-13T08:01:28","date_gmt":"2024-11-13T12:01:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100168"},"modified":"2024-11-13T08:01:29","modified_gmt":"2024-11-13T12:01:29","slug":"eu-prohibe-vuelos-a-haiti-tras-ataque-armado-contra-un-avion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eu-prohibe-vuelos-a-haiti-tras-ataque-armado-contra-un-avion\/","title":{"rendered":"EU proh\u00edbe vuelos a Hait\u00ed tras ataque armado contra un avi\u00f3n"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/FAA.jpg\" alt=\"\" class=\"wp-image-100169\" width=\"244\" height=\"153\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/FAA.jpg 563w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/FAA-300x188.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/FAA-400x250.jpg 400w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La agresi\u00f3n de un avi\u00f3n de Spirit Airlines que viajaba de Fort Lauderdale, Florida, a&nbsp;Hait\u00ed, que ocurri\u00f3 el lunes, llev\u00f3 a la&nbsp;Administraci\u00f3n Federal de Aviaci\u00f3n (FAA)&nbsp;de Estados Unidos a&nbsp;prohibir los vuelos&nbsp;hacia el pa\u00eds caribe\u00f1o&nbsp;durante 30 d\u00edas, seg\u00fan un aviso emitido el martes, inform\u00f3&nbsp;ABC News.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El vuelo fue desviado tras ser alcanzado por disparos mientras intentaba aterrizar en el aeropuerto Toussaint Louverture de Puerto Pr\u00edncipe, seg\u00fan inform\u00f3 la Oficina Nacional de Aviaci\u00f3n Civil de Hait\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La FAA inform\u00f3 su decisi\u00f3n a trav\u00e9s un aviso a la Misi\u00f3n A\u00e9rea emitido el martes. \u201cLas operaciones de la aviaci\u00f3n civil estadounidense en el territorio y espacio a\u00e9reo de&nbsp;Hait\u00ed&nbsp;por debajo de los 10.000 pies\u201d estar\u00e1n prohibidas, seg\u00fan la nota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta restricci\u00f3n, inicialmente prevista hasta el lunes, se extendi\u00f3 por al menos 30 d\u00edas. La prohibici\u00f3n afecta a todos los operadores de aeronaves civiles registradas en Estados Unidos, salvo en casos de emergencia o vuelos autorizados por el gobierno estadounidense con la aprobaci\u00f3n de la FAA, seg\u00fan inform\u00f3 el&nbsp;Miami Herald.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Aeropuerto Internacional Toussaint Louverture en Puerto Pr\u00edncipe suspendi\u00f3 operaciones en octubre luego de otro incidente de violencia armada. (REUTERS\/Ralph Tedy Erol)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Agresiones armadas contra vuelos internacionales en Hait\u00ed<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El contexto del ataque se enmarca en un d\u00eda de intensos enfrentamientos entre la polic\u00eda y bandas armadas en Hait\u00ed. Estos incidentes ocurrieron tras amenazas de violencia por parte de una coalici\u00f3n de bandas, luego de que el consejo presidencial destituyera al primer ministro&nbsp;Garry Conille&nbsp;y designara al empresario&nbsp;Alix Didier Fils-Aime&nbsp;como su sucesor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el momento, las autoridades haitianas no han emitido declaraciones sobre los tiroteos. La situaci\u00f3n en Hait\u00ed sigue siendo tensa, con un trasfondo de inestabilidad pol\u00edtica y social que ha afectado la seguridad en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;avi\u00f3n de Spirit Airlines&nbsp;fue impactado por disparos en cuatro ocasiones mientras se aproximaba a la pista, pero logr\u00f3 desviarse y aterrizar de manera segura en Santiago,&nbsp;Rep\u00fablica Dominicana, seg\u00fan un comunicado de la aerol\u00ednea. Ning\u00fan pasajero result\u00f3 herido, aunque un asistente de vuelo sufri\u00f3 lesiones menores y fue sometido a evaluaci\u00f3n m\u00e9dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El incidente se produjo cuando el avi\u00f3n estaba a solo 550 pies de la pista, seg\u00fan datos de&nbsp;FlightRadar24. La FAA confirm\u00f3 que el vuelo de&nbsp;Spirit Airlines&nbsp;aterriz\u00f3 sin problemas en la Rep\u00fablica Dominicana despu\u00e9s de que el avi\u00f3n sufriera da\u00f1os por los disparos mientras intentaba aterrizar en Puerto Pr\u00edncipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, un vuelo de JetBlue que part\u00eda de&nbsp;Hait\u00ed&nbsp;hacia&nbsp;Nueva York&nbsp;tambi\u00e9n fue alcanzado por una bala, seg\u00fan un comunicado de la aerol\u00ednea a&nbsp;ABC News.&nbsp;Como resultado de la creciente inestabilidad en el pa\u00eds,&nbsp;JetBlue&nbsp;decidi\u00f3 suspender todos sus vuelos hacia y desde&nbsp;Hait\u00ed&nbsp;hasta el 2 de diciembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situaci\u00f3n de seguridad en\u00a0Hait\u00ed\u00a0ha generado preocupaciones significativas, lo que ha llevado a estas medidas preventivas por parte de las aerol\u00edneas y autoridades de aviaci\u00f3n. La prohibici\u00f3n de vuelos y la suspensi\u00f3n de servicios reflejan la gravedad de los incidentes recientes y la necesidad de garantizar la seguridad de los pasajeros y tripulaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <strong>FUENTE: INFOBAE<\/strong> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La agresi\u00f3n de un avi\u00f3n de Spirit Airlines que viajaba de Fort Lauderdale, Florida, a&nbsp;Hait\u00ed, que ocurri\u00f3 el lunes, llev\u00f3 a la&nbsp;Administraci\u00f3n Federal de Aviaci\u00f3n (FAA)&nbsp;de Estados Unidos a&nbsp;prohibir los vuelos&nbsp;hacia el pa\u00eds caribe\u00f1o&nbsp;durante 30 d\u00edas, seg\u00fan un aviso emitido el martes, inform\u00f3&nbsp;ABC News. El vuelo fue desviado tras ser alcanzado por disparos mientras intentaba aterrizar en el aeropuerto Toussaint Louverture de Puerto Pr\u00edncipe, seg\u00fan inform\u00f3 la Oficina Nacional de Aviaci\u00f3n Civil de Hait\u00ed. La FAA inform\u00f3 su decisi\u00f3n a trav\u00e9s un aviso a la Misi\u00f3n A\u00e9rea emitido el martes. \u201cLas operaciones de la aviaci\u00f3n civil estadounidense en el territorio y espacio a\u00e9reo de&nbsp;Hait\u00ed&nbsp;por debajo de los 10.000 pies\u201d estar\u00e1n prohibidas, seg\u00fan la nota. Esta restricci\u00f3n, inicialmente prevista hasta el lunes, se extendi\u00f3 por al menos 30 d\u00edas. La prohibici\u00f3n afecta a todos los operadores de aeronaves civiles registradas en Estados Unidos, salvo en casos de emergencia o vuelos autorizados por el gobierno estadounidense con la aprobaci\u00f3n de la FAA, seg\u00fan inform\u00f3 el&nbsp;Miami Herald. El Aeropuerto Internacional Toussaint Louverture en Puerto Pr\u00edncipe suspendi\u00f3 operaciones en octubre luego de otro incidente de violencia armada. (REUTERS\/Ralph Tedy Erol) Agresiones armadas contra vuelos internacionales en Hait\u00ed El contexto del ataque se enmarca en un d\u00eda de intensos enfrentamientos entre la polic\u00eda y bandas armadas en Hait\u00ed. Estos incidentes ocurrieron tras amenazas de violencia por parte de una coalici\u00f3n de bandas, luego de que el consejo presidencial destituyera al primer ministro&nbsp;Garry Conille&nbsp;y designara al empresario&nbsp;Alix Didier Fils-Aime&nbsp;como su sucesor. Hasta el momento, las autoridades haitianas no han emitido declaraciones sobre los tiroteos. La situaci\u00f3n en Hait\u00ed sigue siendo tensa, con un trasfondo de inestabilidad pol\u00edtica y social que ha afectado la seguridad en el pa\u00eds. El&nbsp;avi\u00f3n de Spirit Airlines&nbsp;fue impactado por disparos en cuatro ocasiones mientras se aproximaba a la pista, pero logr\u00f3 desviarse y aterrizar de manera segura en Santiago,&nbsp;Rep\u00fablica Dominicana, seg\u00fan un comunicado de la aerol\u00ednea. Ning\u00fan pasajero result\u00f3 herido, aunque un asistente de vuelo sufri\u00f3 lesiones menores y fue sometido a evaluaci\u00f3n m\u00e9dica. El incidente se produjo cuando el avi\u00f3n estaba a solo 550 pies de la pista, seg\u00fan datos de&nbsp;FlightRadar24. La FAA confirm\u00f3 que el vuelo de&nbsp;Spirit Airlines&nbsp;aterriz\u00f3 sin problemas en la Rep\u00fablica Dominicana despu\u00e9s de que el avi\u00f3n sufriera da\u00f1os por los disparos mientras intentaba aterrizar en Puerto Pr\u00edncipe. Adem\u00e1s, un vuelo de JetBlue que part\u00eda de&nbsp;Hait\u00ed&nbsp;hacia&nbsp;Nueva York&nbsp;tambi\u00e9n fue alcanzado por una bala, seg\u00fan un comunicado de la aerol\u00ednea a&nbsp;ABC News.&nbsp;Como resultado de la creciente inestabilidad en el pa\u00eds,&nbsp;JetBlue&nbsp;decidi\u00f3 suspender todos sus vuelos hacia y desde&nbsp;Hait\u00ed&nbsp;hasta el 2 de diciembre. La situaci\u00f3n de seguridad en\u00a0Hait\u00ed\u00a0ha generado preocupaciones significativas, lo que ha llevado a estas medidas preventivas por parte de las aerol\u00edneas y autoridades de aviaci\u00f3n. La prohibici\u00f3n de vuelos y la suspensi\u00f3n de servicios reflejan la gravedad de los incidentes recientes y la necesidad de garantizar la seguridad de los pasajeros y tripulaciones. FUENTE: INFOBAE<\/p>\n","protected":false},"author":9,"featured_media":100169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-100168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100168"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100168\/revisions"}],"predecessor-version":[{"id":100170,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100168\/revisions\/100170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100169"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}