{"id":100199,"date":"2024-11-15T07:09:36","date_gmt":"2024-11-15T11:09:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100199"},"modified":"2024-11-15T07:09:38","modified_gmt":"2024-11-15T11:09:38","slug":"estrellas-propinan-paliza-a-los-gigantes-toros-vencen-aguilas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/estrellas-propinan-paliza-a-los-gigantes-toros-vencen-aguilas\/","title":{"rendered":"Estrellas propinan paliza a los Gigantes; Toros vencen Aguilas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/bun-300x200-1.jpg\" alt=\"\" class=\"wp-image-100200\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SAN FRANCISCO DE MACORIS.- Las Estrellas propinaron paliza de 11-2 a los Gigantes del Cibao en partido correspondiente al torneo de b\u00e9isbol oto\u00f1o-invernal y celebrado en el Estadio Juli\u00e1n Javier de esta ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">David Bu\u00f1uelos fue el \u201cJugador Estrella de las Estrellas\u201d al remolcar tres carreras, producto de un doble en el rally de siete vueltas en la tercera entrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el triunfo, las Estrellas cortaron una racha de cinco derrotas en la ruta. La \u00faltima vez que ganaron un encuentro fue el 27 de octubre pasado, cuando, precisamente, derrotaron a los Gigantes 13-11.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de Bu\u00f1uelos, tambi\u00e9n brillaron a la ofensiva Ismael Mungu\u00eda, Eguy Rosario y Miguel San\u00f3, los tres con dos carreras remolcadas cada uno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria fue para Oscar de la Cruz (1-0), mientras que Iv\u00e1n Oviedo (0-1) carg\u00f3 con la derrota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las Estrellas contin\u00faan su periplo por la ruta y la noche de este viernes se miden a las \u00c1guilas Cibae\u00f1as en el Estadio Cibao de Santiago de los Caballeros a partir de las 7:30 P.M. Ra\u00fal Alc\u00e1ntara est\u00e1 se\u00f1alado abrir por el equipo de la ense\u00f1a verde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, por los Gigantes abri\u00f3 Iv\u00e1n Ogando, con actuaci\u00f3n de dos episodios de tres imparables, cuatro carreras, dos transferencias y un ponche. Fue sustituido por Edgar E. Garc\u00eda (3), Joelvis del Rosario (3), Danny Salazar (4), Anderson Pilar (6), Christian Montes de Oca (7), Yerry Rodr\u00edguez (8), Johan Dom\u00ednguez (9) y Camilo Doval (9).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TOROS 5 AGUILAS 4<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SANTIAGO DE LOS CABALLEROS.- Pablo Reyes lo empat\u00f3 con doble de dos carreras en el octavo, Troy Johnston hizo lo mismo en el d\u00e9cimo inning, para que los Toros del Este remontaran y se impusieran 5-4 sobre las \u00c1guilas Cibae\u00f1as, en partido que se decidi\u00f3 en entradas extras en el Estadio Cibao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el juego empatado 3-3, y dos a bordo, Johnston peg\u00f3 doblete al jard\u00edn derecho, limpiando las bases, ante los env\u00edos del brasile\u00f1o Thiago Vieira, para ser este el batazo de la diferencia en el d\u00e9cimo episodio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la victoria, los Toros (8-12) se acercan a solo medio juego de las \u00c1guilas (8-11) en el cuarto lugar clasificatorio, luego de ganar dos de tres juegos consecutivos entre ambos equipos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria fue para el relevista zurdo Fernando Abad (2-0, 0.90) tras lanzar dos entradas de un hit, una carrera (corredor fantasma), un boleto y dos ponches. La derrota recay\u00f3 sobre el relevista amarillo Thiago Vieira (0-1, 6.75) al permitir las dos carreras del d\u00e9cimo episodio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN FRANCISCO DE MACORIS.- Las Estrellas propinaron paliza de 11-2 a los Gigantes del Cibao en partido correspondiente al torneo de b\u00e9isbol oto\u00f1o-invernal y celebrado en el Estadio Juli\u00e1n Javier de esta ciudad. David Bu\u00f1uelos fue el \u201cJugador Estrella de las Estrellas\u201d al remolcar tres carreras, producto de un doble en el rally de siete vueltas en la tercera entrada. Con el triunfo, las Estrellas cortaron una racha de cinco derrotas en la ruta. La \u00faltima vez que ganaron un encuentro fue el 27 de octubre pasado, cuando, precisamente, derrotaron a los Gigantes 13-11. Adem\u00e1s de Bu\u00f1uelos, tambi\u00e9n brillaron a la ofensiva Ismael Mungu\u00eda, Eguy Rosario y Miguel San\u00f3, los tres con dos carreras remolcadas cada uno. La victoria fue para Oscar de la Cruz (1-0), mientras que Iv\u00e1n Oviedo (0-1) carg\u00f3 con la derrota. Las Estrellas contin\u00faan su periplo por la ruta y la noche de este viernes se miden a las \u00c1guilas Cibae\u00f1as en el Estadio Cibao de Santiago de los Caballeros a partir de las 7:30 P.M. Ra\u00fal Alc\u00e1ntara est\u00e1 se\u00f1alado abrir por el equipo de la ense\u00f1a verde. En tanto, por los Gigantes abri\u00f3 Iv\u00e1n Ogando, con actuaci\u00f3n de dos episodios de tres imparables, cuatro carreras, dos transferencias y un ponche. Fue sustituido por Edgar E. Garc\u00eda (3), Joelvis del Rosario (3), Danny Salazar (4), Anderson Pilar (6), Christian Montes de Oca (7), Yerry Rodr\u00edguez (8), Johan Dom\u00ednguez (9) y Camilo Doval (9). TOROS 5 AGUILAS 4 SANTIAGO DE LOS CABALLEROS.- Pablo Reyes lo empat\u00f3 con doble de dos carreras en el octavo, Troy Johnston hizo lo mismo en el d\u00e9cimo inning, para que los Toros del Este remontaran y se impusieran 5-4 sobre las \u00c1guilas Cibae\u00f1as, en partido que se decidi\u00f3 en entradas extras en el Estadio Cibao. Con el juego empatado 3-3, y dos a bordo, Johnston peg\u00f3 doblete al jard\u00edn derecho, limpiando las bases, ante los env\u00edos del brasile\u00f1o Thiago Vieira, para ser este el batazo de la diferencia en el d\u00e9cimo episodio. Con la victoria, los Toros (8-12) se acercan a solo medio juego de las \u00c1guilas (8-11) en el cuarto lugar clasificatorio, luego de ganar dos de tres juegos consecutivos entre ambos equipos. La victoria fue para el relevista zurdo Fernando Abad (2-0, 0.90) tras lanzar dos entradas de un hit, una carrera (corredor fantasma), un boleto y dos ponches. La derrota recay\u00f3 sobre el relevista amarillo Thiago Vieira (0-1, 6.75) al permitir las dos carreras del d\u00e9cimo episodio.<\/p>\n","protected":false},"author":9,"featured_media":100200,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-100199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100199"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100199\/revisions"}],"predecessor-version":[{"id":100201,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100199\/revisions\/100201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100200"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}