{"id":100400,"date":"2024-11-27T07:02:00","date_gmt":"2024-11-27T11:02:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100400"},"modified":"2024-11-27T07:02:11","modified_gmt":"2024-11-27T11:02:11","slug":"gary-sanchez-pega-jonron-por-los-leones-aguilas-y-estrellas-ganan","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gary-sanchez-pega-jonron-por-los-leones-aguilas-y-estrellas-ganan\/","title":{"rendered":"Gary S\u00e1nchez pega jonr\u00f3n por los Leones; Aguilas y Estrellas ganan"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/gary-300x200-1.jpg\" alt=\"\" class=\"wp-image-100401\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- Un doble con las bases llenas de Franchy Cordero en el octavo episodio y un jonr\u00f3n de dos carreras del debutante Gary S\u00e1nchez le dieron a los Leones del Escogido una victoria 7-6 sobre los Tigres del Licey en el estadio Quisqueya Juan Marichal, de esta ciudad.Con desventaja 6-5 en la parte baja del octavo y Wander Suero lanzando, los locales llenaron los sacos con un out cuando lleg\u00f3 la l\u00ednea de Cordero al jard\u00edn derecho para llevar a Steward Berroa y a Junior Lake a la goma desde tercera y segunda, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cuadrangular de S\u00e1nchez se produjo en el s\u00e9ptimo con los lice\u00edstas al frente 5-3. Con Cordero corriendo en segunda tras otro doble, esta vez al central, el receptor escarlata conect\u00f3 la pelota a 414 pies de distancia entre los bosques izquierdo y central a una velocidad de 107.1 millas por hora contra Yunior Marte para volver a igualar las acciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yohan Ram\u00edrez (2-1) gan\u00f3 el juego al tirar 0.2 cap\u00edtulos de un boleto y dos ponches. La derrota fue para Suero (0-1), luego de que le marcaran las dos rayitas del octavo. Brian Moran (1) consigui\u00f3 el salvamento al presentarse en el noveno cediendo solo una transferencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ESTRELLAS 4 GIGANTES 1<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SAN FRANCISCO DE MACORIS.- Las Estrellas vinieron de atr\u00e1s para derrotar 4-1 a los Gigantes del Cibao la noche de este martes en partido correspondiente al torneo de b\u00e9isbol oto\u00f1o-invernal 2024-2025, celebrado en el Estadio Juli\u00e1n Javier de esta ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enmanuel Valdez fue el l\u00edder del juego al conectar un Grand Slam en la novena entrada ante el relevista \u00c1ngel Chivilli en conteo de cero bola y un strike. Antes del palo de Valdez, los Gigantes dominaban 1-0 el encuentro.Fue la s\u00e9ptima victoria del equipo verde en los \u00faltimos diez encuentros. Asimismo, el representativo petromacorisano pas\u00f3 a comandar la serie particular ante los del \u201cJaya\u201d 4-3.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Un doble con las bases llenas de Franchy Cordero en el octavo episodio y un jonr\u00f3n de dos carreras del debutante Gary S\u00e1nchez le dieron a los Leones del Escogido una victoria 7-6 sobre los Tigres del Licey en el estadio Quisqueya Juan Marichal, de esta ciudad.Con desventaja 6-5 en la parte baja del octavo y Wander Suero lanzando, los locales llenaron los sacos con un out cuando lleg\u00f3 la l\u00ednea de Cordero al jard\u00edn derecho para llevar a Steward Berroa y a Junior Lake a la goma desde tercera y segunda, respectivamente. El cuadrangular de S\u00e1nchez se produjo en el s\u00e9ptimo con los lice\u00edstas al frente 5-3. Con Cordero corriendo en segunda tras otro doble, esta vez al central, el receptor escarlata conect\u00f3 la pelota a 414 pies de distancia entre los bosques izquierdo y central a una velocidad de 107.1 millas por hora contra Yunior Marte para volver a igualar las acciones. Yohan Ram\u00edrez (2-1) gan\u00f3 el juego al tirar 0.2 cap\u00edtulos de un boleto y dos ponches. La derrota fue para Suero (0-1), luego de que le marcaran las dos rayitas del octavo. Brian Moran (1) consigui\u00f3 el salvamento al presentarse en el noveno cediendo solo una transferencia. ESTRELLAS 4 GIGANTES 1 SAN FRANCISCO DE MACORIS.- Las Estrellas vinieron de atr\u00e1s para derrotar 4-1 a los Gigantes del Cibao la noche de este martes en partido correspondiente al torneo de b\u00e9isbol oto\u00f1o-invernal 2024-2025, celebrado en el Estadio Juli\u00e1n Javier de esta ciudad. Enmanuel Valdez fue el l\u00edder del juego al conectar un Grand Slam en la novena entrada ante el relevista \u00c1ngel Chivilli en conteo de cero bola y un strike. Antes del palo de Valdez, los Gigantes dominaban 1-0 el encuentro.Fue la s\u00e9ptima victoria del equipo verde en los \u00faltimos diez encuentros. Asimismo, el representativo petromacorisano pas\u00f3 a comandar la serie particular ante los del \u201cJaya\u201d 4-3.<\/p>\n","protected":false},"author":9,"featured_media":100401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-100400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100400"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100400\/revisions"}],"predecessor-version":[{"id":100402,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100400\/revisions\/100402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100401"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}