{"id":100587,"date":"2024-12-09T06:48:59","date_gmt":"2024-12-09T10:48:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100587"},"modified":"2024-12-09T06:49:01","modified_gmt":"2024-12-09T10:49:01","slug":"eeuu-trump-promete-indultar-en-2025-asaltantes-de-capitolio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eeuu-trump-promete-indultar-en-2025-asaltantes-de-capitolio\/","title":{"rendered":"EEUU: Trump promete indultar en 2025 asaltantes de Capitolio"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/12\/asalt-300x200-1.jpg\" alt=\"\" class=\"wp-image-100588\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">NUEVA YORK, 8 Dic.- El presidente electo de Estados Unidos, Donald Trump, ha prometido que comenzar\u00e1 a indultar a las personas encarceladas por asaltar el Capitolio el 6 de enero de 2021 para protestar contra el resultado de las elecciones presidenciales que se saldaron con la derrota del magnate neoyorquino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump ha negado por activa y por pasiva que incitara a los manifestantes a asaltar la sede del Congreso estadounidense. M\u00e1s de 900 participantes en el asalto se declararon culpables de diferentes delitos para ver reducida su pena durante los procesos abiertos en su contra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los argumentos que m\u00e1s han repetido en esas discretas audiencias los detenidos es el de que se vieron instigados a actuar para detener la confirmaci\u00f3n del triunfo de Joe Biden por el expresidente estadounidense, que ya durante la campa\u00f1a insisti\u00f3 en que ser\u00eda v\u00edctima de un fraude electoral. Unas acusaciones sin fundamento que sigui\u00f3 lanzando, y a\u00fan deja caer, tras perder de manera ajustada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abVoy a examinarlo todo y voy a actuar muy r\u00e1pido. Desde el primer d\u00eda\u00bb, ha asegurado Trump durante una amplia entrevista al programa Meet the Press, de la cadena NBC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEsta gente lleva.. \u00bfcu\u00e1nto tiempo?, \u00bftres, cuatro a\u00f1os?, viviendo en un sitio sucio y repugnante. Esta gente est\u00e1 viviendo en un infierno\u00bb, ha asegurado Trump antes de amenazar a los miembros de la comisi\u00f3n de la C\u00e1mara de Representantes que investig\u00f3 el asalto y sus consecuencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQuienes deber\u00edan estar en la c\u00e1rcel son ellos. No son m\u00e1s que unos matones pol\u00edticos y, sabe usted, unos raritos\u00bb, ha manifestado el mandatario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUEVA YORK, 8 Dic.- El presidente electo de Estados Unidos, Donald Trump, ha prometido que comenzar\u00e1 a indultar a las personas encarceladas por asaltar el Capitolio el 6 de enero de 2021 para protestar contra el resultado de las elecciones presidenciales que se saldaron con la derrota del magnate neoyorquino. Trump ha negado por activa y por pasiva que incitara a los manifestantes a asaltar la sede del Congreso estadounidense. M\u00e1s de 900 participantes en el asalto se declararon culpables de diferentes delitos para ver reducida su pena durante los procesos abiertos en su contra. Uno de los argumentos que m\u00e1s han repetido en esas discretas audiencias los detenidos es el de que se vieron instigados a actuar para detener la confirmaci\u00f3n del triunfo de Joe Biden por el expresidente estadounidense, que ya durante la campa\u00f1a insisti\u00f3 en que ser\u00eda v\u00edctima de un fraude electoral. Unas acusaciones sin fundamento que sigui\u00f3 lanzando, y a\u00fan deja caer, tras perder de manera ajustada. \u00abVoy a examinarlo todo y voy a actuar muy r\u00e1pido. Desde el primer d\u00eda\u00bb, ha asegurado Trump durante una amplia entrevista al programa Meet the Press, de la cadena NBC. \u00abEsta gente lleva.. \u00bfcu\u00e1nto tiempo?, \u00bftres, cuatro a\u00f1os?, viviendo en un sitio sucio y repugnante. Esta gente est\u00e1 viviendo en un infierno\u00bb, ha asegurado Trump antes de amenazar a los miembros de la comisi\u00f3n de la C\u00e1mara de Representantes que investig\u00f3 el asalto y sus consecuencias. \u00abQuienes deber\u00edan estar en la c\u00e1rcel son ellos. No son m\u00e1s que unos matones pol\u00edticos y, sabe usted, unos raritos\u00bb, ha manifestado el mandatario.<\/p>\n","protected":false},"author":9,"featured_media":100588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-100587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100587"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100587\/revisions"}],"predecessor-version":[{"id":100589,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100587\/revisions\/100589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100588"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}