{"id":100614,"date":"2024-12-10T05:03:16","date_gmt":"2024-12-10T09:03:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100614"},"modified":"2024-12-10T05:03:18","modified_gmt":"2024-12-10T09:03:18","slug":"asociacion-de-mao-gana-primer-lugar-copa-navidena-de-lucha","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/asociacion-de-mao-gana-primer-lugar-copa-navidena-de-lucha\/","title":{"rendered":"Asociaci\u00f3n de Mao gana primer lugar Copa Navide\u00f1a de Lucha"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/12\/mao-300x200-1.jpg\" alt=\"\" class=\"wp-image-100615\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO. La Asociaci\u00f3n de Lucha de Mao, Valverde, se alz\u00f3 con el primer lugar de la XX edici\u00f3n de la Copa Navide\u00f1a de Lucha profesor On\u00e9simo Rufino G\u00f3mez que concluy\u00f3 el domingo en el Pabell\u00f3n de ese deporte del Centro Ol\u00edmpico Juan Pablo Duarte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La representaci\u00f3n de Mao exhibi\u00f3 su dominio al acumular un total de 92 puntos tras conseguir 76 en las competencias U-15 y U-17, y 16 en 8-10 y 11-12 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El segundo lugar fue para la Asociaci\u00f3n de Lucha de Bonao, que tuvo 88 puntos, incluidos 30 tantos en U15 y U17, y otros 58 en las competencias 8-10 y 11-12 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con 87 puntos, el equipo de la Asociaci\u00f3n de Lucha de Azua se adjudic\u00f3 la copa de tercer puesto. Los judocas azuanos sumaron 76 unidades en U-15, U-17, y 11 en 8-10, 11-12 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cuarto lugar recay\u00f3 sobre Barahona, con 56 puntos, mientras que el quinto puesto lo reserv\u00f3 la provincia Santo Domingo, con 47 tantos, en tanto que San Francisco de Macor\u00eds y San Crist\u00f3bal compartieron el sexto puesto, con 38 unidades para cada asociaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El certamen, organizado por la Federaci\u00f3n Dominicana de Lucha (Fedola), tuvo la participaci\u00f3n de algo m\u00e1s de 500 atletas en las diferentes categor\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el torneo participar\u00e1n delegaciones del Distrito Nacional y las provincias de Santo Domingo, El\u00edas Pi\u00f1a, Barahona, San Juan, San Crist\u00f3bal, Monse\u00f1or Nouel, La Vega, Duarte, Santiago, Valverde, Puerto Plata, La Romana, San Pedro de Macor\u00eds y Monte Plata, entre otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, ver\u00e1n acci\u00f3n representaciones del C\u00edrculo Deportivo Militar y Policial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ceremonia de inauguraci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Federaci\u00f3n Dominicana de Lucha (Fedola) hizo sendos reconocimientos a los dirigentes deportivos Isaac Ogando, fundador de la Asociaci\u00f3n de Lucha de Monte Plata, y a C\u00e9sar Medrano, titular de la Asociaci\u00f3n de San Juan de la Maguana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La distinci\u00f3n form\u00f3 parte de la ceremonia de inauguraci\u00f3n de la XX Copa Navide\u00f1a de Lucha profesor On\u00e9simo Rufino G\u00f3mez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Fedola, Antonio Acosta, resalt\u00f3 la labor que a favor del deporte y la lucha han realizado Ogando y Medrano en sus respectivas comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kennedy Vargas, viceministro de Deportes, valor\u00f3 la importancia de celebrar este tipo de competencia a nivel nacional porque contribuye al desarrollo del deporte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el acto estuvo tambi\u00e9n Franklin de la Cruz, presidente de la Federaci\u00f3n Dominicana de Triatl\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yer\u00f3n D\u00edaz, atleta del representativo de Azua, tuvo a su cargo la juramentaci\u00f3n deportiva, y Juan Carlos Cuello, hizo lo propio por el cuerpo&nbsp;de&nbsp;\u00e1rbitros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. La Asociaci\u00f3n de Lucha de Mao, Valverde, se alz\u00f3 con el primer lugar de la XX edici\u00f3n de la Copa Navide\u00f1a de Lucha profesor On\u00e9simo Rufino G\u00f3mez que concluy\u00f3 el domingo en el Pabell\u00f3n de ese deporte del Centro Ol\u00edmpico Juan Pablo Duarte. La representaci\u00f3n de Mao exhibi\u00f3 su dominio al acumular un total de 92 puntos tras conseguir 76 en las competencias U-15 y U-17, y 16 en 8-10 y 11-12 a\u00f1os. El segundo lugar fue para la Asociaci\u00f3n de Lucha de Bonao, que tuvo 88 puntos, incluidos 30 tantos en U15 y U17, y otros 58 en las competencias 8-10 y 11-12 a\u00f1os. Con 87 puntos, el equipo de la Asociaci\u00f3n de Lucha de Azua se adjudic\u00f3 la copa de tercer puesto. Los judocas azuanos sumaron 76 unidades en U-15, U-17, y 11 en 8-10, 11-12 a\u00f1os. El cuarto lugar recay\u00f3 sobre Barahona, con 56 puntos, mientras que el quinto puesto lo reserv\u00f3 la provincia Santo Domingo, con 47 tantos, en tanto que San Francisco de Macor\u00eds y San Crist\u00f3bal compartieron el sexto puesto, con 38 unidades para cada asociaci\u00f3n. El certamen, organizado por la Federaci\u00f3n Dominicana de Lucha (Fedola), tuvo la participaci\u00f3n de algo m\u00e1s de 500 atletas en las diferentes categor\u00edas. En el torneo participar\u00e1n delegaciones del Distrito Nacional y las provincias de Santo Domingo, El\u00edas Pi\u00f1a, Barahona, San Juan, San Crist\u00f3bal, Monse\u00f1or Nouel, La Vega, Duarte, Santiago, Valverde, Puerto Plata, La Romana, San Pedro de Macor\u00eds y Monte Plata, entre otras. Adem\u00e1s, ver\u00e1n acci\u00f3n representaciones del C\u00edrculo Deportivo Militar y Policial. Ceremonia de inauguraci\u00f3n La Federaci\u00f3n Dominicana de Lucha (Fedola) hizo sendos reconocimientos a los dirigentes deportivos Isaac Ogando, fundador de la Asociaci\u00f3n de Lucha de Monte Plata, y a C\u00e9sar Medrano, titular de la Asociaci\u00f3n de San Juan de la Maguana. La distinci\u00f3n form\u00f3 parte de la ceremonia de inauguraci\u00f3n de la XX Copa Navide\u00f1a de Lucha profesor On\u00e9simo Rufino G\u00f3mez. El presidente de la Fedola, Antonio Acosta, resalt\u00f3 la labor que a favor del deporte y la lucha han realizado Ogando y Medrano en sus respectivas comunidades. Kennedy Vargas, viceministro de Deportes, valor\u00f3 la importancia de celebrar este tipo de competencia a nivel nacional porque contribuye al desarrollo del deporte. En el acto estuvo tambi\u00e9n Franklin de la Cruz, presidente de la Federaci\u00f3n Dominicana de Triatl\u00f3n. Yer\u00f3n D\u00edaz, atleta del representativo de Azua, tuvo a su cargo la juramentaci\u00f3n deportiva, y Juan Carlos Cuello, hizo lo propio por el cuerpo&nbsp;de&nbsp;\u00e1rbitros.<\/p>\n","protected":false},"author":9,"featured_media":100615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-100614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100614"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100614\/revisions"}],"predecessor-version":[{"id":100616,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100614\/revisions\/100616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100615"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}