{"id":100661,"date":"2024-12-12T12:56:59","date_gmt":"2024-12-12T16:56:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100661"},"modified":"2024-12-12T12:57:01","modified_gmt":"2024-12-12T16:57:01","slug":"magia-de-navidad-llega-a-plaza-espana-con-el-arbol-coca-cola","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/magia-de-navidad-llega-a-plaza-espana-con-el-arbol-coca-cola\/","title":{"rendered":"Magia de Navidad llega a Plaza Espa\u00f1a con el \u00e1rbol Coca Cola"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"166\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/12\/magia-300x166-1.jpg\" alt=\"\" class=\"wp-image-100662\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/12\/magia-300x166-1.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/12\/magia-300x166-1-400x220.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.-&nbsp;El tradicional \u00e1rbol Coca Cola, s\u00edmbolo de uni\u00f3n y alegr\u00eda, ya ilumina la Plaza Espa\u00f1a e invita a celebrar las navidades en familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como cada a\u00f1o, el imponente s\u00edmbolo es el centro de las fiestas, ya que ofrece a mayores y chicos el espacio ideal para crear nuevos e inolvidables recuerdos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este evento es una tradici\u00f3n esperada por muchas familias y simboliza la importancia de los peque\u00f1os gestos que unen corazones y construyen comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa estadounidense Coca-Cola, con el lema \u00abDespierta el Santa que vive en ti\u201d, propone inspirar actos de bondad esta Navidad, y que el esp\u00edritu de la temporada est\u00e9 presente todos los d\u00edas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c1RBOL MAJESTUOSO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El majestuoso \u00e1rbol, de 60 pies de altura, estar\u00e1 iluminando durante el mes de diciembre y ofrece el lugar ideal para compartir y celebrar en familia el verdadero esp\u00edritu de estas fiestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Virginia Garc\u00eda, directora de Marketing de Coca-Cola Rep\u00fablica Dominicana, se\u00f1al\u00f3 que con la tradici\u00f3n navide\u00f1a se desea despertar los mejores sentimientos en cada persona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, C\u00e9sar de Le\u00f3n, director de Marketing de Bepensa Dominicana, agreg\u00f3 que hoy, con este \u00e1rbol, celebramos la magia de estar juntos y de hacer el bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En colaboraci\u00f3n con Mucho Project, Coca-Cola distribuir\u00e1 alimentos y bebidas a personas en situaci\u00f3n de vulnerabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>INTERACTUAR CON SANTA CLAUS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o, Coca-Cola integra la tecnolog\u00eda Create Real Magic\u2122, accesible mediante c\u00f3digos QR en sus botellas y latas, para que sus&nbsp;&nbsp;consumidores interact\u00faen con Santa Claus mediante inteligencia artificial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el encendido del \u00e1rbol en la Plaza Espa\u00f1a, esta experiencia se vivi\u00f3 por primera vez en el pa\u00eds, la que destaca como una innovadora forma de conectar tradici\u00f3n con modernidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-&nbsp;El tradicional \u00e1rbol Coca Cola, s\u00edmbolo de uni\u00f3n y alegr\u00eda, ya ilumina la Plaza Espa\u00f1a e invita a celebrar las navidades en familia. Como cada a\u00f1o, el imponente s\u00edmbolo es el centro de las fiestas, ya que ofrece a mayores y chicos el espacio ideal para crear nuevos e inolvidables recuerdos. Este evento es una tradici\u00f3n esperada por muchas familias y simboliza la importancia de los peque\u00f1os gestos que unen corazones y construyen comunidad. La empresa estadounidense Coca-Cola, con el lema \u00abDespierta el Santa que vive en ti\u201d, propone inspirar actos de bondad esta Navidad, y que el esp\u00edritu de la temporada est\u00e9 presente todos los d\u00edas. \u00c1RBOL MAJESTUOSO El majestuoso \u00e1rbol, de 60 pies de altura, estar\u00e1 iluminando durante el mes de diciembre y ofrece el lugar ideal para compartir y celebrar en familia el verdadero esp\u00edritu de estas fiestas. Ana Virginia Garc\u00eda, directora de Marketing de Coca-Cola Rep\u00fablica Dominicana, se\u00f1al\u00f3 que con la tradici\u00f3n navide\u00f1a se desea despertar los mejores sentimientos en cada persona. Adem\u00e1s, C\u00e9sar de Le\u00f3n, director de Marketing de Bepensa Dominicana, agreg\u00f3 que hoy, con este \u00e1rbol, celebramos la magia de estar juntos y de hacer el bien. En colaboraci\u00f3n con Mucho Project, Coca-Cola distribuir\u00e1 alimentos y bebidas a personas en situaci\u00f3n de vulnerabilidad. INTERACTUAR CON SANTA CLAUS Este a\u00f1o, Coca-Cola integra la tecnolog\u00eda Create Real Magic\u2122, accesible mediante c\u00f3digos QR en sus botellas y latas, para que sus&nbsp;&nbsp;consumidores interact\u00faen con Santa Claus mediante inteligencia artificial. Durante el encendido del \u00e1rbol en la Plaza Espa\u00f1a, esta experiencia se vivi\u00f3 por primera vez en el pa\u00eds, la que destaca como una innovadora forma de conectar tradici\u00f3n con modernidad.<\/p>\n","protected":false},"author":9,"featured_media":100662,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-100661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100661"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100661\/revisions"}],"predecessor-version":[{"id":100663,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100661\/revisions\/100663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100662"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}