{"id":100925,"date":"2024-12-30T07:37:42","date_gmt":"2024-12-30T11:37:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100925"},"modified":"2024-12-30T07:37:44","modified_gmt":"2024-12-30T11:37:44","slug":"salud-publica-cierra-centro-tras-fallecimiento-de-paciente-de-edgar-contreras","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/salud-publica-cierra-centro-tras-fallecimiento-de-paciente-de-edgar-contreras\/","title":{"rendered":"Salud P\u00fablica cierra centro tras fallecimiento de paciente de Edgar Contreras"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"188\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/12\/hos.jpg\" alt=\"\" class=\"wp-image-100926\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/12\/hos.jpg 339w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/12\/hos-300x166.jpg 300w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo.- El Ministerio de Salud P\u00fablica orden\u00f3 el cierre inmediato de los quir\u00f3fanos del Centro M\u00e9dico y Diagn\u00f3stico Arroyo Hondo (CEDIAH), tras el fallecimiento de la paciente Pamela Alm\u00e1nzar luego de un procedimiento quir\u00fargico con el doctor Edgar Contreras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el comunicado, el cierre se realiz\u00f3, a trav\u00e9s de la Direcci\u00f3n de Habilitaci\u00f3n de Establecimientos y Servicios de Salud, que intervino el lugar este domingo, por supuestas violaciones reiteradas a la Ley General de Salud 42-01, en particular al incumplimiento de los protocolos de seguridad y calidad establecidos para la prestaci\u00f3n de servicios de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La paciente Pamela Alm\u00e1nzar se someti\u00f3 a varios procedimientos m\u00e9dicos en el mencionado centro y posteriormente perdi\u00f3 la vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En respuesta, el Ministerio de Salud ha citado al m\u00e9dico cirujano, anestesi\u00f3logo y al director m\u00e9dico del CEDIAH para comparecer ma\u00f1ana lunes en horas de la ma\u00f1ana, en el Viceministerio de Garant\u00eda de la Calidad y ofrecer explicaciones sobre los hechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cReiteramos nuestro compromiso con garantizar la calidad de los servicios de salud en el pa\u00eds y asegurar que ning\u00fan establecimiento opere fuera de los lineamientos establecidos por las normativas nacionales\u201d, destac\u00f3 el Ministerio en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio continuar\u00e1 supervisando y evaluando las condiciones del centro mientras avanza la investigaci\u00f3n correspondiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El Ministerio de Salud P\u00fablica orden\u00f3 el cierre inmediato de los quir\u00f3fanos del Centro M\u00e9dico y Diagn\u00f3stico Arroyo Hondo (CEDIAH), tras el fallecimiento de la paciente Pamela Alm\u00e1nzar luego de un procedimiento quir\u00fargico con el doctor Edgar Contreras. Seg\u00fan el comunicado, el cierre se realiz\u00f3, a trav\u00e9s de la Direcci\u00f3n de Habilitaci\u00f3n de Establecimientos y Servicios de Salud, que intervino el lugar este domingo, por supuestas violaciones reiteradas a la Ley General de Salud 42-01, en particular al incumplimiento de los protocolos de seguridad y calidad establecidos para la prestaci\u00f3n de servicios de salud. La paciente Pamela Alm\u00e1nzar se someti\u00f3 a varios procedimientos m\u00e9dicos en el mencionado centro y posteriormente perdi\u00f3 la vida. En respuesta, el Ministerio de Salud ha citado al m\u00e9dico cirujano, anestesi\u00f3logo y al director m\u00e9dico del CEDIAH para comparecer ma\u00f1ana lunes en horas de la ma\u00f1ana, en el Viceministerio de Garant\u00eda de la Calidad y ofrecer explicaciones sobre los hechos. \u201cReiteramos nuestro compromiso con garantizar la calidad de los servicios de salud en el pa\u00eds y asegurar que ning\u00fan establecimiento opere fuera de los lineamientos establecidos por las normativas nacionales\u201d, destac\u00f3 el Ministerio en un comunicado. El Ministerio continuar\u00e1 supervisando y evaluando las condiciones del centro mientras avanza la investigaci\u00f3n correspondiente.<\/p>\n","protected":false},"author":9,"featured_media":100926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-100925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100925"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100925\/revisions"}],"predecessor-version":[{"id":100927,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100925\/revisions\/100927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100926"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}