{"id":100993,"date":"2025-01-04T07:12:58","date_gmt":"2025-01-04T11:12:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=100993"},"modified":"2025-01-04T07:13:18","modified_gmt":"2025-01-04T11:13:18","slug":"los-chavistas-despliegan-1-200-efectivos-para-toma-posesion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-chavistas-despliegan-1-200-efectivos-para-toma-posesion\/","title":{"rendered":"Los chavistas despliegan 1.200 efectivos para toma posesi\u00f3n"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/Militares-venezolanos.jpg\" alt=\"\" class=\"wp-image-100994\" width=\"263\" height=\"175\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/Militares-venezolanos.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/Militares-venezolanos-300x200.jpg 300w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">CARACAS, 4 Ene. (EUROPA PRESS) \u2013 Las autoridades de Venezuela informaron que han desplegado 1.200 efectivos de la Fuerza Armada Nacional Bolivariana (FANB) \u00abpara la defensa de este pa\u00eds\u00bb, con motivo de la toma de posesi\u00f3n de Nicol\u00e1s Maduro como presidente el pr\u00f3ximo 10 de enero en esta capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHicimos un despliegue por la seguridad y la paz de nuestro pueblo. Somos 1.200 hombres y mujeres uniformados de esta gloriosa Fuerza Armada Nacional Bolivariana, \u00fanica en el mundo que ha salido de su frontera a dar libertad a otros pa\u00edses\u00bb, ha afirmado en un v\u00eddeo el coronel Alexander Granko Arteaga, de la Direcci\u00f3n General de Contrainteligencia Militar (Dgcim).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DIDE VENEZUELA \u00abEST\u00c1 AMENAZADA\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras alegar que el pa\u00eds \u00abest\u00e1 amenazado\u00bb, dijo: \u00abVamos a darle seguridad al pueblo. Vamos a garantizar que el 10 de enero seguramente el presidente. El 10 nosotros nos juramentamos con \u00e9l. Vamos juntos por la victoria\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abVamos a garantizar la paz como les dije. Aqu\u00ed nuestra revoluci\u00f3n, nuestro pa\u00eds est\u00e1 amenazado. Hemos ido desarrollando operaciones en contra de mercenarios. Han dado fruct\u00edferos resultados y este a\u00f1o no va a ser excepcional\u00bb, recalc\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venezuela celebr\u00f3 a finales de julio unas elecciones presidenciales tras las que el presidente Maduro se reafirm\u00f3 como triunfador, si bien la oposici\u00f3n neg\u00f3 los resultados y asegura contar con las actas electorales que avalan el triunfo de Gonz\u00e1lez, exiliado en Espa\u00f1a y buscado por la Justicia venezolana, aunque asegura que tomar\u00e1 posesi\u00f3n del cargo el pr\u00f3ximo d\u00eda 10 de enero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LA POSICI\u00d3N GONZ\u00c1LEZ URRUTIA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Urrutia ha asegurado que no tiene \u00abrestricciones\u00bb para regresar a Venezuela y que no revelar\u00e1 \u00abni el d\u00eda ni la forma\u00bb en la que volver\u00e1 a su pa\u00eds, siempre con vistas a tomar posesi\u00f3n el 10 de enero pese a una posible detenci\u00f3n por parte de las autoridades chavistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CARACAS, 4 Ene. (EUROPA PRESS) \u2013 Las autoridades de Venezuela informaron que han desplegado 1.200 efectivos de la Fuerza Armada Nacional Bolivariana (FANB) \u00abpara la defensa de este pa\u00eds\u00bb, con motivo de la toma de posesi\u00f3n de Nicol\u00e1s Maduro como presidente el pr\u00f3ximo 10 de enero en esta capital. \u00abHicimos un despliegue por la seguridad y la paz de nuestro pueblo. Somos 1.200 hombres y mujeres uniformados de esta gloriosa Fuerza Armada Nacional Bolivariana, \u00fanica en el mundo que ha salido de su frontera a dar libertad a otros pa\u00edses\u00bb, ha afirmado en un v\u00eddeo el coronel Alexander Granko Arteaga, de la Direcci\u00f3n General de Contrainteligencia Militar (Dgcim). DIDE VENEZUELA \u00abEST\u00c1 AMENAZADA\u00bb Tras alegar que el pa\u00eds \u00abest\u00e1 amenazado\u00bb, dijo: \u00abVamos a darle seguridad al pueblo. Vamos a garantizar que el 10 de enero seguramente el presidente. El 10 nosotros nos juramentamos con \u00e9l. Vamos juntos por la victoria\u00bb. \u00abVamos a garantizar la paz como les dije. Aqu\u00ed nuestra revoluci\u00f3n, nuestro pa\u00eds est\u00e1 amenazado. Hemos ido desarrollando operaciones en contra de mercenarios. Han dado fruct\u00edferos resultados y este a\u00f1o no va a ser excepcional\u00bb, recalc\u00f3. Venezuela celebr\u00f3 a finales de julio unas elecciones presidenciales tras las que el presidente Maduro se reafirm\u00f3 como triunfador, si bien la oposici\u00f3n neg\u00f3 los resultados y asegura contar con las actas electorales que avalan el triunfo de Gonz\u00e1lez, exiliado en Espa\u00f1a y buscado por la Justicia venezolana, aunque asegura que tomar\u00e1 posesi\u00f3n del cargo el pr\u00f3ximo d\u00eda 10 de enero. LA POSICI\u00d3N GONZ\u00c1LEZ URRUTIA Urrutia ha asegurado que no tiene \u00abrestricciones\u00bb para regresar a Venezuela y que no revelar\u00e1 \u00abni el d\u00eda ni la forma\u00bb en la que volver\u00e1 a su pa\u00eds, siempre con vistas a tomar posesi\u00f3n el 10 de enero pese a una posible detenci\u00f3n por parte de las autoridades chavistas.<\/p>\n","protected":false},"author":9,"featured_media":100994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-100993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=100993"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100993\/revisions"}],"predecessor-version":[{"id":100995,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/100993\/revisions\/100995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/100994"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=100993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=100993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=100993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}