{"id":10111,"date":"2014-11-04T13:00:03","date_gmt":"2014-11-04T17:00:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10111"},"modified":"2014-11-03T20:32:44","modified_gmt":"2014-11-04T00:32:44","slug":"dile-adios-a-la-depresion-y-mejora-tu-salud-emocional","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dile-adios-a-la-depresion-y-mejora-tu-salud-emocional\/","title":{"rendered":"Dile adi\u00f3s a la depresi\u00f3n y mejora tu salud emocional"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/istockdepresion-salud-emocional-felicidad.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10112 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/istockdepresion-salud-emocional-felicidad-300x200.jpg\" alt=\"istockdepresion-salud-emocional-felicidad\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/istockdepresion-salud-emocional-felicidad-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/istockdepresion-salud-emocional-felicidad.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00bfQui\u00e9n no ha pasado por un momento dif\u00edcil? Si lloraste y cre\u00edste que tu situaci\u00f3n no ten\u00eda remedio recuerda lo que dicen: \u201ctodo tiene soluci\u00f3n, lo \u00fanico que no la tiene es la muerte\u201d. Hay que aprender a dejar de sentirse mal y disfrutar de la <label>vida<\/label>.<!--more--><\/p>\n<p>La Encuesta Nacional de la Juventud 2010 arroj\u00f3 como dato que entre los j\u00f3venes de 12 a 29 de a\u00f1os las tres principales actividades que realizan para divertirse son: reunirse con amigos, ver televisi\u00f3n y estar con su pareja. Sin duda, estas actividades son ben\u00e9ficas, pero no bastan para que lograr una buena <label>salud<\/label> emocional.<\/p>\n<p>Es importante que dediques un momento a reflexionar sobre las maneras en las que buscas diariamente la alegr\u00eda y <label>bienestar<\/label> en tu vida; si lo haces ser\u00e1s capaz de afrontar mejor lo que venga en el futuro, como separaciones de pareja o amistades, <label>cambios<\/label> de escuela, despidos en el <label>trabajo<\/label>, entre otros.<\/p>\n<p><strong>\u00bfPor d\u00f3nde comenzar?<\/strong><\/p>\n<p>La depresi\u00f3n se puede apoderar de ti f\u00e1cilmente, pero si tienes tu mente ocupada y tu coraz\u00f3n en paz no habr\u00e1 manera de que eche ra\u00edces. Te compartimos tres consejos que te ayudar\u00e1n:<\/p>\n<p>1. Piensa si tienes pendientes, asuntos no resueltos, sue\u00f1os sin cumplir u otras situaciones aplazadas que no has realizado por falta de decisi\u00f3n. Un caso t\u00edpico es cuando una persona ha querido tomar clases de alg\u00fan idioma o disciplina, pero nunca ha buscado escuelas, opciones o becas. No dejes que esto te pase a ti.<\/p>\n<p>2. Reflexiona sobre las causas que han hecho que te distraigas de lo que te propones y por consecuencia, te aleja de que vivas al m\u00e1ximo. \u00a1Fuera pretextos! Todo lo que haces y dejas de hacer impacta en tu estado de \u00e1nimo, no olvides que t\u00fa y nadie m\u00e1s es responsable de tu bienestar emocional.<\/p>\n<p>3. Planea, cumple lo que te propones y adopta como estilo de vida el esfuerzo, as\u00ed sabr\u00e1s que t\u00fa eres tu mejor compa\u00f1\u00eda.<\/p>\n<p><strong>Punto de reflexi\u00f3n<\/strong><\/p>\n<p>Bronnie Ware, autora de \u2018De qu\u00e9 te arrepentir\u00e1s antes de morir\u2019 (Editorial Grijalbo) explica que en su experiencia en el cuidado de personas con enfermedades en estado terminal, un tema que los pacientes platican de manera frecuente es si han logrado o no ser felices. La autora comparte un testimonio de una de las mujeres que acompa\u00f1\u00f3 en sus \u00faltimos d\u00edas de vida, de nombre Cath: \u201cEs importante, esforzarse por encontrar un prop\u00f3sito en la vida y contribuir a que el mundo sea mejor de la manera que sea. Pero que tu felicidad dependa del resultado final no es la mejor manera de conseguirlo. Sentirse afortunada cada d\u00eda es la clave para tomar conciencia de que una es feliz ahora y disfrutar de ello, y ni cuando los resultados llegan o sucede tal o cual cosa\u201d.<\/p>\n<p>Adem\u00e1s, la autora recomienda para disfrutar de la fabulosa experiencia de la existencia: \u201cS\u00e9 quien eres, busca el equilibrio, habla con franqueza, valora a quienes te quieren, date permiso para ser feliz. Si lo haces, no solo estar\u00e1s mostrando respeto por ti mismo, sino tambi\u00e9n por todos los que cayeron en la desesperaci\u00f3n durante sus semanas finales por no haber tenido el valor de hacerlo antes. T\u00fa eliges. Es tu vida\u201d, finaliza la autora.<\/p>\n<p>Para evitar la depresi\u00f3n divi\u00e9rtete, dedica tiempo a tus amigos, lee, dona tu tiempo a alguna causa que te motive, y adem\u00e1s no olvides ir tras tus sue\u00f1os.<\/p>\n<p>Fuente: <a href=\"http:\/\/vidayestilo.terra.com\/salud\/despidete-de-la-depresion-y-mejora-tu-salud-emocional,ace6b3301c869410VgnVCM4000009bcceb0aRCRD.html\" target=\"_blank\">Terra<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n no ha pasado por un momento dif\u00edcil? Si lloraste y cre\u00edste que tu situaci\u00f3n no ten\u00eda remedio recuerda lo que dicen: \u201ctodo tiene soluci\u00f3n, lo \u00fanico que no la tiene es la muerte\u201d. Hay que aprender a dejar de sentirse mal y disfrutar de la vida.<\/p>\n","protected":false},"author":3,"featured_media":10112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10111"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10111\/revisions"}],"predecessor-version":[{"id":10113,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10111\/revisions\/10113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10112"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}