{"id":10117,"date":"2014-11-04T19:00:00","date_gmt":"2014-11-04T23:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10117"},"modified":"2014-11-03T20:50:06","modified_gmt":"2014-11-04T00:50:06","slug":"por-que-el-ejercicio-sirve-como-un-antidepresivo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/por-que-el-ejercicio-sirve-como-un-antidepresivo\/","title":{"rendered":"\u00bfPor qu\u00e9 el ejercicio sirve como un antidepresivo?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/canciones-para-hacer-ejercicio-2012.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10118 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/canciones-para-hacer-ejercicio-2012-300x200.jpg\" alt=\"canciones-para-hacer-ejercicio-2012\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/canciones-para-hacer-ejercicio-2012-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/canciones-para-hacer-ejercicio-2012.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Si realizas actividad <label>f\u00edsica<\/label>, probablemente has notado que tu estado de \u00e1nimo ha cambiado para bien. Esto tiene una explicaci\u00f3n, ya que el ejercicio es una de las mejores opciones para mantener la sensaci\u00f3n de felicidad. Estudios recientes confirman que el ejercicio funciona como un antidepresivo.<!--more--><\/p>\n<p>Seguramente has notado que cuando realizas una actividad f\u00edsica cambia tu estado de \u00e1nimo. Efectivamente, esta es una de las mejores opciones para mantener la sensaci\u00f3n de felicidad. Incluso, recientes investigaciones confirman que el ejercicio funciona como un antidepresivo.<\/p>\n<p>Con el ejercicio f\u00edsico se generan <label>cambios<\/label> en el sistema m\u00fasculo esquel\u00e9tico que ayudan a expulsar de la sangre una sustancia que se acumula a causa del estr\u00e9s y se sabe que son perjudiciales para el cerebro\u201d, explica Jorge Ruas, investigador del Departamento de Fisiolog\u00eda y Farmacolog\u00eda, Instituto Karolinska.<\/p>\n<p><strong>Cambios en el m\u00fasculo esquel\u00e9tico, la clave<\/strong><\/p>\n<p>De acuerdo con un estudio del Instituto Karolinska, el ejercicio aumenta en el m\u00fasculo esquel\u00e9tico la prote\u00edna PGC-1A1 y las enzimas KAT, que convierten quinurenina (sustancia formada durante el estr\u00e9s) en \u00e1cido quinur\u00e9nico. Esta \u00faltima sustancia no es capaz de pasar de la sangre al cerebro y funciona como un mecanismo de <label>protecci\u00f3n<\/label>contra la depresi\u00f3n.<\/p>\n<p>Es posible que este hallazgo lleve a encontrar un tratamiento farmacol\u00f3gico para aliviar la depresi\u00f3n. La clave est\u00e1 en la funci\u00f3n de estas sustancias en el m\u00fasculo esquel\u00e9tico en lugar de dirigirse al cerebro\u201d, dice Ruas.<\/p>\n<p>Con el ejercicio se generan cambios bioqu\u00edmicos sobre el m\u00fasculo esquel\u00e9tico que a su vez provocan un efecto de desintoxicaci\u00f3n que protege al cerebro de la depresi\u00f3n, as\u00ed como de bajos estados de \u00e1nimo.<\/p>\n<p><strong>Ejercicio, ant\u00eddoto contra la depresi\u00f3n<\/strong><\/p>\n<p>La evidencia de que el ejercicio regular mejora el estado de \u00e1nimo en personas depresivas ya se hab\u00eda establecido en estudios anterior, la diferencia es que se trataba a nivel cerebral.<\/p>\n<p>Cuando se realiza una actividad f\u00edsica intensa y regular, por lo menos tres veces a la semana durante 60 minutos, se liberan endorfinas, sustancia que aumentan el estado de<label>bienestar<\/label> y disminuyen la sensaci\u00f3n de dolor emocional.<\/p>\n<p>El ejercicio es un antidepresivo <label>natural<\/label> porque estimula las funciones de la norepinefrina, neurotransmisor que mejorar el estado de \u00e1nimo.<\/p>\n<p>Otra explicaci\u00f3n es que al aumentar la temperatura del cuerpo se reduce la tensi\u00f3n muscular, creando una sensaci\u00f3n de relajaci\u00f3n.<\/p>\n<p>A nivel emocional, permite acabar con los pensamientos negativos; potencia las habilidades y refuerza la creencia de que es f\u00e1cil cumplir un objetivo, por ejemplo, lograr perder peso o ponerte en forma.<\/p>\n<p>No es exagerado decir que el ejercicio regular mejora las funciones y el desempe\u00f1o cerebral. Es es tan eficaz como cualquier antidepresivo. En realidad, una medicina maravillosa\u201d, afirma John Ratey, profesor asociado de psiquiatr\u00eda en Harvard Medical School.<\/p>\n<p>Para obtener los beneficios del ejercicio como un antidepresivo natural es necesario activarse. Lo ideal es mantener rutinas de resistencia y aer\u00f3bicas. De tres a cinco sesiones por semana, con una duraci\u00f3n de 45 a 60 minutos, sugiere Chad Rethorst, del Departamento de Psiquiatr\u00eda de la Universidad de Texas Southwestern Medical Center, Dallas.<\/p>\n<p>As\u00ed que al hacer ejercicio tambi\u00e9n te proteges de la depresi\u00f3n. \u00bfCu\u00e1nto tiempo dedicas a la semana?<\/p>\n<p>Fuente: <a href=\"http:\/\/bienestar.salud180.com\/nutricion-y-ejercicio\/por-que-el-ejercicio-funciona-como-un-antidepresivo\" target=\"_blank\">Salud 180<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si realizas actividad f\u00edsica, probablemente has notado que tu estado de \u00e1nimo ha cambiado para bien. Esto tiene una explicaci\u00f3n, ya que el ejercicio es una de las mejores opciones para mantener la sensaci\u00f3n de felicidad. Estudios recientes confirman que el ejercicio funciona como un antidepresivo.<\/p>\n","protected":false},"author":3,"featured_media":10118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10117"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10117\/revisions"}],"predecessor-version":[{"id":10119,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10117\/revisions\/10119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10118"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}