{"id":10126,"date":"2014-11-04T15:00:50","date_gmt":"2014-11-04T19:00:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10126"},"modified":"2014-11-03T21:05:53","modified_gmt":"2014-11-04T01:05:53","slug":"por-que-la-tierra-se-llama-asi","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/por-que-la-tierra-se-llama-asi\/","title":{"rendered":"\u00bfPor qu\u00e9 la Tierra se llama as\u00ed?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/141031173009_curiosos_tierra_promos_624x351_thinkstock.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10127 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/141031173009_curiosos_tierra_promos_624x351_thinkstock-300x200.jpg\" alt=\"141031173009_curiosos_tierra_promos_624x351_thinkstock\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/141031173009_curiosos_tierra_promos_624x351_thinkstock-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/141031173009_curiosos_tierra_promos_624x351_thinkstock.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Si bien es cierto que cada lenguaje tiene su propio nombre para nuestro planeta, todos tienen algo en com\u00fan: se derivan de una palabra que significa \u00absuelo\u00bb, \u00abtierra\u00bb o -en ciertos casos- \u00abuniverso\u00bb o \u00abcreaci\u00f3n\u00bb. Descubre m\u00e1s ac\u00e1.<!--more--><\/p>\n<p>En espa\u00f1ol, proviene del lat\u00edn \u00abterra\u00bb con mismo significado que el nuestro y relacionado con el verbo \u00abtorror\u00bb, que significa secar o chamuscar. Se piensa que quiz\u00e1s se debe a que en la filosof\u00eda presocr\u00e1tica, una l\u00ednea de pensamiento era que la tierra proven\u00eda del<label>agua<\/label> que se sec\u00f3.<\/p>\n<p>En ingl\u00e9s, la palabra \u00abEarth\u00bb se deriva de la germana \u00aberde\u00bb, que significa \u00absuelo\u00bb.<\/p>\n<p>Las ra\u00edces de esas palabras datan de una \u00e9poca en la que la humanidad aun no sab\u00eda que la Tierra era un planeta.<\/p>\n<p>Las palabras s\u00f3lo significaban el suelo bajo sus <label>pies<\/label>, y fueron adoptadas como el nombre del planeta despu\u00e9s.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2014\/11\/141031_respuestas_curiosos_1nov_finde_dv\" target=\"_blank\">BBC<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si bien es cierto que cada lenguaje tiene su propio nombre para nuestro planeta, todos tienen algo en com\u00fan: se derivan de una palabra que significa \u00absuelo\u00bb, \u00abtierra\u00bb o -en ciertos casos- \u00abuniverso\u00bb o \u00abcreaci\u00f3n\u00bb. Descubre m\u00e1s ac\u00e1.<\/p>\n","protected":false},"author":3,"featured_media":10127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-10126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10126"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10126\/revisions"}],"predecessor-version":[{"id":10128,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10126\/revisions\/10128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10127"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}