{"id":101288,"date":"2025-01-18T08:25:11","date_gmt":"2025-01-18T12:25:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=101288"},"modified":"2025-01-18T08:39:46","modified_gmt":"2025-01-18T12:39:46","slug":"adios-a-las-fiestas-a-saludar-la-salud-bucal-luego-de-los-excesos-cometidos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/adios-a-las-fiestas-a-saludar-la-salud-bucal-luego-de-los-excesos-cometidos\/","title":{"rendered":"Adi\u00f3s a las fiestas: \u00a1A saludar la salud bucal luego de los excesos cometidos!"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/67893ddd13015.jpeg\" alt=\"\" class=\"wp-image-101289\" width=\"227\" height=\"151\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/67893ddd13015.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/67893ddd13015-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/67893ddd13015-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/67893ddd13015-600x400.jpeg 600w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Se terminaron las fiestas de fin de a\u00f1o, pero, \u00bfQu\u00e9 se hace con las consecuencias de los excesos de alimentaci\u00f3n propios de esta \u00e9poca, tomando en cuenta que pueden suponer un riesgo para la salud bucal?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La respuesta la ofrece Heitor Serapicos, cirujano dentista egresado de la Universidad de S\u00e3o Paulo (USP), quien asegura que el consumo de dulces, bebidas alcoh\u00f3licas y alimentos grasos contribuye al aumento de las caries, la inflamaci\u00f3n de las enc\u00edas e incluso, la erosi\u00f3n de los dientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El especialista, al igual que otros expertos, se\u00f1alan que un consumo elevado de az\u00facar y bebidas \u00e1cidas puede alterar el equilibrio de la microbiota bucal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl az\u00facar favorece la producci\u00f3n de \u00e1cidos por parte de las bacterias presentes en la boca, provocando la desmineralizaci\u00f3n del esmalte y aumentando el riesgo de caries. Las bebidas alcoh\u00f3licas alteran el pH de la boca, resecando las mucosas y debilitando la barrera gingival protectora, lo que puede provocar inflamaciones como la gingivitis\u201d, explica Serapicos, con especializaci\u00f3n en Periodoncia por la Facultad S\u00e3o Leopoldo Mandic.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde su \u00f3ptica, estos cambios no s\u00f3lo afectan la est\u00e9tica de la sonrisa, sino tambi\u00e9n la salud sist\u00e9mica. Los estudios ya han relacionado los problemas bucales con afecciones como las enfermedades cardiovasculares, lo que refuerza la importancia de la atenci\u00f3n preventiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de las fiestas navide\u00f1as, es muy recomendable una limpieza dental profesional para eliminar el biofilm acumulado. Los procedimientos guiados por las nuevas tecnolog\u00edas, han destacado por ofrecer un abordaje m\u00e1s preciso y c\u00f3modo. Esta t\u00e9cnica permite la eliminaci\u00f3n eficaz de placas y manchas, centr\u00e1ndose en preservar la estructura de los dientes y los tejidos blandos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">CONSEJOS PR\u00c1CTICOS&nbsp;PARA EL CUIDADO DIARIO<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de programar citas peri\u00f3dicas, algunas pr\u00e1cticas sencillas pueden ayudar a preservar la salud bucal:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Evite cepillarse los dientes inmediatamente despu\u00e9s de alimentos \u00e1cidos. Lo aconsejabla es enjuagarse la boca con agua y esperar 30 minutos antes de cepillarse para evitar da\u00f1ar el esmalte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Masticar chicle sin az\u00facar: Estimula la salivaci\u00f3n para neutralizar los \u00e1cidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Elige dulces durante las comidas principales: El alto flujo salival durante las comidas protege tus dientes de forma natural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Reemplace el az\u00facar refinada con alternativas naturales: esto puede reducir los impactos negativos en la salud bucal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">LA PREVENCI\u00d3N ES LA CLAVE<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Heitor Serapicos, gerente nacional de ventas del \u00e1rea odontol\u00f3gica de la firma suiza EMS (Electro Medical Systems), las visitas peri\u00f3dicas al dentista permiten un seguimiento m\u00e1s eficaz de la salud bucal, adem\u00e1s de prevenir problemas m\u00e1s graves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Las modernas t\u00e9cnicas de profilaxis, combinadas con buenos h\u00e1bitos de higiene, son fundamentales para garantizar una sonrisa sana y sin complicaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante confirmar que la cl\u00ednica a la que se asista, cuente con el protocolo GBT (Guided Biofilm Therapy), \u201cuna evoluci\u00f3n en la profilaxis, que brinda una atenci\u00f3n m\u00e1s personalizada y menos invasiva, adem\u00e1s de incentivar al paciente a mantener la rutina de visitas peri\u00f3dicas al dentista\u201d, comenta Serapicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se terminaron las fiestas de fin de a\u00f1o, pero, \u00bfQu\u00e9 se hace con las consecuencias de los excesos de alimentaci\u00f3n propios de esta \u00e9poca, tomando en cuenta que pueden suponer un riesgo para la salud bucal?&nbsp; La respuesta la ofrece Heitor Serapicos, cirujano dentista egresado de la Universidad de S\u00e3o Paulo (USP), quien asegura que el consumo de dulces, bebidas alcoh\u00f3licas y alimentos grasos contribuye al aumento de las caries, la inflamaci\u00f3n de las enc\u00edas e incluso, la erosi\u00f3n de los dientes. El especialista, al igual que otros expertos, se\u00f1alan que un consumo elevado de az\u00facar y bebidas \u00e1cidas puede alterar el equilibrio de la microbiota bucal.&nbsp; \u201cEl az\u00facar favorece la producci\u00f3n de \u00e1cidos por parte de las bacterias presentes en la boca, provocando la desmineralizaci\u00f3n del esmalte y aumentando el riesgo de caries. Las bebidas alcoh\u00f3licas alteran el pH de la boca, resecando las mucosas y debilitando la barrera gingival protectora, lo que puede provocar inflamaciones como la gingivitis\u201d, explica Serapicos, con especializaci\u00f3n en Periodoncia por la Facultad S\u00e3o Leopoldo Mandic. Desde su \u00f3ptica, estos cambios no s\u00f3lo afectan la est\u00e9tica de la sonrisa, sino tambi\u00e9n la salud sist\u00e9mica. Los estudios ya han relacionado los problemas bucales con afecciones como las enfermedades cardiovasculares, lo que refuerza la importancia de la atenci\u00f3n preventiva. Despu\u00e9s de las fiestas navide\u00f1as, es muy recomendable una limpieza dental profesional para eliminar el biofilm acumulado. Los procedimientos guiados por las nuevas tecnolog\u00edas, han destacado por ofrecer un abordaje m\u00e1s preciso y c\u00f3modo. Esta t\u00e9cnica permite la eliminaci\u00f3n eficaz de placas y manchas, centr\u00e1ndose en preservar la estructura de los dientes y los tejidos blandos. CONSEJOS PR\u00c1CTICOS&nbsp;PARA EL CUIDADO DIARIO Adem\u00e1s de programar citas peri\u00f3dicas, algunas pr\u00e1cticas sencillas pueden ayudar a preservar la salud bucal: 1. Evite cepillarse los dientes inmediatamente despu\u00e9s de alimentos \u00e1cidos. Lo aconsejabla es enjuagarse la boca con agua y esperar 30 minutos antes de cepillarse para evitar da\u00f1ar el esmalte. 2. Masticar chicle sin az\u00facar: Estimula la salivaci\u00f3n para neutralizar los \u00e1cidos. 3. Elige dulces durante las comidas principales: El alto flujo salival durante las comidas protege tus dientes de forma natural. 4. Reemplace el az\u00facar refinada con alternativas naturales: esto puede reducir los impactos negativos en la salud bucal. LA PREVENCI\u00d3N ES LA CLAVE Seg\u00fan Heitor Serapicos, gerente nacional de ventas del \u00e1rea odontol\u00f3gica de la firma suiza EMS (Electro Medical Systems), las visitas peri\u00f3dicas al dentista permiten un seguimiento m\u00e1s eficaz de la salud bucal, adem\u00e1s de prevenir problemas m\u00e1s graves. &nbsp;Las modernas t\u00e9cnicas de profilaxis, combinadas con buenos h\u00e1bitos de higiene, son fundamentales para garantizar una sonrisa sana y sin complicaciones. Es importante confirmar que la cl\u00ednica a la que se asista, cuente con el protocolo GBT (Guided Biofilm Therapy), \u201cuna evoluci\u00f3n en la profilaxis, que brinda una atenci\u00f3n m\u00e1s personalizada y menos invasiva, adem\u00e1s de incentivar al paciente a mantener la rutina de visitas peri\u00f3dicas al dentista\u201d, comenta Serapicos.<\/p>\n","protected":false},"author":9,"featured_media":101289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-101288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=101288"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101288\/revisions"}],"predecessor-version":[{"id":101290,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101288\/revisions\/101290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/101289"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=101288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=101288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=101288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}