{"id":10129,"date":"2014-11-04T12:08:32","date_gmt":"2014-11-04T16:08:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10129"},"modified":"2014-11-03T21:11:29","modified_gmt":"2014-11-04T01:11:29","slug":"aplicacion-detecta-si-eres-adicto-al-celular","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aplicacion-detecta-si-eres-adicto-al-celular\/","title":{"rendered":"Aplicaci\u00f3n detecta si eres adicto al celular"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/apl.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10130 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/apl-300x200.jpg\" alt=\"apl\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/apl-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/apl.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Cheky es una nueva aplicaci\u00f3n que calcula el n\u00famero de veces que miramos el <label>m\u00f3vil<\/label>.<!--more--><\/p>\n<p>Que no podemos salir de <label>casa<\/label> sin nuestro tel\u00e9fono m\u00f3vil es una realidad. La mayor\u00eda no reconocemos nuestra adicci\u00f3n a este <label>aparato<\/label>, pero cada vez son m\u00e1s habituales escenas en las que estamos m\u00e1s atentos del m\u00f3vil que de hablar con el que tenemos en frente.<\/p>\n<p>\u00bfCu\u00e1ntas veces sacas el m\u00f3vil del bolsillo? Y es que este gesto se ha convertido en una man\u00eda y, ahora, una nueva App se encargar\u00e1 de contar por nosotros el n\u00famero de veces que lo consultamos.<\/p>\n<p>Se trata de Cheky, una aplicaci\u00f3n que calcula el n\u00famero de veces que hemos mirado el aparato. Da igual el motivo de la consulta -ya sea un WhatsApp, mirar el correo o simplemente consultar la hora- la aplicaci\u00f3n monitoriza la <label>frecuencia<\/label> con la que desbloqueamos y consultamos nuestro tel\u00e9fono.<\/p>\n<p>Los creadores de la aplicaci\u00f3n son Calm. Sin embargo, esta <label>idea<\/label> no es nueva. Los desarrolladores de Moment ya andaban detr\u00e1s de la idea pero, a diferencia de Checky, \u00e9sta indica el tiempo que pasamos mirando la pantalla.<\/p>\n<p>Con esta nueva aplicaci\u00f3n, sus creadores pretenden concienciar a la gente de lo enganchados que estamos al tel\u00e9fono con el fin de disminuir el n\u00famero de veces que lo consultamos, adem\u00e1s de dar publicidad a Calm, una p\u00e1gina de meditaci\u00f3n y relajaci\u00f3n.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.que.es\/ultimas-noticias\/curiosas\/201410311934-aplicacion-detecta-eres-adicto-movil.html\" target=\"_blank\">Q!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cheky es una nueva aplicaci\u00f3n que calcula el n\u00famero de veces que miramos el m\u00f3vil.<\/p>\n","protected":false},"author":3,"featured_media":10130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-10129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10129"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10129\/revisions"}],"predecessor-version":[{"id":10131,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10129\/revisions\/10131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10130"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}