{"id":101433,"date":"2025-01-24T07:54:17","date_gmt":"2025-01-24T11:54:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=101433"},"modified":"2025-01-24T07:54:18","modified_gmt":"2025-01-24T11:54:18","slug":"celebran-en-montecristi-con-exito-el-festi-mayimbe-2025","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/celebran-en-montecristi-con-exito-el-festi-mayimbe-2025\/","title":{"rendered":"Celebran en Montecristi con \u00e9xito el \u00abFesti Mayimbe 2025\u00bb"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/fest-300x210-1.jpeg\" alt=\"\" class=\"wp-image-101434\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/fest-300x210-1.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/fest-300x210-1-75x52.jpeg 75w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">MONTECRISTI, Rep\u00fablica Dominicana.- Miles de personas asistieron al \u00a8Festi Mayimbe 2025\u00a8, en esta provincia, que en su 37 aniversario recibi\u00f3 figuras ic\u00f3nicas de la m\u00fasica de Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Artistas como Fernando Villalona, (Mayimbe), El Chaval, Ram\u00f3n Orlando, Steffany Constanza, Chimbala, Crazy Design y Davicito Kada ofrecieron sus interpretaciones ante un abarrotado Estadio Municipal Loma de Cabrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el evento, los alcaldes de la zona, incluyendo a los de Dajab\u00f3n, Montecristi, Loma de Cabrera y Casta\u00f1uela, rindieron homenaje a Villalona, un reconocido cantante de m\u00fasica popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ALCALD\u00cdAS RENDIR\u00c1N HOMENAJE AL MAYIMBE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El alcalde de Dajab\u00f3n anunci\u00f3 que sus pares de la provincia de Montecristi rendir\u00e1n tributo a Mayimbe (Montecristi 1955), luego de solicitar a la sala capitular que una calle en cada municipio ostente su nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La presencia del artista emocion\u00f3 a los miles de asistentes al Festival, en especial cuando son\u00f3 su \u00e9xito \u00a8Quijote\u00a8 y al un\u00edsono estallaron fuegos artificiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Festival cont\u00f3 con el respaldo del presidente de la Rep\u00fablica, Luis Abinader, as\u00ed como del Ministerio de Turismo y otras instituciones, lo que permiti\u00f3 alcanzar un r\u00e9cord de asistencia in\u00e9dito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTECRISTI, Rep\u00fablica Dominicana.- Miles de personas asistieron al \u00a8Festi Mayimbe 2025\u00a8, en esta provincia, que en su 37 aniversario recibi\u00f3 figuras ic\u00f3nicas de la m\u00fasica de Rep\u00fablica Dominicana. Artistas como Fernando Villalona, (Mayimbe), El Chaval, Ram\u00f3n Orlando, Steffany Constanza, Chimbala, Crazy Design y Davicito Kada ofrecieron sus interpretaciones ante un abarrotado Estadio Municipal Loma de Cabrera. Durante el evento, los alcaldes de la zona, incluyendo a los de Dajab\u00f3n, Montecristi, Loma de Cabrera y Casta\u00f1uela, rindieron homenaje a Villalona, un reconocido cantante de m\u00fasica popular. ALCALD\u00cdAS RENDIR\u00c1N HOMENAJE AL MAYIMBE El alcalde de Dajab\u00f3n anunci\u00f3 que sus pares de la provincia de Montecristi rendir\u00e1n tributo a Mayimbe (Montecristi 1955), luego de solicitar a la sala capitular que una calle en cada municipio ostente su nombre. &nbsp;La presencia del artista emocion\u00f3 a los miles de asistentes al Festival, en especial cuando son\u00f3 su \u00e9xito \u00a8Quijote\u00a8 y al un\u00edsono estallaron fuegos artificiales. El Festival cont\u00f3 con el respaldo del presidente de la Rep\u00fablica, Luis Abinader, as\u00ed como del Ministerio de Turismo y otras instituciones, lo que permiti\u00f3 alcanzar un r\u00e9cord de asistencia in\u00e9dito.<\/p>\n","protected":false},"author":9,"featured_media":101434,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-101433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=101433"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101433\/revisions"}],"predecessor-version":[{"id":101435,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101433\/revisions\/101435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/101434"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=101433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=101433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=101433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}