{"id":101511,"date":"2025-01-28T06:40:23","date_gmt":"2025-01-28T10:40:23","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=101511"},"modified":"2025-01-28T06:40:25","modified_gmt":"2025-01-28T10:40:25","slug":"eeuu-trump-firma-orden-excluye-ejercito-miembros-transgenero","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eeuu-trump-firma-orden-excluye-ejercito-miembros-transgenero\/","title":{"rendered":"EEUU: Trump firma orden excluye Ej\u00e9rcito miembros transg\u00e9nero"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/01\/Trump-firmando-e1737672264672-300x200-1.jpg\" alt=\"\" class=\"wp-image-101512\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">WASHINGTON, 28 Ene.-&nbsp;El presidente de Estados Unidos, Donald Trump, ha firmado una serie de \u00f3rdenes ejecutivas para reestructurar el Ej\u00e9rcito estadounidense, incluida la prohibici\u00f3n de que los militares transg\u00e9nero sirvan en las Fuerzas Armadas del pa\u00eds o la reincorporaci\u00f3n con pago retroactivo de los miembros que fueron dados de baja por negarse a vacunarse contra la COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump ha considerado que \u00abla b\u00fasqueda de la excelencia militar no puede diluirse para dar cabida a agendas pol\u00edticas u otras ideolog\u00edas perjudiciales para la cohesi\u00f3n de la unidad\u00bb, si bien \u00abrecientemente las Fuerzas Armadas se han visto afectadas por una ideolog\u00eda de g\u00e9nero radical para apaciguar a activistas que no se preocupan por los requisitos del servicio militar, como la salud f\u00edsica y mental\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, ha indicado que \u00abexpresar una \u2018identidad de g\u00e9nero\u2019 falsa que difiera del sexo de una persona no puede satisfacer los rigurosos est\u00e1ndares necesarios para el servicio militar\u00bb, porque, \u00abm\u00e1s all\u00e1 de las intervenciones m\u00e9dicas hormonales y quir\u00fargicas que implica, la adopci\u00f3n de una identidad de g\u00e9nero incompatible con el sexo de una persona entra en conflicto con el compromiso de un soldado con un estilo de vida honorable, veraz y disciplinado\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, ha eliminado los programas de diversidad, equidad e inclusi\u00f3n (DEI, por sus siglas en ingl\u00e9s), al considerar que estas acciones \u00absocavan\u00bb la meritocracia y \u00ablas conciencias de los estadounidenses al participar en una discriminaci\u00f3n racial y sexual odiosa\u00bb. \u00abNing\u00fan individuo o grupo dentro de nuestras Fuerzas Armadas debe ser preferido o desfavorecido por motivos de sexo, raza, etnia, color o credo\u00bb, ha concluido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El inquilino de la Casa Blanca ha firmado un decreto por el cual readmitir\u00e1 a aquellos militares que no se vacunaron de la COVID-19 a modo de \u00abreparaci\u00f3n\u00bb, despu\u00e9s de que en 2021 se ordenara que todos recibieran la vacuna y en 2023 se les rescindiera el mandato, lo que era \u00abuna carga injusta, excesivamente amplia y completamente innecesaria\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl Ej\u00e9rcito despidi\u00f3 injustamente a quienes se negaron a vacunarse, independientemente de los a\u00f1os de servicio prestados a nuestra naci\u00f3n, despu\u00e9s de no conceder a muchos de ellos una exenci\u00f3n que deber\u00edan haber recibido. La reparaci\u00f3n por parte del Gobierno federal de cualquier despido injustificado est\u00e1 pendiente\u00bb, reza el texto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, el mandatario ha ordenado construir un sistema de defensa inspirado en el modelo israel\u00ed, la C\u00fapula de Hierro, al sostener que \u00abla amenaza de ataque con misiles bal\u00edsticos, hipers\u00f3nicos y de crucero, as\u00ed como otros ataques a\u00e9reos avanzados, sigue siendo la amenaza m\u00e1s catastr\u00f3fica que enfrenta Estado Unidos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEn los \u00faltimos 40 a\u00f1os, en lugar de disminuir, la amenaza de las armas estrat\u00e9gicas de nueva generaci\u00f3n se ha hecho m\u00e1s intensa y compleja con el desarrollo por parte de adversarios (\u2026) de sistemas vectores de nueva generaci\u00f3n y de sus propias capacidades de defensa a\u00e9rea y antimisiles integradas en el territorio nacional\u00bb, ha se\u00f1alado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON, 28 Ene.-&nbsp;El presidente de Estados Unidos, Donald Trump, ha firmado una serie de \u00f3rdenes ejecutivas para reestructurar el Ej\u00e9rcito estadounidense, incluida la prohibici\u00f3n de que los militares transg\u00e9nero sirvan en las Fuerzas Armadas del pa\u00eds o la reincorporaci\u00f3n con pago retroactivo de los miembros que fueron dados de baja por negarse a vacunarse contra la COVID-19. Trump ha considerado que \u00abla b\u00fasqueda de la excelencia militar no puede diluirse para dar cabida a agendas pol\u00edticas u otras ideolog\u00edas perjudiciales para la cohesi\u00f3n de la unidad\u00bb, si bien \u00abrecientemente las Fuerzas Armadas se han visto afectadas por una ideolog\u00eda de g\u00e9nero radical para apaciguar a activistas que no se preocupan por los requisitos del servicio militar, como la salud f\u00edsica y mental\u00bb. As\u00ed, ha indicado que \u00abexpresar una \u2018identidad de g\u00e9nero\u2019 falsa que difiera del sexo de una persona no puede satisfacer los rigurosos est\u00e1ndares necesarios para el servicio militar\u00bb, porque, \u00abm\u00e1s all\u00e1 de las intervenciones m\u00e9dicas hormonales y quir\u00fargicas que implica, la adopci\u00f3n de una identidad de g\u00e9nero incompatible con el sexo de una persona entra en conflicto con el compromiso de un soldado con un estilo de vida honorable, veraz y disciplinado\u00bb. Por otro lado, ha eliminado los programas de diversidad, equidad e inclusi\u00f3n (DEI, por sus siglas en ingl\u00e9s), al considerar que estas acciones \u00absocavan\u00bb la meritocracia y \u00ablas conciencias de los estadounidenses al participar en una discriminaci\u00f3n racial y sexual odiosa\u00bb. \u00abNing\u00fan individuo o grupo dentro de nuestras Fuerzas Armadas debe ser preferido o desfavorecido por motivos de sexo, raza, etnia, color o credo\u00bb, ha concluido. El inquilino de la Casa Blanca ha firmado un decreto por el cual readmitir\u00e1 a aquellos militares que no se vacunaron de la COVID-19 a modo de \u00abreparaci\u00f3n\u00bb, despu\u00e9s de que en 2021 se ordenara que todos recibieran la vacuna y en 2023 se les rescindiera el mandato, lo que era \u00abuna carga injusta, excesivamente amplia y completamente innecesaria\u00bb. \u00abEl Ej\u00e9rcito despidi\u00f3 injustamente a quienes se negaron a vacunarse, independientemente de los a\u00f1os de servicio prestados a nuestra naci\u00f3n, despu\u00e9s de no conceder a muchos de ellos una exenci\u00f3n que deber\u00edan haber recibido. La reparaci\u00f3n por parte del Gobierno federal de cualquier despido injustificado est\u00e1 pendiente\u00bb, reza el texto. Por \u00faltimo, el mandatario ha ordenado construir un sistema de defensa inspirado en el modelo israel\u00ed, la C\u00fapula de Hierro, al sostener que \u00abla amenaza de ataque con misiles bal\u00edsticos, hipers\u00f3nicos y de crucero, as\u00ed como otros ataques a\u00e9reos avanzados, sigue siendo la amenaza m\u00e1s catastr\u00f3fica que enfrenta Estado Unidos\u00bb. \u00abEn los \u00faltimos 40 a\u00f1os, en lugar de disminuir, la amenaza de las armas estrat\u00e9gicas de nueva generaci\u00f3n se ha hecho m\u00e1s intensa y compleja con el desarrollo por parte de adversarios (\u2026) de sistemas vectores de nueva generaci\u00f3n y de sus propias capacidades de defensa a\u00e9rea y antimisiles integradas en el territorio nacional\u00bb, ha se\u00f1alado.<\/p>\n","protected":false},"author":9,"featured_media":101512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-101511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=101511"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101511\/revisions"}],"predecessor-version":[{"id":101513,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101511\/revisions\/101513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/101512"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=101511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=101511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=101511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}