{"id":101679,"date":"2025-02-01T07:27:35","date_gmt":"2025-02-01T11:27:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=101679"},"modified":"2025-02-01T07:27:41","modified_gmt":"2025-02-01T11:27:41","slug":"gobierno-rd-se-solidariza-con-estados-unidos-tras-accidente","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gobierno-rd-se-solidariza-con-estados-unidos-tras-accidente\/","title":{"rendered":"Gobierno RD se solidariza con Estados Unidos tras accidente"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"191\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/02\/615kjqpj-300x191-1.png\" alt=\"\" class=\"wp-image-101680\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El Gobierno dominicano expres\u00f3 su solidaridad con Estados Unidos tras el accidente a\u00e9reo en el que murieron 67 personas sobre el r\u00edo Potomac, pr\u00f3ximo al Aeropuerto Ronald Reagan, de Washington.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno extendi\u00f3 sus condolencias a los familiares de las v\u00edctimas, a trav\u00e9s de la cuenta de X de la Canciller\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Gobierno dominicano expresa su solidaridad a los Estados Unidos de Am\u00e9rica, por el tr\u00e1gico accidente ocurrido la noche de este mi\u00e9rcoles, tras el choque de un avi\u00f3n de pasajeros contra un helic\u00f3ptero militar cerca del Aeropuerto Nacional Ronald Reagan de Washington D.C., ocasionando la p\u00e9rdida de vidas humanas. Rep\u00fablica Dominicana extiende sus condolencias a los familiares de cada una de las v\u00edctimas\u201d, indica el mensaje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El Gobierno dominicano expres\u00f3 su solidaridad con Estados Unidos tras el accidente a\u00e9reo en el que murieron 67 personas sobre el r\u00edo Potomac, pr\u00f3ximo al Aeropuerto Ronald Reagan, de Washington. El Gobierno extendi\u00f3 sus condolencias a los familiares de las v\u00edctimas, a trav\u00e9s de la cuenta de X de la Canciller\u00eda. \u201cEl Gobierno dominicano expresa su solidaridad a los Estados Unidos de Am\u00e9rica, por el tr\u00e1gico accidente ocurrido la noche de este mi\u00e9rcoles, tras el choque de un avi\u00f3n de pasajeros contra un helic\u00f3ptero militar cerca del Aeropuerto Nacional Ronald Reagan de Washington D.C., ocasionando la p\u00e9rdida de vidas humanas. Rep\u00fablica Dominicana extiende sus condolencias a los familiares de cada una de las v\u00edctimas\u201d, indica el mensaje.<\/p>\n","protected":false},"author":9,"featured_media":101680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-101679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=101679"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101679\/revisions"}],"predecessor-version":[{"id":101681,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101679\/revisions\/101681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/101680"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=101679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=101679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=101679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}