{"id":10191,"date":"2014-11-05T18:25:09","date_gmt":"2014-11-05T22:25:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10191"},"modified":"2014-11-05T13:30:07","modified_gmt":"2014-11-05T17:30:07","slug":"9-trucos-divertidos-escondidos-en-las-busquedas-de-google","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/9-trucos-divertidos-escondidos-en-las-busquedas-de-google\/","title":{"rendered":"9 trucos divertidos escondidos en las b\u00fasquedas de Google"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/trucos-escondidos-busquedas-de-google-1_0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10192 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/trucos-escondidos-busquedas-de-google-1_0-300x200.jpg\" alt=\"trucos-escondidos-busquedas-de-google-1_0\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/trucos-escondidos-busquedas-de-google-1_0-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/trucos-escondidos-busquedas-de-google-1_0.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Los easter eggs, o huevos de pascua virtuales, son esos mensajes ocultos, <label>chistes<\/label> para unos pocos o gui\u00f1os para entendidos que tienen la virtud de irrumpir en un espacio por lo dem\u00e1s marcado por la cotidianidad y la rutina. Como lo es la b\u00fasqueda en Google.A continuaci\u00f3n, te presentamos 9 trucos divertidos escondidos en las b\u00fasquedas de<label>Google.<\/label><!--more--><\/p>\n<p>Si bien la <label>idea<\/label> de plantar gui\u00f1os semi ocultos para aquellos que tengan las ganas o el ingenio para descubrirlos se puede remontar a muchos a\u00f1os atr\u00e1s, desde que Diego Rivera se inclu\u00eda a s\u00ed mismo en sus murales o Alfred Hitchcock aparec\u00eda como extra en sus pel\u00edculas, la presencia de algo tan masivo y vasto como <label>internet<\/label> no ha hecho m\u00e1s que afinarlos y reproducirlos a niveles cada vez m\u00e1s ingeniosos y divertidos.<\/p>\n<p>Google, la compa\u00f1\u00eda m\u00e1s grande y exitosa de internet, no dej\u00f3 pasar la oportunidad de incluir varios de estos en sus b\u00fasquedas, a manera de trucos que tienen diferentes efectos y resultados. Tal vez ya conoces muchos de ellos, pero de todas maneras, aqu\u00ed te dejamos 9 divertidos trucos que Google ha escondido en sus b\u00fasquedas:<\/p>\n<p><strong>9 \u201cDo a Barrel Roll\u201d<\/strong><\/p>\n<p>\u201cDo a Barrel Roll\u201d se traduce como \u201cHaz un tonel volado\u201d, que hace referencia a una maniobra a\u00e9rea acrob\u00e1tica en la que el avi\u00f3n rota 360\u00b0 respecto a su eje. Aunque nunca hayas visto este truco, es f\u00e1cil imaginar qu\u00e9 sucede cuando <label>uno<\/label> busca, en ingl\u00e9s, \u201cDo a Barrel Roll\u201d.<\/p>\n<p><strong>8 \u201cTilt\u00bb<\/strong><\/p>\n<p>\u201cTilt\u201d, o \u201cinclinado\u201d, es un truco no recomendado para aquellos obsesionados con la simetr\u00eda. El mismo truco puede obtenerse googleando \u201cAskew\u201d (\u201cTorcido\u201d).<\/p>\n<p><strong>7 \u201cLa respuesta definitiva a la pregunta sobre la vida, el universo y todo lo dem\u00e1s\u201d<\/strong><\/p>\n<p>Esta es una referencia a The Hitchhiker&#8217;s Guide to the Galaxy (Gu\u00eda del autoestopista gal\u00e1ctico en Espa\u00f1a y Gu\u00eda del viajero intergal\u00e1ctico en Latinoam\u00e9rica), la popular franquicia de ciencia ficci\u00f3n que comenz\u00f3 como una comedia radial y su \u00e9xito le permiti\u00f3 extenderse en una saga de libros, una serie de televisi\u00f3n, videojuegos y una pel\u00edcula.<\/p>\n<p>En el programa de radio y en la primera novela, se crea una computadora superinteligente llamada Deep Thought para que obtenga \u201cla respuesta definitiva a la pregunta sobre la vida, el universo y todo lo dem\u00e1s\u201d. Luego de m\u00e1s de 7 millones de a\u00f1os, Deep Thought obtiene la respuesta: \u201c42\u201d.<\/p>\n<p>Y aclara que si la respuesta parece rid\u00edcula es porque quienes la crearon no sab\u00edan cu\u00e1l era realmente la pregunta. La referencia se puede observar buscando en Google \u201canswer to life, the universe, and everything\u201d.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/MbGNcoB2Y4I\" width=\"600\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>6 Anagrama<\/strong><\/p>\n<p>Un chiste bastante ocurrente y gracioso en torno a la b\u00fasqueda de la palabra \u201cAnagrama\u201d apela al recurso habitual en las b\u00fasquedas de Google, que sugiere otros resultados para palabras similares.<\/p>\n<p>Un anagrama es una palabra que se forma con las mismas letras de otra palabra. \u201cAmor\u201d y \u201cRoma\u201d, por ejemplo, son anagramas. Si buscas \u201canagram\u201d, google te pregunta si quisiste decir \u201cnag a ram\u201d. Lo divertido es que probablemente quien realice la b\u00fasqueda es porque quiera saber qu\u00e9 significa, algo que se responde directamente mediante este chiste.<\/p>\n<p><strong>5 Festivus<\/strong><\/p>\n<p>Festivus es una celebraci\u00f3n-parodia que tiene lugar el 23 de diciembre y que se propone como alternativa y s\u00e1tira a la celebraci\u00f3n de la navidad, a sus costumbres, sus ritos y al desenfrenado consumismo que tiene lugar en ella.<\/p>\n<p>Originalmente era una tradici\u00f3n familiar inventada por el padre del guionista televisivo Dan O&#8217;Keefe, pero este, trabajando para la serie Seinfeld, la incluy\u00f3 en un episodio, introduci\u00e9ndola as\u00ed en la cultura popular y contribuyendo a su propagaci\u00f3n.<\/p>\n<p>La \u201ccelebraci\u00f3n\u201d incluye una \u201ccena de Festivus\u201d, costumbres como \u201cel desahogo de quejas\u201d y las \u201chaza\u00f1as de fortaleza\u201d, o el asignarle a eventos completamente cotidianos y f\u00e1cilmente explicables la etiqueta de \u201cmilagros de Festivus\u201d. El s\u00edmbolo de la celebraci\u00f3n \u2013en lugar de un \u00e1rbol decorado con luces y adornos\u2013 es un simple tubo de aluminio sin ninguna clase de adorno. Este \u00faltimo, se puede apreciar en la b\u00fasqueda de \u201cFestivus\u201d en Google.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/dS7-jcsB_WQ\" width=\"600\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>4 Homenaje a StarCraft<\/strong><\/p>\n<p>Dos cosas que encajan muy bien juntas son los easter eggs y los aficionados a los videojuegos. StarCraft es un videojuego de ciencia ficci\u00f3n militar lanzado para Windows en 1998, que ten\u00eda como principales villanos a una raza de aliens con forma de insectos llamados Zerg.<\/p>\n<p>Google decidi\u00f3 incluir una referencia dirigida a los aficionados a este videojuego, en la b\u00fasqueda \u201cZerg Rush\u201d, en la que, de manera similar a los aliens de StarCraft, unas temibles y hambrientas \u201cO&#8217;s\u201d de Google vienen a comerse todos tus resultados de b\u00fasqueda.<\/p>\n<p><strong>3 \u00bfC\u00f3mo era Google en 1998?<\/strong><\/p>\n<p>Si alguna vez te hiciste esta pregunta, pues la respuesta se encuentra simplemente buscando \u201cGoogle in 1998\u201d.<\/p>\n<p><strong>2 B\u00fasquedas en YouTube<\/strong><\/p>\n<p>Si bien no es Google, de todas maneras, la compa\u00f1\u00eda de videos fue adquirida por Google en 2006, y tambi\u00e9n ha utilizado el motor de b\u00fasqueda de \u00e9sta para crear divertidos efectos.<\/p>\n<p>El fen\u00f3meno del Harlem Shake por suerte ya qued\u00f3 olvidado, pero cuando estaba en su apogeo, pod\u00edas buscar \u201cDo the Harlem Shake\u201d en YouTube y sorprenderte con los resultados.<\/p>\n<p>Otra b\u00fasqueda en YouTube tiene que ver con la inevitable referencia a Star Wars que no puede faltar: \u201cUse the force, Luke\u201d.<\/p>\n<p><strong>1 Breakout<\/strong><\/p>\n<p>Otra cosa con la que se llevan muy bien los videojuegos y sus aficionados es con la nostalgia. Y si hablamos de nostalgia no pueden faltar los videojuegos arcade de Atari.<\/p>\n<p>Breakout fue uno de los m\u00e1s c\u00e9lebres de ellos (que despu\u00e9s tuvo un famoso derivado llamado Arkanoid).<\/p>\n<p>Este truco secreto fue ubicado en el \u00faltimo lugar de esta lista porque sabemos que si buscas en im\u00e1genes de Google \u201cAtari Breakout\u201d perder\u00e1s los pr\u00f3ximos minutos (u horas) jugando.<\/p>\n<p>\u00bfConoc\u00edas algunos de estos trucos?<\/p>\n<p>Fuente: <a href=\"http:\/\/curiosidades.batanga.com\/7350\/9-divertidos-trucos-escondidos-en-las-busquedas-de-google\" target=\"_blank\">Ojo Cient\u00edfico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los easter eggs, o huevos de pascua virtuales, son esos mensajes ocultos, chistes para unos pocos o gui\u00f1os para entendidos que tienen la virtud de irrumpir en un espacio por lo dem\u00e1s marcado por la cotidianidad y la rutina. Como lo es la b\u00fasqueda en Google.A continuaci\u00f3n, te presentamos 9 trucos divertidos escondidos en las b\u00fasquedas deGoogle.<\/p>\n","protected":false},"author":3,"featured_media":10192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-10191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10191"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10191\/revisions"}],"predecessor-version":[{"id":10193,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10191\/revisions\/10193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10192"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}