{"id":101923,"date":"2025-02-15T07:06:05","date_gmt":"2025-02-15T11:06:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=101923"},"modified":"2025-02-15T07:06:07","modified_gmt":"2025-02-15T11:06:07","slug":"resaltan-determinacion-de-abinader-contra-la-corrupcion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/resaltan-determinacion-de-abinader-contra-la-corrupcion\/","title":{"rendered":"Resaltan \u00abdeterminaci\u00f3n\u00bb de Abinader contra la corrupci\u00f3n"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-13-at-7.34.14-PM-scaled-e1739503848132-300x200-1.jpeg\" alt=\"\" class=\"wp-image-101924\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El director de la Conferencia Internacional Anticorrupci\u00f3n, Roberto P\u00e9rez Rocha, resalt\u00f3 la \u00abfirme e inequ\u00edvoca determinaci\u00f3n pol\u00edtica\u00bb del presidente Luis Abinader contra la corrupci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que \u00abese es uno de los puntos clave para que Rep\u00fablica Dominicana haya ascendido ocho puntos en el \u00cdndice de la Percepci\u00f3n contra la Corrupci\u00f3n, dado a conocer esta semana\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que \u00abla \u00abbr\u00fajula moral y \u00e9tica de liderazgo de Abinader han contribuido a este ascenso, al igual que las reformas a nivel institucional y constitucional, que ayudan a cimentar el trabajo anticorrupci\u00f3n para un mediano y largo plazo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AVANCES SOLIDOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que \u00abgracias a estos trabajos, se han logrado avances muy s\u00f3lidos y positivos en materia de anticorrupci\u00f3n en Rep\u00fablica Dominicana\u00bb, lo que permite a la entidad denominada Transparencia Internacionalseguir trabajando de manera conjunta a nivel internacional con este pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00e9rez habl\u00f3 al t\u00e9rmino de una reuni\u00f3n en el Palacio Nacional con el ministro de la Presidencia, Jos\u00e9 Ignacio Paliza, y el director de Contrataciones P\u00fablicas, Carlos Pimentel, en la que coordinaron asuntos relativos de la celebraci\u00f3n en Rep\u00fablica Dominicana de una Conferencia Internacional Anticorrupci\u00f3n, en la que participar\u00edan &nbsp;m\u00e1s de 500 expertos munciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El director de la Conferencia Internacional Anticorrupci\u00f3n, Roberto P\u00e9rez Rocha, resalt\u00f3 la \u00abfirme e inequ\u00edvoca determinaci\u00f3n pol\u00edtica\u00bb del presidente Luis Abinader contra la corrupci\u00f3n. Dijo que \u00abese es uno de los puntos clave para que Rep\u00fablica Dominicana haya ascendido ocho puntos en el \u00cdndice de la Percepci\u00f3n contra la Corrupci\u00f3n, dado a conocer esta semana\u00bb. Agreg\u00f3 que \u00abla \u00abbr\u00fajula moral y \u00e9tica de liderazgo de Abinader han contribuido a este ascenso, al igual que las reformas a nivel institucional y constitucional, que ayudan a cimentar el trabajo anticorrupci\u00f3n para un mediano y largo plazo\u00bb. AVANCES SOLIDOS Indic\u00f3 que \u00abgracias a estos trabajos, se han logrado avances muy s\u00f3lidos y positivos en materia de anticorrupci\u00f3n en Rep\u00fablica Dominicana\u00bb, lo que permite a la entidad denominada Transparencia Internacionalseguir trabajando de manera conjunta a nivel internacional con este pa\u00eds. P\u00e9rez habl\u00f3 al t\u00e9rmino de una reuni\u00f3n en el Palacio Nacional con el ministro de la Presidencia, Jos\u00e9 Ignacio Paliza, y el director de Contrataciones P\u00fablicas, Carlos Pimentel, en la que coordinaron asuntos relativos de la celebraci\u00f3n en Rep\u00fablica Dominicana de una Conferencia Internacional Anticorrupci\u00f3n, en la que participar\u00edan &nbsp;m\u00e1s de 500 expertos munciales.<\/p>\n","protected":false},"author":9,"featured_media":101924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-101923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=101923"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101923\/revisions"}],"predecessor-version":[{"id":101925,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101923\/revisions\/101925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/101924"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=101923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=101923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=101923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}