{"id":101945,"date":"2025-02-16T06:43:34","date_gmt":"2025-02-16T10:43:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=101945"},"modified":"2025-02-16T06:45:29","modified_gmt":"2025-02-16T10:45:29","slug":"eeuu-y-rusia-inician-contactos-para-cumbre-de-trump-y-putin","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eeuu-y-rusia-inician-contactos-para-cumbre-de-trump-y-putin\/","title":{"rendered":"EEUU y Rusia inician contactos para cumbre de Trump y Putin"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/02\/Marco-Rubio-y-Serguei-Lavrov.jpg\" alt=\"\" class=\"wp-image-101946\" width=\"273\" height=\"159\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/02\/Marco-Rubio-y-Serguei-Lavrov.jpg 710w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/02\/Marco-Rubio-y-Serguei-Lavrov-300x175.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/02\/Marco-Rubio-y-Serguei-Lavrov-600x351.jpg 600w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Washington\/Mosc\u00fa (EFE).- Los jefes de la diplomacia de EE.UU. y Rusia, Marco Rubio y Sergu\u00e9i Lavrov, conversaron este s\u00e1bado por tel\u00e9fono y acordaron mantenerse en contacto de manera regular para preparar la cumbre entre los presidentes Donald Trump y Vlad\u00edmir Putin, seg\u00fan informaron ambos Gobiernos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan no hay una fecha fijada para\u00a0la cumbre, pero Trump afirm\u00f3 esta semana que podr\u00eda celebrarse en Arabia Saud\u00ed y que su objetivo ser\u00eda poner fin a la guerra en Ucrania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan indic\u00f3 el Ministerio de Exteriores ruso en un comunicado, la llamada se realiz\u00f3 por iniciativa de Washington y en ella ambos ministros \u00abreafirmaron su disposici\u00f3n a colaborar para restablecer un di\u00e1logo interestatal basado en el respeto mutuo, en l\u00ednea con el tono marcado por los presidentes\u00bb en su conversaci\u00f3n del mi\u00e9rcoles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Mosc\u00fa se\u00f1al\u00f3 que \u00abambas partes expresaron su voluntad de cooperar en cuestiones internacionales actuales, incluida la resoluci\u00f3n del conflicto en Ucrania, la situaci\u00f3n en Palestina y, en general, en Oriente Medio, as\u00ed como en otras cuestiones regionales\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el Departamento de Estado de EE.UU. explic\u00f3 en otro comunicado que, durante la llamada, Rubio reafirm\u00f3 el \u00abcompromiso\u00bb de Trump para encontrar una soluci\u00f3n al conflicto en Ucrania.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-cumbre-de-trump-y-putin-puede-tomar-forma-en-arabia-saudi\"><strong>LA CUMBRE PUEDE TOMAR FORMA EN ARABIA SAUD\u00cd<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El anuncio de la conversaci\u00f3n se produjo poco\u00a0antes de que Rubio llegara a Jerusal\u00e9n, como parte de una gira que tambi\u00e9n lo llevar\u00e1 a Arabia Saud\u00ed, donde est\u00e1 previsto que se re\u00fana con funcionarios rusos para iniciar negociaciones con el fin de poner fin a la guerra en Ucrania, seg\u00fan inform\u00f3 este s\u00e1bado la CNN citando m\u00faltiples fuentes familiarizadas con el asunto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de Rubio, se espera que en esas conversaciones participen el asesor de Seguridad Nacional de la Casa Blanca, Mike Waltz, y el enviado para Oriente Medio, Steve Witkoff.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington\/Mosc\u00fa (EFE).- Los jefes de la diplomacia de EE.UU. y Rusia, Marco Rubio y Sergu\u00e9i Lavrov, conversaron este s\u00e1bado por tel\u00e9fono y acordaron mantenerse en contacto de manera regular para preparar la cumbre entre los presidentes Donald Trump y Vlad\u00edmir Putin, seg\u00fan informaron ambos Gobiernos. A\u00fan no hay una fecha fijada para\u00a0la cumbre, pero Trump afirm\u00f3 esta semana que podr\u00eda celebrarse en Arabia Saud\u00ed y que su objetivo ser\u00eda poner fin a la guerra en Ucrania. Seg\u00fan indic\u00f3 el Ministerio de Exteriores ruso en un comunicado, la llamada se realiz\u00f3 por iniciativa de Washington y en ella ambos ministros \u00abreafirmaron su disposici\u00f3n a colaborar para restablecer un di\u00e1logo interestatal basado en el respeto mutuo, en l\u00ednea con el tono marcado por los presidentes\u00bb en su conversaci\u00f3n del mi\u00e9rcoles. Adem\u00e1s, Mosc\u00fa se\u00f1al\u00f3 que \u00abambas partes expresaron su voluntad de cooperar en cuestiones internacionales actuales, incluida la resoluci\u00f3n del conflicto en Ucrania, la situaci\u00f3n en Palestina y, en general, en Oriente Medio, as\u00ed como en otras cuestiones regionales\u00bb. Por su parte, el Departamento de Estado de EE.UU. explic\u00f3 en otro comunicado que, durante la llamada, Rubio reafirm\u00f3 el \u00abcompromiso\u00bb de Trump para encontrar una soluci\u00f3n al conflicto en Ucrania. LA CUMBRE PUEDE TOMAR FORMA EN ARABIA SAUD\u00cd El anuncio de la conversaci\u00f3n se produjo poco\u00a0antes de que Rubio llegara a Jerusal\u00e9n, como parte de una gira que tambi\u00e9n lo llevar\u00e1 a Arabia Saud\u00ed, donde est\u00e1 previsto que se re\u00fana con funcionarios rusos para iniciar negociaciones con el fin de poner fin a la guerra en Ucrania, seg\u00fan inform\u00f3 este s\u00e1bado la CNN citando m\u00faltiples fuentes familiarizadas con el asunto. Adem\u00e1s de Rubio, se espera que en esas conversaciones participen el asesor de Seguridad Nacional de la Casa Blanca, Mike Waltz, y el enviado para Oriente Medio, Steve Witkoff.<\/p>\n","protected":false},"author":9,"featured_media":101946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-101945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=101945"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101945\/revisions"}],"predecessor-version":[{"id":101947,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/101945\/revisions\/101947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/101946"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=101945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=101945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=101945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}