{"id":102170,"date":"2025-03-09T20:02:44","date_gmt":"2025-03-10T00:02:44","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=102170"},"modified":"2025-03-09T20:02:45","modified_gmt":"2025-03-10T00:02:45","slug":"muere-el-cantante-diomedes-nunez-lider-del-grupo-mio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muere-el-cantante-diomedes-nunez-lider-del-grupo-mio\/","title":{"rendered":"Muere el cantante Di\u00f3medes N\u00fa\u00f1ez, l\u00edder del Grupo M\u00edo"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"699\" height=\"506\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/diom.jpg\" alt=\"\" class=\"wp-image-102171\" style=\"width:298px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/diom.jpg 699w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/diom-300x217.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/diom-600x434.jpg 600w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- Muri\u00f3 este domingo el cantante Diomedes N\u00fa\u00f1ez, l\u00edder de la agrupaci\u00f3n merenguera el Grupo M\u00edo. Ten\u00eda 58 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n de su fallecimiento fue comunicada por el productor Alberto Bernab\u00e9 (Bebeto), a trav\u00e9s de sus redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLamentablemente acaba de fallecer el merenguero Diomedes, debido a complicaciones de salud. Paz a su alma, que Dios lo tenga en la gloria. Te queremos, descansa en paz\u00bb, expres\u00f3 Bernab\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En abril de 2024, N\u00fa\u00f1ez, quien fue una de las voces estelares de los \u00abA\u00f1os Dorados del Merengue\u00bb, fue diagnosticado con una seria afecci\u00f3n en los ri\u00f1ones, por la que tuvo que ser dializado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SUS PROBLEMAS DE SALUD<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diomedes N\u00fa\u00f1ez naci\u00f3 en Santa Cruz del municipio Mao ubicado en al provincia Valverde, el 3 de febrero de 1967.Hijo de Zunilda Guzm\u00e1n&nbsp;y del trompetista&nbsp;Diosnedy N\u00fa\u00f1ez, mejor conocido como Papirilo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el a\u00f1o 2023 tuvo, solo en diciembre, 56 presentaciones y en una noche de esas, cantando en un bar, se dio cuenta de que ten\u00eda las extremidades inferiores y el vientre muy hinchados, lo que provoc\u00f3 que asistiera al hospital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>RELATO DE SU ENFERMEDAD<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese momento, confes\u00f3 en una entrevista, \u00abpens\u00e9 que podr\u00eda morir\u00bb y que eso fue el resultado de ser una persona hipertensa, pero sin presentar s\u00edntomas. Luego de ah\u00ed, se mantuvo en un proceso de recuperaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo ten\u00eda presi\u00f3n alta y nunca me dio mareo ni dolor de cabeza, yo trabajaba normal lo \u00fanico que ve\u00eda era que hab\u00eda perdido peso y eso me hac\u00eda sentir feliz porque me ve\u00eda bien\u201d, coment\u00f3 semanas despu\u00e9s de haber recibido atenci\u00f3n medica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de pasar por est\u00e1 etapa de su vida decidi\u00f3 grabar el merengue \u00abUn d\u00eda especial\u00bb, dedicado a aquellas personas que han sentido que sin Dios no se hab\u00eda podido salir de la situaci\u00f3n o enfermedad que lo aquejaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SUS EXITOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre sus \u00e9xitos en el merengue se encuentran Esto se encendi\u00f3, Esto es pa hombre, Una chica bien, Balsi\u00e9, Mi locura, El so\u00f1ador, Si tu piensas que no te amo y Ya empez\u00f3 la fiesta, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Muri\u00f3 este domingo el cantante Diomedes N\u00fa\u00f1ez, l\u00edder de la agrupaci\u00f3n merenguera el Grupo M\u00edo. Ten\u00eda 58 a\u00f1os. La informaci\u00f3n de su fallecimiento fue comunicada por el productor Alberto Bernab\u00e9 (Bebeto), a trav\u00e9s de sus redes sociales. \u00abLamentablemente acaba de fallecer el merenguero Diomedes, debido a complicaciones de salud. Paz a su alma, que Dios lo tenga en la gloria. Te queremos, descansa en paz\u00bb, expres\u00f3 Bernab\u00e9. En abril de 2024, N\u00fa\u00f1ez, quien fue una de las voces estelares de los \u00abA\u00f1os Dorados del Merengue\u00bb, fue diagnosticado con una seria afecci\u00f3n en los ri\u00f1ones, por la que tuvo que ser dializado. SUS PROBLEMAS DE SALUD Diomedes N\u00fa\u00f1ez naci\u00f3 en Santa Cruz del municipio Mao ubicado en al provincia Valverde, el 3 de febrero de 1967.Hijo de Zunilda Guzm\u00e1n&nbsp;y del trompetista&nbsp;Diosnedy N\u00fa\u00f1ez, mejor conocido como Papirilo\u00bb. Para el a\u00f1o 2023 tuvo, solo en diciembre, 56 presentaciones y en una noche de esas, cantando en un bar, se dio cuenta de que ten\u00eda las extremidades inferiores y el vientre muy hinchados, lo que provoc\u00f3 que asistiera al hospital. RELATO DE SU ENFERMEDAD En ese momento, confes\u00f3 en una entrevista, \u00abpens\u00e9 que podr\u00eda morir\u00bb y que eso fue el resultado de ser una persona hipertensa, pero sin presentar s\u00edntomas. Luego de ah\u00ed, se mantuvo en un proceso de recuperaci\u00f3n. \u201cYo ten\u00eda presi\u00f3n alta y nunca me dio mareo ni dolor de cabeza, yo trabajaba normal lo \u00fanico que ve\u00eda era que hab\u00eda perdido peso y eso me hac\u00eda sentir feliz porque me ve\u00eda bien\u201d, coment\u00f3 semanas despu\u00e9s de haber recibido atenci\u00f3n medica. Luego de pasar por est\u00e1 etapa de su vida decidi\u00f3 grabar el merengue \u00abUn d\u00eda especial\u00bb, dedicado a aquellas personas que han sentido que sin Dios no se hab\u00eda podido salir de la situaci\u00f3n o enfermedad que lo aquejaba. SUS EXITOS Entre sus \u00e9xitos en el merengue se encuentran Esto se encendi\u00f3, Esto es pa hombre, Una chica bien, Balsi\u00e9, Mi locura, El so\u00f1ador, Si tu piensas que no te amo y Ya empez\u00f3 la fiesta, entre otros.<\/p>\n","protected":false},"author":9,"featured_media":102171,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-102170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=102170"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102170\/revisions"}],"predecessor-version":[{"id":102172,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102170\/revisions\/102172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/102171"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=102170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=102170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=102170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}