{"id":102177,"date":"2025-03-10T06:47:23","date_gmt":"2025-03-10T10:47:23","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=102177"},"modified":"2025-03-10T06:47:24","modified_gmt":"2025-03-10T10:47:24","slug":"yeni-berenice-reynoso-designa-nuevos-procuradores-generales-adjuntos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/yeni-berenice-reynoso-designa-nuevos-procuradores-generales-adjuntos\/","title":{"rendered":"Yeni Berenice Reynoso designa nuevos procuradores generales adjuntos"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67cdef60cbe46.jpeg\" alt=\"\" class=\"wp-image-102178\" style=\"width:325px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67cdef60cbe46.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67cdef60cbe46-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67cdef60cbe46-768x513.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67cdef60cbe46-600x401.jpeg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La procuradora general de la Rep\u00fablica, Yeni Berenice Reynoso, design\u00f3 los siete procuradores adjuntos que les corresponde por ley, incluyendo al primer sustituto Rodolfo Espi\u00f1eira Ceballos, luego de que el presidente Luis Abinader recomendar\u00e1 al Consejo Nacional de la Magistratura los procuradores que le correspponde al Poder Ejecutivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La magistrada designo adem\u00e1s a Wilson Manuel Camacho Peralta, Pedro Fr\u00edas Morillo, Jos\u00e9 Vitervo Cabral Gonz\u00e1lez, Juan Medina de los Santos, Sourelly Jaquez Vialet y Alba Corona Valerio, las cuales se amparan en las atribuciones que le confiere el art\u00edculo 31 de la Ley Org\u00e1nica del Ministerio P\u00fablico (N\u00fam. 133-11, del 7 de junio de 2011).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La magistrada Reynoso nombr\u00f3 a Espi\u00f1eira Ceballos como primer sustituto de la Procuradora General de la Rep\u00fablica, con funciones en el despacho, mientras que Camacho Peralta estar\u00e1 al frente de la Direcci\u00f3n General de Persecuci\u00f3n del Ministerio P\u00fablico y Osvaldo Bonilla Hiraldo ser\u00e1 director de Asistencia Jur\u00eddica Internacional, y representar\u00e1 a la instituci\u00f3n en los procesos cooperativos de extradiciones y derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pedro Fr\u00edas Morillo ser\u00e1 el segundo sustituto de la Procuradora General de la Rep\u00fablica y director t\u00e9cnico del despacho; Jos\u00e9 Vitervo E. Cabral Gonz\u00e1lez, que est\u00e1 en la funci\u00f3n de inspector general del Ministerio P\u00fablico, e Isis de la Cruz Duarte, actual consejera, le fueron ratificadas sus funciones de directora de la Unidad de Investigaci\u00f3n de Comercio Il\u00edcito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sourelly Jaquez Vialet fungir\u00e1 como directora de la Unidad de Jurisdicci\u00f3n Privilegiada en Procesos Especiales; Juan Medina de los Santos fungir\u00e1 como director de la Unidad de Litigios Civiles y Administrativos y Alba Corona Valerio ser\u00e1 directora nacional del Sistema de Atenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fadulia Rosa ser\u00e1 la directora de la Unidad de Dict\u00e1menes y Litigios Ante las Altas Cortes y le acompa\u00f1ar\u00e1n Mar\u00eda del Carmen de Le\u00f3n y Fior Daliza Alduey y Emilio Rodr\u00edguez, miembros de la Unidad de Dict\u00e1menes y Litigios. Mientras que Iv\u00e1n Feliz Vargas fungir\u00e1 como director del Proyecto G-5 destinado a la transformaci\u00f3n tecnol\u00f3gica en las investigaciones y el Sistema Nacional de Atenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la Procuradur\u00eda Especializada de Persecuci\u00f3n de la Corrupci\u00f3n Administrativa (PEPCA) fue designada como su titular la procuradora de Corte Mirna Ortiz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para cubrir las vacantes surgidas a ra\u00edz de las designaciones de fiscales titulares como procuradores generales adjuntos, quedaron designados como fiscales titulares en Santiago Quirsa Abreu Pe\u00f1a; en San Crist\u00f3bal, Ramona Santana y en Monte Plata, Andr\u00e9s Comas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">OTRAS DESIGNACIONES<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Rosalba D\u00edaz qued\u00f3 designada como directora del Servicio Nacional de Representaci\u00f3n Legal de los Derechos de las V\u00edctimas (RELEVIC); Wendy Estrella Monsanto ser\u00e1 la secretaria general del Ministerio P\u00fablico y Katiusca Viviano la coordinadora de la reci\u00e9n creada Unidad Central de Gesti\u00f3n de Cobros de Multas y Ejecuciones de Garant\u00edas Econ\u00f3micas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La procuradora Reynoso resalt\u00f3 que el Ministerio P\u00fablico y todas sus unidades especiales y dependencias se encuentran inmersas en una revoluci\u00f3n de transformaciones que buscan concluir su misi\u00f3n constitucional con altos est\u00e1ndares de calidad, honestidad y transparencia en beneficio de la sociedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La procuradora general de la Rep\u00fablica, Yeni Berenice Reynoso, design\u00f3 los siete procuradores adjuntos que les corresponde por ley, incluyendo al primer sustituto Rodolfo Espi\u00f1eira Ceballos, luego de que el presidente Luis Abinader recomendar\u00e1 al Consejo Nacional de la Magistratura los procuradores que le correspponde al Poder Ejecutivo. La magistrada designo adem\u00e1s a Wilson Manuel Camacho Peralta, Pedro Fr\u00edas Morillo, Jos\u00e9 Vitervo Cabral Gonz\u00e1lez, Juan Medina de los Santos, Sourelly Jaquez Vialet y Alba Corona Valerio, las cuales se amparan en las atribuciones que le confiere el art\u00edculo 31 de la Ley Org\u00e1nica del Ministerio P\u00fablico (N\u00fam. 133-11, del 7 de junio de 2011). La magistrada Reynoso nombr\u00f3 a Espi\u00f1eira Ceballos como primer sustituto de la Procuradora General de la Rep\u00fablica, con funciones en el despacho, mientras que Camacho Peralta estar\u00e1 al frente de la Direcci\u00f3n General de Persecuci\u00f3n del Ministerio P\u00fablico y Osvaldo Bonilla Hiraldo ser\u00e1 director de Asistencia Jur\u00eddica Internacional, y representar\u00e1 a la instituci\u00f3n en los procesos cooperativos de extradiciones y derechos humanos. Pedro Fr\u00edas Morillo ser\u00e1 el segundo sustituto de la Procuradora General de la Rep\u00fablica y director t\u00e9cnico del despacho; Jos\u00e9 Vitervo E. Cabral Gonz\u00e1lez, que est\u00e1 en la funci\u00f3n de inspector general del Ministerio P\u00fablico, e Isis de la Cruz Duarte, actual consejera, le fueron ratificadas sus funciones de directora de la Unidad de Investigaci\u00f3n de Comercio Il\u00edcito. Sourelly Jaquez Vialet fungir\u00e1 como directora de la Unidad de Jurisdicci\u00f3n Privilegiada en Procesos Especiales; Juan Medina de los Santos fungir\u00e1 como director de la Unidad de Litigios Civiles y Administrativos y Alba Corona Valerio ser\u00e1 directora nacional del Sistema de Atenci\u00f3n. Fadulia Rosa ser\u00e1 la directora de la Unidad de Dict\u00e1menes y Litigios Ante las Altas Cortes y le acompa\u00f1ar\u00e1n Mar\u00eda del Carmen de Le\u00f3n y Fior Daliza Alduey y Emilio Rodr\u00edguez, miembros de la Unidad de Dict\u00e1menes y Litigios. Mientras que Iv\u00e1n Feliz Vargas fungir\u00e1 como director del Proyecto G-5 destinado a la transformaci\u00f3n tecnol\u00f3gica en las investigaciones y el Sistema Nacional de Atenci\u00f3n. En la Procuradur\u00eda Especializada de Persecuci\u00f3n de la Corrupci\u00f3n Administrativa (PEPCA) fue designada como su titular la procuradora de Corte Mirna Ortiz. Para cubrir las vacantes surgidas a ra\u00edz de las designaciones de fiscales titulares como procuradores generales adjuntos, quedaron designados como fiscales titulares en Santiago Quirsa Abreu Pe\u00f1a; en San Crist\u00f3bal, Ramona Santana y en Monte Plata, Andr\u00e9s Comas. OTRAS DESIGNACIONES Mar\u00eda Rosalba D\u00edaz qued\u00f3 designada como directora del Servicio Nacional de Representaci\u00f3n Legal de los Derechos de las V\u00edctimas (RELEVIC); Wendy Estrella Monsanto ser\u00e1 la secretaria general del Ministerio P\u00fablico y Katiusca Viviano la coordinadora de la reci\u00e9n creada Unidad Central de Gesti\u00f3n de Cobros de Multas y Ejecuciones de Garant\u00edas Econ\u00f3micas. La procuradora Reynoso resalt\u00f3 que el Ministerio P\u00fablico y todas sus unidades especiales y dependencias se encuentran inmersas en una revoluci\u00f3n de transformaciones que buscan concluir su misi\u00f3n constitucional con altos est\u00e1ndares de calidad, honestidad y transparencia en beneficio de la sociedad.<\/p>\n","protected":false},"author":9,"featured_media":102178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-102177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=102177"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102177\/revisions"}],"predecessor-version":[{"id":102179,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102177\/revisions\/102179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/102178"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=102177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=102177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=102177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}