{"id":102280,"date":"2025-03-15T07:20:07","date_gmt":"2025-03-15T11:20:07","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=102280"},"modified":"2025-03-15T07:20:08","modified_gmt":"2025-03-15T11:20:08","slug":"muller-vs-kovacevic-en-semifinales-de-la-copa-cap-cana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muller-vs-kovacevic-en-semifinales-de-la-copa-cap-cana\/","title":{"rendered":"Muller vs Kovacevic en semifinales de la Copa Cap Cana"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67d4e163d5137.jpeg\" alt=\"\" class=\"wp-image-102281\" style=\"width:257px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67d4e163d5137.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67d4e163d5137-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67d4e163d5137-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/67d4e163d5137-600x400.jpeg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El franc\u00e9s Alexandre Muller, primer favorito, y el estadounidense Aleksandar Kovacevic se enfrentar\u00e1n este s\u00e1bado en busca de acceder a la final del Rep\u00fablica Dominicana Open, Copa Cap Cana, Ciudad Destino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muller avanz\u00f3 a las semifinales tras superar por 7-6(6), 6-4, a su compatriota Constant Lestienne. Mientras que Kovacevic necesit\u00f3 de tres sets para despachar por 4-6, 6-4, 6-3 al alem\u00e1n Daniel Altmaier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En dobles, los alemanes Jakob Schnaitter y Mark Wallner dejaron en el camino a los primeros favoritos Guido Andreozzi, de Argentina, y Theo Arribage, de Francia, a quienes vencieron con pizarra de 6-4, 6-3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otros resultados, el dueto compuesto por el portugu\u00e9s Francisco Cabral y el alem\u00e1n Hendrik Jebens, segundos preclasificados, se instal\u00f3 tambi\u00e9n en semis al disponer de la pareja estadounidense formada por JJ Tracy y Robert Cash por 7-5, 6-3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las semifinales se jugar\u00e1n este s\u00e1bado a partir de la 1:00 de la tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la Copa Cap Cana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Rep\u00fablica Dominicana Open Copa Cap Cana es un torneo ATP Challenger 175 que reparte una bolsa de 250 mil d\u00f3lares entre los jugadores participantes, y que se extender\u00e1 hasta el pr\u00f3ximo domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento se dan cita m\u00e1s de 60 tenistas profesionales provenientes de m\u00e1s de 20 pa\u00edses, los cuales participan en las modalidades de dobles y sencillos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El franc\u00e9s Alexandre Muller, primer favorito, y el estadounidense Aleksandar Kovacevic se enfrentar\u00e1n este s\u00e1bado en busca de acceder a la final del Rep\u00fablica Dominicana Open, Copa Cap Cana, Ciudad Destino. Muller avanz\u00f3 a las semifinales tras superar por 7-6(6), 6-4, a su compatriota Constant Lestienne. Mientras que Kovacevic necesit\u00f3 de tres sets para despachar por 4-6, 6-4, 6-3 al alem\u00e1n Daniel Altmaier. En dobles, los alemanes Jakob Schnaitter y Mark Wallner dejaron en el camino a los primeros favoritos Guido Andreozzi, de Argentina, y Theo Arribage, de Francia, a quienes vencieron con pizarra de 6-4, 6-3. En otros resultados, el dueto compuesto por el portugu\u00e9s Francisco Cabral y el alem\u00e1n Hendrik Jebens, segundos preclasificados, se instal\u00f3 tambi\u00e9n en semis al disponer de la pareja estadounidense formada por JJ Tracy y Robert Cash por 7-5, 6-3. Las semifinales se jugar\u00e1n este s\u00e1bado a partir de la 1:00 de la tarde. Sobre la Copa Cap Cana El Rep\u00fablica Dominicana Open Copa Cap Cana es un torneo ATP Challenger 175 que reparte una bolsa de 250 mil d\u00f3lares entre los jugadores participantes, y que se extender\u00e1 hasta el pr\u00f3ximo domingo. En el evento se dan cita m\u00e1s de 60 tenistas profesionales provenientes de m\u00e1s de 20 pa\u00edses, los cuales participan en las modalidades de dobles y sencillos.<\/p>\n","protected":false},"author":9,"featured_media":102281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-102280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=102280"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102280\/revisions"}],"predecessor-version":[{"id":102282,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102280\/revisions\/102282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/102281"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=102280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=102280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=102280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}