{"id":10231,"date":"2014-11-06T12:18:40","date_gmt":"2014-11-06T16:18:40","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10231"},"modified":"2014-11-06T12:18:40","modified_gmt":"2014-11-06T16:18:40","slug":"hoy-se-cumplen-170-anos-de-la-constitucion-dominicana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hoy-se-cumplen-170-anos-de-la-constitucion-dominicana\/","title":{"rendered":"Hoy se cumplen 170 a\u00f1os de la Constituci\u00f3n dominicana"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/monumento.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10232 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/monumento-300x174.jpg\" alt=\"monumento\" width=\"300\" height=\"174\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/monumento-300x174.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/monumento.jpg 398w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>SANTO DOMINGO<\/strong>.-Hoy se cumplen 170 a\u00f1os de aquel d\u00eda en que 31 dominicanos se reunieron en San Crist\u00f3bal para aprobar la primera Constituci\u00f3n y conformar la Rep\u00fablica, en la que el d\u00eda 27 de febrero de ese mismo a\u00f1o se proclam\u00f3 la separaci\u00f3n de Hait\u00ed.<!--more--><\/p>\n<p>La Carta Magna de la naci\u00f3n ha sido modificada 38 veces, la \u00faltima\u00a0el 26 de enero del 2010, mediante la gaceta oficial no. 10561.1<\/p>\n<p><strong>Actividades<\/strong><\/p>\n<p>El gobierno dominicano organiza varios actos para conmemorar durante esta semana el 170 Aniversario de la Constituci\u00f3n Dominicana.<\/p>\n<p>La informaci\u00f3n la dio a conocer el presidente de la Comisi\u00f3n Permanente de Efem\u00e9rides Patrias, Juan Daniel Balc\u00e1cer, quien precis\u00f3 que dichos actos son programados por la dependencia que dirige en colaboraci\u00f3n con la gobernaci\u00f3n provincial de San Crist\u00f3bal y el Ayuntamiento Municipal de la referida provincia.<\/p>\n<p>Balc\u00e1cer considera esta conmemoraci\u00f3n como fundamental pues fue \u201cla firma de la primera Constituci\u00f3n Dominicana, que convirti\u00f3 al pa\u00eds en un estado de derecho\u201d.<\/p>\n<p>Las actividades programadas iniciaron el pasado domingo y se efectuar\u00e1n hasta el domingo 9, tiempo en el que se dictar\u00e1n conferencias magistrales, y se realizar\u00e1n actos culturales, desfile c\u00edvico militar, Expo-constituci\u00f3n 2014, ofrendas flores y torneo deportivo.<\/p>\n<p>El programa que recuerda la firma de la primera constituci\u00f3n de la Rep\u00fablica Dominicana -el 6 de noviembre del 1844 en San Crist\u00f3bal, inici\u00f3 el pasado domingo con una conferencia sobre liderazgo responsable a cargo del periodista Jos\u00e9 Laluz y contin\u00faa este martes 4 con la conferencia \u201cAntecedentes hist\u00f3ricos de la Constituci\u00f3n de San Crist\u00f3bal que dictar\u00e1 Roberto Cass\u00e1 en el sal\u00f3n de conferencias de la Gobernaci\u00f3n Provincial, a las 4:00 p.m, para culminar con un show art\u00edstico cultural con el Grupo Ra\u00edces Folcl\u00f3ricas y grupos de bailes de varias escuelas p\u00fablicas.<\/p>\n<p><a href=\"http:\/\/eldia.com.do\/hoy-se-cumplen-170-anos-de-la-constitucion-dominicana\/\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-Hoy se cumplen 170 a\u00f1os de aquel d\u00eda en que 31 dominicanos se reunieron en San Crist\u00f3bal para aprobar la primera Constituci\u00f3n y conformar la Rep\u00fablica, en la que el d\u00eda 27 de febrero de ese mismo a\u00f1o se proclam\u00f3 la separaci\u00f3n de Hait\u00ed.<\/p>\n","protected":false},"author":3,"featured_media":10232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-10231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10231"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10231\/revisions"}],"predecessor-version":[{"id":10233,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10231\/revisions\/10233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10232"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}