{"id":102359,"date":"2025-03-19T11:12:34","date_gmt":"2025-03-19T15:12:34","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=102359"},"modified":"2025-03-19T11:12:35","modified_gmt":"2025-03-19T15:12:35","slug":"piloto-jimmy-llibre-se-destaca-en-carrera-porshe-cup-florida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/piloto-jimmy-llibre-se-destaca-en-carrera-porshe-cup-florida\/","title":{"rendered":"Piloto Jimmy Llibre se destaca en carrera Porshe Cup Florida"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"162\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/03\/PILOTO-300x162-1.jpeg\" alt=\"\" class=\"wp-image-102360\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO. Tras su impresionante victoria en el arranque de la temporada de la Porsche Carrera Cup North America en Sebring, Florida, el piloto Jimmy Llibre vaticin\u00f3 \u201cque se vienen cosas buenas, m\u00e1s carreras y muchas emociones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el triunfo en el legendario circuito de Sebring, Llibre se apoy\u00f3 en una gran determinaci\u00f3n y dio una gran demostraci\u00f3n. \u201cEsto apenas empieza\u2026 as\u00ed que atentos, que se vienen cosas buenas\u201d, sigui\u00f3 diciendo el piloto al concluir la carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dominicano parti\u00f3 desde la octava posici\u00f3n (P8) y protagoniz\u00f3 una remontada espectacular, hasta cruzar la meta en el tercer lugar (P3), pero luego ascendiendo en la clasificaci\u00f3n final, al conseguir as\u00ed su primer triunfo en la categor\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEmpezamos el 2025 como se debe: primera carrera de la temporada y subimos al podio. El trabajo, la disciplina y el enfoque est\u00e1n dando resultados, y esto es solo el comienzo\u201d, asegur\u00f3 Llibre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El joven piloto destac\u00f3 la intensidad de la carrera y el esfuerzo de su equipo, ACI Motorsports, del cual asegur\u00f3 que ha sido clave en su desarrollo y \u00e9xito en la categor\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFue un d\u00eda de pura batalla en pista. Demostramos que en las carreras todo puede pasar y que dar el mayor esfuerzo en cada vuelta es importante\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llibre agradeci\u00f3 a Dios, a su equipo, a su familia y a sus patrocinadores por el apoyo incondicional, y que la victoria es solo el inicio de una temporada prometedora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre sus patrocinadores destacan Banreservas, Baldom, Arroz Campos, GoDomRep, Mobil RD, Ground Burger, Grupo Cometa, Lab Mallen, Hospital HOMS, Neomoon, Don Pollo, Fidureservas, ARV Group, Livery Station, Muttat USA, ACI Motorsports, Chatt Porsche, Redbridge Insurance, Redbridge Assist, Casa de Campo y Porsche Center Santo Domingo, quienes han sido fundamentales para su participaci\u00f3n en la serie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el resultado, Jimmy Llibre se posiciona como uno de los pilotos a seguir en la Porsche Carrera Cup North America 2025, y promete seguir luchando por m\u00e1s victorias en el transcurso de la temporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Porsche Carrera Cup North America es una de las competencias de mayor prestigio del continente, donde los mejores pilotos compiten en igualdad de condiciones a bordo de los ic\u00f3nicos Porsche 911 GT3 Cup.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llibre es un piloto dominicano con una destacada trayectoria en el automovilismo internacional. Con disciplina y pasi\u00f3n se ha consolidado como una de las grandes promesas del automovilismo en la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. Tras su impresionante victoria en el arranque de la temporada de la Porsche Carrera Cup North America en Sebring, Florida, el piloto Jimmy Llibre vaticin\u00f3 \u201cque se vienen cosas buenas, m\u00e1s carreras y muchas emociones\u201d. Con el triunfo en el legendario circuito de Sebring, Llibre se apoy\u00f3 en una gran determinaci\u00f3n y dio una gran demostraci\u00f3n. \u201cEsto apenas empieza\u2026 as\u00ed que atentos, que se vienen cosas buenas\u201d, sigui\u00f3 diciendo el piloto al concluir la carrera. El dominicano parti\u00f3 desde la octava posici\u00f3n (P8) y protagoniz\u00f3 una remontada espectacular, hasta cruzar la meta en el tercer lugar (P3), pero luego ascendiendo en la clasificaci\u00f3n final, al conseguir as\u00ed su primer triunfo en la categor\u00eda. \u201cEmpezamos el 2025 como se debe: primera carrera de la temporada y subimos al podio. El trabajo, la disciplina y el enfoque est\u00e1n dando resultados, y esto es solo el comienzo\u201d, asegur\u00f3 Llibre. El joven piloto destac\u00f3 la intensidad de la carrera y el esfuerzo de su equipo, ACI Motorsports, del cual asegur\u00f3 que ha sido clave en su desarrollo y \u00e9xito en la categor\u00eda. \u201cFue un d\u00eda de pura batalla en pista. Demostramos que en las carreras todo puede pasar y que dar el mayor esfuerzo en cada vuelta es importante\u201d, se\u00f1al\u00f3. Llibre agradeci\u00f3 a Dios, a su equipo, a su familia y a sus patrocinadores por el apoyo incondicional, y que la victoria es solo el inicio de una temporada prometedora. Entre sus patrocinadores destacan Banreservas, Baldom, Arroz Campos, GoDomRep, Mobil RD, Ground Burger, Grupo Cometa, Lab Mallen, Hospital HOMS, Neomoon, Don Pollo, Fidureservas, ARV Group, Livery Station, Muttat USA, ACI Motorsports, Chatt Porsche, Redbridge Insurance, Redbridge Assist, Casa de Campo y Porsche Center Santo Domingo, quienes han sido fundamentales para su participaci\u00f3n en la serie. Tras el resultado, Jimmy Llibre se posiciona como uno de los pilotos a seguir en la Porsche Carrera Cup North America 2025, y promete seguir luchando por m\u00e1s victorias en el transcurso de la temporada. La Porsche Carrera Cup North America es una de las competencias de mayor prestigio del continente, donde los mejores pilotos compiten en igualdad de condiciones a bordo de los ic\u00f3nicos Porsche 911 GT3 Cup. Llibre es un piloto dominicano con una destacada trayectoria en el automovilismo internacional. Con disciplina y pasi\u00f3n se ha consolidado como una de las grandes promesas del automovilismo en la regi\u00f3n.<\/p>\n","protected":false},"author":9,"featured_media":102360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-102359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=102359"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102359\/revisions"}],"predecessor-version":[{"id":102361,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/102359\/revisions\/102361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/102360"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=102359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=102359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=102359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}