{"id":10276,"date":"2014-11-07T14:00:36","date_gmt":"2014-11-07T18:00:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10276"},"modified":"2014-11-07T10:29:00","modified_gmt":"2014-11-07T14:29:00","slug":"nuevo-virus-puede-infectar-iphones-a-traves-de-computadoras-mac","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nuevo-virus-puede-infectar-iphones-a-traves-de-computadoras-mac\/","title":{"rendered":"Nuevo virus puede infectar iPhones a trav\u00e9s de computadoras Mac"},"content":{"rendered":"<p>Un nuevo malware reci\u00e9n descubierto puede infectar los <label>celulares<\/label> <label>iPhone<\/label> a trav\u00e9s de las<label>computadoras<\/label> <label>Apple<\/label>, una amenaza contra estos <label>dispositivos<\/label> que por mucho tiempo fueron resistentes a los cibercriminales, dijeron investigadores.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/ipo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10277 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/ipo-300x200.jpg\" alt=\"ipo\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/ipo-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/ipo.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Investigadores de Palo Alto Networks, una firma de ciberseguridad, indic\u00f3 que el malware (software malicioso) muestra \u00abcaracter\u00edsticas no vistas en ninguna amenaza previa documentada contra las plataformas de Apple\u00bb.<!--more--><\/p>\n<p>Esto representa \u00abuna potencial amenaza para el negocio, gobiernos y los clientes de Apple en todo el mundo\u00bb, se\u00f1alaron.<\/p>\n<p>El \u00abmalware\u00bb, llamado WireLurker, \u00abes capaz de robar una variedad de informaci\u00f3n de los dispositivos m\u00f3viles que infecta y regularmente requiere actualizaciones del comando de atacantes y el servidor de control\u00bb, seg\u00fan un reporte de seguridad de la firma, agregando que \u00abla meta final del creador aun no est\u00e1 clara\u00bb.<\/p>\n<p>Aunque en el pasado los piratas inform\u00e1ticos han podido atacar iPhones \u00abjailbroken\u00bb, es decir que fueron modificados por su usuario para usar software no autorizado por Apple, esta nueva amenaza parece poner en riesgo a los dispositivos que no han sido modificados, dijo el equipo de seguridad.<\/p>\n<p>\u00abWireLurker no se parece a nada que hayamos visto en t\u00e9rminos de malwares contra Apple iOS y OS X\u00bb, dijo Ryan Olson de Palo Alto.<\/p>\n<p>\u00abLas t\u00e9cnicas que utilizan estos piratas sugieren que se est\u00e1n volviendo cada vez m\u00e1s sofisticados a la hora de explotar una de las mejores plataformas de escritorio y celular que hay en el mundo\u00bb.<\/p>\n<p>Seg\u00fan los investigadores, el malware WireLurker primero infecta las computadoras Mac, que usan el sistema operativo OS X, y luego se instala solo en los dispositivos iOS &#8211;iPads o iPhones&#8211; cuando est\u00e1n conectados a las computadoras por un puerto USB.<\/p>\n<p>El malware fue rastreado hasta una tienda de aplicaciones china, que hab\u00eda infectado 467 aplicaciones de descarga unas 356.104 veces, afectando potencialmente a cientos de miles de usuarios.<\/p>\n<p>AFP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo malware reci\u00e9n descubierto puede infectar los celulares iPhone a trav\u00e9s de lascomputadoras Apple, una amenaza contra estos dispositivos que por mucho tiempo fueron resistentes a los cibercriminales, dijeron investigadores. Investigadores de Palo Alto Networks, una firma de ciberseguridad, indic\u00f3 que el malware (software malicioso) muestra \u00abcaracter\u00edsticas no vistas en ninguna amenaza previa documentada contra las plataformas de Apple\u00bb.<\/p>\n","protected":false},"author":3,"featured_media":10277,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-10276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10276"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10276\/revisions"}],"predecessor-version":[{"id":10278,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10276\/revisions\/10278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10277"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}