{"id":10296,"date":"2014-11-07T14:30:04","date_gmt":"2014-11-07T18:30:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10296"},"modified":"2014-11-07T10:59:18","modified_gmt":"2014-11-07T14:59:18","slug":"chiquito-team-band-asegura-que-hay-hermandad-entre-los-cantantes-de-salsa","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/chiquito-team-band-asegura-que-hay-hermandad-entre-los-cantantes-de-salsa\/","title":{"rendered":"Chiquito Team Band asegura que hay hermandad entre los cantantes de salsa"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/Chiquito-Team-Band-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10297 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/Chiquito-Team-Band--300x161.jpg\" alt=\"Chiquito-Team-Band-\" width=\"300\" height=\"161\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/Chiquito-Team-Band--300x161.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/Chiquito-Team-Band-.jpg 688w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Santo Domingo, Rep\u00fablica Dominicana. Los integrantes de la agrupaci\u00f3n salsera dominicana Chiquito Team Band ratifican que la participaci\u00f3n de los salseros en el Festival Presidente de M\u00fasica Latina, evidencia la hermandad y compa\u00f1erismo entre los diversos exponentes salseros dominicanos.<!--more--><\/p>\n<p>Para los chicos de la banda realmente fue muy emotivo ese momento en que todos compartieron un mismo escenario, sin rivalidad ni competencia, en un entorno cargado de hermandad y amistad.<\/p>\n<p>Adelantaron que trabajan en la preparaci\u00f3n del video del tema in\u00e9dito \u201cNos Desacatamos\u201d una composici\u00f3n de Eddy Wilson Berroa, y dan los toque finales a su \u00faltima canci\u00f3n \u201cQue te Parta un Rayo\u201d.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/l3iGloQpKoY\" width=\"548\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Hablan de todos los logros que han alcanzado con tan s\u00f3lo dos a\u00f1os de haberse formando la banda, siendo ganadores de Premios Soberano como Revelaci\u00f3n de A\u00f1o, haber estado en dos ocasiones en el Centro Ol\u00edmpico, ganadores al Premio Conga de Salsa como Revelaci\u00f3n as\u00ed como por sus giras internacionales que los han llevado a recorrer diversas partes de los Estados Unidos y Europa.<\/p>\n<p>\u201cLo que m\u00e1s nos llena de satisfacci\u00f3n en estos dos a\u00f1os ha sido el saber que a la gente le ha gustado lo que hemos estado haciendo con la salsa, haber conectado con la gente y calar en sus gustos es un gran privilegio\u201d, expresan.<\/p>\n<p>Para \u00e9sta entrega nos visita la holista, Karina Pereyra, quien habla de la importancia del valor de la gratitud, en una enriquecedora entrevista para aprender a identificar esos momentos del d\u00eda en que debemos ser agradecidos con nosotros mismos, lo que seg\u00fan la experta estar conectados al sentimiento de la gratitud nos ayuda a ser personas m\u00e1s confiadas y alegres.<\/p>\n<p>El contenido de Noche de Luz contin\u00faa \u00e9ste pr\u00f3ximo s\u00e1bado repleto de novedades a cargo de una producci\u00f3n dise\u00f1ada y planeada para los que buscan televisi\u00f3n de calidad.<\/p>\n<p>Fuente: ensegundos.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, Rep\u00fablica Dominicana. Los integrantes de la agrupaci\u00f3n salsera dominicana Chiquito Team Band ratifican que la participaci\u00f3n de los salseros en el Festival Presidente de M\u00fasica Latina, evidencia la hermandad y compa\u00f1erismo entre los diversos exponentes salseros dominicanos.<\/p>\n","protected":false},"author":3,"featured_media":10297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10296"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10296\/revisions"}],"predecessor-version":[{"id":10298,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10296\/revisions\/10298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10297"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}