{"id":105351,"date":"2025-05-06T03:09:51","date_gmt":"2025-05-06T07:09:51","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=105351"},"modified":"2025-05-06T03:10:00","modified_gmt":"2025-05-06T07:10:00","slug":"exigidos-al-maximo-y-con-42-de-jokic-denver-gana-primero-a-oklahoma-city","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/exigidos-al-maximo-y-con-42-de-jokic-denver-gana-primero-a-oklahoma-city\/","title":{"rendered":"Exigidos al m\u00e1ximo y con 42 de Jokic, Denver gana primero a Oklahoma City"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"896\" height=\"504\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/semifinal-oeste.jpg\" alt=\"\" class=\"wp-image-105353\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/semifinal-oeste.jpg 896w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/semifinal-oeste-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/semifinal-oeste-768x432.jpg 768w\" sizes=\"auto, (max-width: 896px) 100vw, 896px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nikola Jokic tuvo 42 puntos y 22 rebotes, y Aaron Gordon conect\u00f3 un triple en los \u00faltimos segundos para dar a los Denver&nbsp;<strong>Nuggets<\/strong>&nbsp;una impresionante victoria de regreso de 121-119 sobre el cabeza de serie Oklahoma City&nbsp;<strong>Thunder<\/strong>&nbsp;el lunes por la noche en el Juego 1 de su serie de semifinales de la Conferencia Oeste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oklahoma City, fuera de los tiempos muertos, se perdi\u00f3 una desesperaci\u00f3n cuando se agot\u00f3 el tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Russell Westbrook de Denver, que comenz\u00f3 su carrera con los&nbsp;<strong>Thunder<\/strong>, ayud\u00f3 al ganador del juego de Gordon. Fue su primer partido de playoffs en Oklahoma City como jugador contrario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gordon termin\u00f3 con 22 puntos y 14 rebotes. Jamal Murray agreg\u00f3 21 puntos para los&nbsp;<strong>Nuggets<\/strong>, cuartos cabeza de serie, que robaron el abridor despu\u00e9s de cerrar una serie de siete partidos contra los Los Angeles Clippers el s\u00e1bado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nikola Jokic tuvo 42 puntos y 22 rebotes, y Aaron Gordon conect\u00f3 un triple en los \u00faltimos segundos para dar a los Denver&nbsp;Nuggets&nbsp;una impresionante victoria de regreso de 121-119 sobre el cabeza de serie Oklahoma City&nbsp;Thunder&nbsp;el lunes por la noche en el Juego 1 de su serie de semifinales de la Conferencia Oeste. Oklahoma City, fuera de los tiempos muertos, se perdi\u00f3 una desesperaci\u00f3n cuando se agot\u00f3 el tiempo. Russell Westbrook de Denver, que comenz\u00f3 su carrera con los&nbsp;Thunder, ayud\u00f3 al ganador del juego de Gordon. Fue su primer partido de playoffs en Oklahoma City como jugador contrario. Gordon termin\u00f3 con 22 puntos y 14 rebotes. Jamal Murray agreg\u00f3 21 puntos para los&nbsp;Nuggets, cuartos cabeza de serie, que robaron el abridor despu\u00e9s de cerrar una serie de siete partidos contra los Los Angeles Clippers el s\u00e1bado.<\/p>\n","protected":false},"author":12,"featured_media":105353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-105351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=105351"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105351\/revisions"}],"predecessor-version":[{"id":105354,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105351\/revisions\/105354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/105353"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=105351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=105351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=105351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}