{"id":105746,"date":"2025-05-27T06:56:14","date_gmt":"2025-05-27T10:56:14","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=105746"},"modified":"2025-05-27T06:56:16","modified_gmt":"2025-05-27T10:56:16","slug":"faride-raful-lamenta-la-falta-de-apoyo-ante-la-crisis-en-haiti-no-podemos-estar-solos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/faride-raful-lamenta-la-falta-de-apoyo-ante-la-crisis-en-haiti-no-podemos-estar-solos\/","title":{"rendered":"Faride Raful lamenta la falta de apoyo ante la crisis en Hait\u00ed: \u00abNo podemos estar solos\u00bb"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/6834c446cd606.jpeg\" alt=\"\" class=\"wp-image-105747\" style=\"width:213px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/6834c446cd606.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/6834c446cd606-300x225.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/6834c446cd606-768x576.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La ministra del Interior y Polic\u00eda, Faride Raful, ha lamentado la falta de apoyo internacional que han recibido para hacer frente a la grave crisis de seguridad, humanitaria y pol\u00edtica que padece la vecina Hait\u00ed y ha remarcado que se trata de un problema que afecta a todos los pa\u00edses de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNos ha faltado m\u00e1s apoyo y&nbsp;<strong>Rep\u00fablica Dominicana definitivamente no puede estar sola<\/strong>\u00ab, ha dicho la ministra del Interior en una entrevista para Europa Press, con motivo de su visita oficial a Espa\u00f1a, durante la cual se ha reunido con varias autoridades, entre ellas su hom\u00f3logo espa\u00f1ol, Fernando Grande-Marlaska.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Raful ha reclamado nuevamente a la comunidad internacional mayor implicaci\u00f3n en un asunto que no es s\u00f3lo un \u00abproblema directo para Rep\u00fablica Dominicana\u00bb, sino tambi\u00e9n un \u00abtema regional\u00bb, ya que la migraci\u00f3n procedente de Hait\u00ed&nbsp;<strong>afecta tambi\u00e9n a otros pa\u00edses de la regi\u00f3n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abComo es natural, el ser humano va a migrar donde cree que puede salvar su vida, puede encontrar mejores oportunidades. Sin embargo, nosotros somos un pa\u00eds en v\u00eda de desarrollo, donde estamos fortaleci\u00e9ndonos institucionalmente y no tenemos capacidad de afrontar la carga migratoria irregular\u00bb, ha dicho la ministra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, ha defendido las pol\u00edticas migratorias del Gobierno y ha incidido en las reformas que se est\u00e1n llevando a cabo para que las mismas est\u00e9n en sinton\u00eda estrecha con los Derechos Humanos y sin \u00abavasallar\u00bb a quienes han sido identificados como migrantes irregulares,&nbsp;<strong>en medio de las cr\u00edticas de las ONG.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno dominicano ha sido cuestionado por las batidas que las fuerzas de seguridad han lanzado en barrios populares en los que residen predominantemente migrantes haitianos, as\u00ed como por los abusos que se habr\u00edan cometido, trasladados en unas especies de jaulas rodantes, que la ministra ha preferido no denominar as\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLa realidad es que no se llevan en jaulas. Acabamos de invertir una gran cantidad de recursos para tener nuevos&nbsp;<strong>autobuses con condiciones para poder hacer los transportes<\/strong>\u00ab, ha dicho la ministra, quien tambi\u00e9n ha rechazado que se niegue a las mujeres haitianas asistencia sanitaria durante el embarazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abA nadie, no importa su nacionalidad, en Rep\u00fablica Dominicana se le niega el acceso a la salud. Eso es importante que se sepa porque hay muchas noticias que desinforman\u00bb, ha incidido Raful, quien ha recordado que existen unos protocolos bajo los cuales estas mujeres puede permanecer en el pa\u00eds un tiempo prudencial antes de ser enviadas de vuelta a Hait\u00ed una vez est\u00e9n \u00abtotalmente estables\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstamos cumpliendo la ley, estamos formando nuevos agentes migratorios para que el abordaje que se haga del migrante irregular&nbsp;<strong>sea respetuoso con los Derechos Humanos<\/strong>\u00ab, ha defendido la ministra, quien tambi\u00e9n ha alertado de la \u00abpermanente vulnerabilidad\u00bb de la \u00abbastante porosa\u00bb frontera con Hait\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Raful tambi\u00e9n ha lamentado que la falta de institucionalidad en Hait\u00ed, sin un \u00abinterlocutor v\u00e1lido pol\u00edtico\u00bb, dificulta las pol\u00edticas del Gobierno, si bien ha destacado la labor de las autoridades haitianas presentes en Rep\u00fablica Dominicana para \u00absalvaguardar el desplazamiento de sus ciudadanos hacia su territorio\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ministra ha explicado que es \u00abdif\u00edcil\u00bb entablar di\u00e1logos permanentes con las instituciones del pa\u00eds vecino, las cuales adem\u00e1s se han visto afectadas por la corrupci\u00f3n y la presencia cada vez mayor de las bandas criminales que controlan ya gran parte del pa\u00eds, en especial la capital, Puerto Pr\u00edncipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ATAQUES EN REDES Y CR\u00cdMENES DE ODIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La crisis migratoria que afecta al pa\u00eds ha tra\u00eddo consigo tambi\u00e9n un aumento de los discursos xen\u00f3fobos, si bien el recelo de los dominicanos con respecto a sus vecinos haitianos es un asunto que forma parte de la historia reciente de la isla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es en este contexto en el que se han erigido algunos grupos para aumentar sus ataques y denunciar una supuesta &#8216;haitinizaci\u00f3n&#8217; de la sociedad, reprochando al Gobierno una inacci\u00f3n contra la migraci\u00f3n irregular, en contraste con las denuncias de las organizaciones de Derechos Humanos en el otro sentido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ministra ha resaltado en esta cuesti\u00f3n que, si bien existe la libertad de expresi\u00f3n, el Gobierno dominicano \u00aben ning\u00fan momento va a permitir que eso siga tomando fuerzas\u00bb y ha advertido contra los grupos que buscan polarizar \u00abhasta extremos\u00bb a la sociedad con el fin de alg\u00fan tipo de reacci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unos discursos de odio, aunque de otra \u00edndole, que ella misma ha sufrido a trav\u00e9s de redes sociales y que responden, seg\u00fan cree, a la respuesta de la \u00abindustria del desorden\u00bb a su trabajo, retroalimentada por esos adversarios pol\u00edticos que se suman \u00abpara tratar de restar credibilidad\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCuando llegamos al Ministerio (&#8230;) nos enfrentamos con grandes intereses. Hay industrias que viven del desorden y se lucran\u00bb, ha dicho la ministra del Interior, citando por ejemplo a las redes del microtr\u00e1fico de drogas, de armas, e incluso a una parte de \u00abla industria de la nocturnidad que de manera irregular se llenaba los bolsillos creando espacios sin ning\u00fan tipo de fiscalizaci\u00f3n\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FALTA DE \u00abCONCIENCIA CIUDADANA\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan con todos los problemas que entra\u00f1a convivir con un vecino de las caracter\u00edsticas actuales de Hait\u00ed, la ministra ha aseverado que el principal motivo de la inseguridad en Rep\u00fablica Dominicana emana de la \u00abconflictividad social\u00bb que procede de las propias caracter\u00edsticas y din\u00e1micas propias de un pa\u00eds caribe\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Raful ha afirmado que se trata de todo un \u00abdesaf\u00edo\u00bb lograr una \u00abconvivencia pac\u00edfica\u00bb en Rep\u00fablica Dominicana, en donde las peque\u00f1as cuitas ciudadanas pueden derivar en graves fricciones. Para ello, ha se\u00f1alado que adem\u00e1s de reformar las instituciones o la Polic\u00eda, es preciso un \u00abcambio de cultura\u00bb en la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, la ministra ha reconocido que \u00aba veces\u00bb por las propias din\u00e1micas de pa\u00edses como Rep\u00fablica Dominicana &#8211;\u00aben v\u00edas de desarrollo, caribe\u00f1os\u00bb, o \u00abfalta de institucionalidad\u00bb&#8211; hace dif\u00edcil el cumplimiento de las normas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNos falta cumplir un orden, nos falta apostar al orden institucional y respetar los derechos de los dem\u00e1s\u00bb, ha admitido Raful, quien han insistido en que trabajan para \u00abgarantizar que la ciudadan\u00eda no pierda la vida en un conflicto\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de esta \u00abfalta de conciencia ciudadana\u00bb, ha destacado que Rep\u00fablica Dominicana \u00abse ha convertido en el pa\u00eds m\u00e1s seguro del Caribe\u00bb, situ\u00e1ndose entre los diez de Am\u00e9rica Latina con una tasa de homicidio por debajo de un d\u00edgito. \u00abAhora estamos en 7,9\u00bb, ha puesto en valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ministra ha participado en varios encuentros estos d\u00edas en Madrid, entre ellos con su hom\u00f3logo Grande-Marlaska, como parte de los actos previos a la octava reuni\u00f3n sobre seguridad p\u00fablica de las Am\u00e9ricas &#8211;auspiciada por la Organizaci\u00f3n de los Estados Americanos (OEA)&#8211; que tendr\u00e1 lugar entre el 17 y el 18 de julio en la ciudad dominicana Santiago de los Caballeros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ministra del Interior y Polic\u00eda, Faride Raful, ha lamentado la falta de apoyo internacional que han recibido para hacer frente a la grave crisis de seguridad, humanitaria y pol\u00edtica que padece la vecina Hait\u00ed y ha remarcado que se trata de un problema que afecta a todos los pa\u00edses de la regi\u00f3n. \u00abNos ha faltado m\u00e1s apoyo y&nbsp;Rep\u00fablica Dominicana definitivamente no puede estar sola\u00ab, ha dicho la ministra del Interior en una entrevista para Europa Press, con motivo de su visita oficial a Espa\u00f1a, durante la cual se ha reunido con varias autoridades, entre ellas su hom\u00f3logo espa\u00f1ol, Fernando Grande-Marlaska. Raful ha reclamado nuevamente a la comunidad internacional mayor implicaci\u00f3n en un asunto que no es s\u00f3lo un \u00abproblema directo para Rep\u00fablica Dominicana\u00bb, sino tambi\u00e9n un \u00abtema regional\u00bb, ya que la migraci\u00f3n procedente de Hait\u00ed&nbsp;afecta tambi\u00e9n a otros pa\u00edses de la regi\u00f3n. \u00abComo es natural, el ser humano va a migrar donde cree que puede salvar su vida, puede encontrar mejores oportunidades. Sin embargo, nosotros somos un pa\u00eds en v\u00eda de desarrollo, donde estamos fortaleci\u00e9ndonos institucionalmente y no tenemos capacidad de afrontar la carga migratoria irregular\u00bb, ha dicho la ministra. En ese sentido, ha defendido las pol\u00edticas migratorias del Gobierno y ha incidido en las reformas que se est\u00e1n llevando a cabo para que las mismas est\u00e9n en sinton\u00eda estrecha con los Derechos Humanos y sin \u00abavasallar\u00bb a quienes han sido identificados como migrantes irregulares,&nbsp;en medio de las cr\u00edticas de las ONG. El Gobierno dominicano ha sido cuestionado por las batidas que las fuerzas de seguridad han lanzado en barrios populares en los que residen predominantemente migrantes haitianos, as\u00ed como por los abusos que se habr\u00edan cometido, trasladados en unas especies de jaulas rodantes, que la ministra ha preferido no denominar as\u00ed. \u00abLa realidad es que no se llevan en jaulas. Acabamos de invertir una gran cantidad de recursos para tener nuevos&nbsp;autobuses con condiciones para poder hacer los transportes\u00ab, ha dicho la ministra, quien tambi\u00e9n ha rechazado que se niegue a las mujeres haitianas asistencia sanitaria durante el embarazo. \u00abA nadie, no importa su nacionalidad, en Rep\u00fablica Dominicana se le niega el acceso a la salud. Eso es importante que se sepa porque hay muchas noticias que desinforman\u00bb, ha incidido Raful, quien ha recordado que existen unos protocolos bajo los cuales estas mujeres puede permanecer en el pa\u00eds un tiempo prudencial antes de ser enviadas de vuelta a Hait\u00ed una vez est\u00e9n \u00abtotalmente estables\u00bb. \u00abEstamos cumpliendo la ley, estamos formando nuevos agentes migratorios para que el abordaje que se haga del migrante irregular&nbsp;sea respetuoso con los Derechos Humanos\u00ab, ha defendido la ministra, quien tambi\u00e9n ha alertado de la \u00abpermanente vulnerabilidad\u00bb de la \u00abbastante porosa\u00bb frontera con Hait\u00ed. Raful tambi\u00e9n ha lamentado que la falta de institucionalidad en Hait\u00ed, sin un \u00abinterlocutor v\u00e1lido pol\u00edtico\u00bb, dificulta las pol\u00edticas del Gobierno, si bien ha destacado la labor de las autoridades haitianas presentes en Rep\u00fablica Dominicana para \u00absalvaguardar el desplazamiento de sus ciudadanos hacia su territorio\u00bb. La ministra ha explicado que es \u00abdif\u00edcil\u00bb entablar di\u00e1logos permanentes con las instituciones del pa\u00eds vecino, las cuales adem\u00e1s se han visto afectadas por la corrupci\u00f3n y la presencia cada vez mayor de las bandas criminales que controlan ya gran parte del pa\u00eds, en especial la capital, Puerto Pr\u00edncipe. ATAQUES EN REDES Y CR\u00cdMENES DE ODIO La crisis migratoria que afecta al pa\u00eds ha tra\u00eddo consigo tambi\u00e9n un aumento de los discursos xen\u00f3fobos, si bien el recelo de los dominicanos con respecto a sus vecinos haitianos es un asunto que forma parte de la historia reciente de la isla. Es en este contexto en el que se han erigido algunos grupos para aumentar sus ataques y denunciar una supuesta &#8216;haitinizaci\u00f3n&#8217; de la sociedad, reprochando al Gobierno una inacci\u00f3n contra la migraci\u00f3n irregular, en contraste con las denuncias de las organizaciones de Derechos Humanos en el otro sentido. La ministra ha resaltado en esta cuesti\u00f3n que, si bien existe la libertad de expresi\u00f3n, el Gobierno dominicano \u00aben ning\u00fan momento va a permitir que eso siga tomando fuerzas\u00bb y ha advertido contra los grupos que buscan polarizar \u00abhasta extremos\u00bb a la sociedad con el fin de alg\u00fan tipo de reacci\u00f3n. Unos discursos de odio, aunque de otra \u00edndole, que ella misma ha sufrido a trav\u00e9s de redes sociales y que responden, seg\u00fan cree, a la respuesta de la \u00abindustria del desorden\u00bb a su trabajo, retroalimentada por esos adversarios pol\u00edticos que se suman \u00abpara tratar de restar credibilidad\u00bb. \u00abCuando llegamos al Ministerio (&#8230;) nos enfrentamos con grandes intereses. Hay industrias que viven del desorden y se lucran\u00bb, ha dicho la ministra del Interior, citando por ejemplo a las redes del microtr\u00e1fico de drogas, de armas, e incluso a una parte de \u00abla industria de la nocturnidad que de manera irregular se llenaba los bolsillos creando espacios sin ning\u00fan tipo de fiscalizaci\u00f3n\u00bb. FALTA DE \u00abCONCIENCIA CIUDADANA\u00bb A\u00fan con todos los problemas que entra\u00f1a convivir con un vecino de las caracter\u00edsticas actuales de Hait\u00ed, la ministra ha aseverado que el principal motivo de la inseguridad en Rep\u00fablica Dominicana emana de la \u00abconflictividad social\u00bb que procede de las propias caracter\u00edsticas y din\u00e1micas propias de un pa\u00eds caribe\u00f1o. Raful ha afirmado que se trata de todo un \u00abdesaf\u00edo\u00bb lograr una \u00abconvivencia pac\u00edfica\u00bb en Rep\u00fablica Dominicana, en donde las peque\u00f1as cuitas ciudadanas pueden derivar en graves fricciones. Para ello, ha se\u00f1alado que adem\u00e1s de reformar las instituciones o la Polic\u00eda, es preciso un \u00abcambio de cultura\u00bb en la sociedad. En ese sentido, la ministra ha reconocido que \u00aba veces\u00bb por las propias din\u00e1micas de pa\u00edses como Rep\u00fablica Dominicana &#8211;\u00aben v\u00edas de desarrollo, caribe\u00f1os\u00bb, o \u00abfalta de institucionalidad\u00bb&#8211; hace dif\u00edcil el cumplimiento de las normas. \u00abNos falta cumplir un orden, nos falta apostar al orden institucional y respetar los derechos de los dem\u00e1s\u00bb, ha admitido Raful, quien han insistido en que trabajan para \u00abgarantizar que la ciudadan\u00eda no pierda la vida en un conflicto\u00bb. A pesar de esta \u00abfalta de conciencia ciudadana\u00bb, ha destacado que Rep\u00fablica Dominicana \u00abse ha convertido en el pa\u00eds m\u00e1s seguro del [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":105747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-105746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=105746"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105746\/revisions"}],"predecessor-version":[{"id":105748,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105746\/revisions\/105748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/105747"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=105746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=105746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=105746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}