{"id":105756,"date":"2025-05-28T06:39:31","date_gmt":"2025-05-28T10:39:31","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=105756"},"modified":"2025-05-28T06:39:33","modified_gmt":"2025-05-28T10:39:33","slug":"de-la-cruz-pega-dos-largos-jonrones-incluido-uno-de-436-pies-ante-los-reales","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/de-la-cruz-pega-dos-largos-jonrones-incluido-uno-de-436-pies-ante-los-reales\/","title":{"rendered":"De La Cruz pega dos largos jonrones, incluido uno de 436 pies ante los Reales"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/68367a249c2d1.r_d.869-325.jpeg\" alt=\"\" class=\"wp-image-105757\" style=\"width:234px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/68367a249c2d1.r_d.869-325.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/68367a249c2d1.r_d.869-325-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/05\/68367a249c2d1.r_d.869-325-768x512.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Elly De La Cruz conect\u00f3 dos largos jonrones, Brady Singer lanz\u00f3 siete s\u00f3lidas entradas contra su ex equipo y los Rojos de Cincinnati vencieron a los Reales de Kansas City 7-2 el martes por la noche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De La Cruz conect\u00f3 un batazo de 436 pies al jard\u00edn central en la cuarta entrada que empat\u00f3 el marcador a 2 contra Jonathan Bowlan, y luego un batazo de 451 pies que puso a la cabeza en la sexta entrada, conectando un batazo de 451 pies hacia la fuente del jard\u00edn derecho-central contra Taylor Clarke (1-1). De La Cruz suma 11 jonrones esta temporada. Empat\u00f3 el r\u00e9cord del equipo de Pete Rose para bateadores ambidiestros con cinco juegos de m\u00e1s de un jonr\u00f3n, incluyendo dos este a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Singer (6-3), adquirido de los Royals en noviembre, permiti\u00f3 dos carreras y siete sencillos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tyler Stephenson conect\u00f3 jonr\u00f3n en el segundo, pero Kyle Isbel y Jonathan India tuvieron sencillos productores en la mitad inferior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Momento clave<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TJ Friedl conect\u00f3 un sencillo para abrir la octava entrada y anot\u00f3 desde primera gracias a un squibber dentro del cuadro. El tiro apresurado del lanzador John Schreiber rebot\u00f3 al jard\u00edn derecho, cometiendo un error. De La Cruz recibi\u00f3 base por bolas intencional antes de que Schreiber otorgara bases por bolas a Stephenson y Spencer Steer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elly De La Cruz conect\u00f3 dos largos jonrones, Brady Singer lanz\u00f3 siete s\u00f3lidas entradas contra su ex equipo y los Rojos de Cincinnati vencieron a los Reales de Kansas City 7-2 el martes por la noche. De La Cruz conect\u00f3 un batazo de 436 pies al jard\u00edn central en la cuarta entrada que empat\u00f3 el marcador a 2 contra Jonathan Bowlan, y luego un batazo de 451 pies que puso a la cabeza en la sexta entrada, conectando un batazo de 451 pies hacia la fuente del jard\u00edn derecho-central contra Taylor Clarke (1-1). De La Cruz suma 11 jonrones esta temporada. Empat\u00f3 el r\u00e9cord del equipo de Pete Rose para bateadores ambidiestros con cinco juegos de m\u00e1s de un jonr\u00f3n, incluyendo dos este a\u00f1o. Singer (6-3), adquirido de los Royals en noviembre, permiti\u00f3 dos carreras y siete sencillos. Tyler Stephenson conect\u00f3 jonr\u00f3n en el segundo, pero Kyle Isbel y Jonathan India tuvieron sencillos productores en la mitad inferior. Momento clave TJ Friedl conect\u00f3 un sencillo para abrir la octava entrada y anot\u00f3 desde primera gracias a un squibber dentro del cuadro. El tiro apresurado del lanzador John Schreiber rebot\u00f3 al jard\u00edn derecho, cometiendo un error. De La Cruz recibi\u00f3 base por bolas intencional antes de que Schreiber otorgara bases por bolas a Stephenson y Spencer Steer.<\/p>\n","protected":false},"author":9,"featured_media":105757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-105756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=105756"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105756\/revisions"}],"predecessor-version":[{"id":105758,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/105756\/revisions\/105758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/105757"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=105756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=105756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=105756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}