{"id":106061,"date":"2025-06-19T07:59:22","date_gmt":"2025-06-19T11:59:22","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=106061"},"modified":"2025-06-19T07:59:23","modified_gmt":"2025-06-19T11:59:23","slug":"bad-bunny-dice-que-es-innecesario-llevar-su-proxima-gira-a-estados-unidos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/bad-bunny-dice-que-es-innecesario-llevar-su-proxima-gira-a-estados-unidos\/","title":{"rendered":"Bad Bunny dice que es \u00abinnecesario\u00bb llevar su pr\u00f3xima gira a Estados Unidos"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/65e7ce401d1db.r_d.249-542-683x1024.jpeg\" alt=\"\" class=\"wp-image-106062\" style=\"width:258px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/65e7ce401d1db.r_d.249-542-683x1024.jpeg 683w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/65e7ce401d1db.r_d.249-542-200x300.jpeg 200w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/65e7ce401d1db.r_d.249-542-768x1152.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/65e7ce401d1db.r_d.249-542.jpeg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Bad Bunny<\/strong>&nbsp;anunci\u00f3 su residencia de 30 funciones en Puerto Rico, 9 para locales y 21 para visitantes, tras&nbsp;casi un a\u00f1o de gira lejos de su isla natal, que se extender\u00e1 los fines de semana del 11 de julio al 14 de septiembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque dio a conocer que tambi\u00e9n iniciar\u00e1 un recorrido de conciertos que llegar\u00e1 a Latinoam\u00e9rica, Europa y Asia, el cantante puertorrique\u00f1o descart\u00f3 presentarse en vivo en Estados Unidos o llevar un documental de su espect\u00e1culo a ese pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00abEs innecesario\u00bb,<\/strong>&nbsp;dijo el artista, quien considera que sus fan\u00e1ticos en ese territorio han disfrutado lo suficiente de sus actuaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de su espect\u00e1culo \u00abNo me quiero ir de aqu\u00ed\u00bb en el Coliseo Jos\u00e9 Miguel Agrelot de Puerto Rico, Bad Bunny tendr\u00e1 su gira mundial \u00abDeb\u00ed tirar m\u00e1s fotos\u00bb, que se desprende de su \u00e1lbum hom\u00f3nimo y que comenzar\u00e1 en noviembre en Rep\u00fablica Dominicana y concluir\u00e1 en B\u00e9lgica el 22 de julio de 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La estrella del trap revel\u00f3 que inicialmente pens\u00f3 hacer su residencia masiva en Puerto Rico de forma gratuita para sus compatriotas, sin embargo, promete un show innovador dedicado a su cultura y sus or\u00edgenes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLa idea de la residencia siempre estuvo ah\u00ed, desde que tengo memoria. Pero se volvi\u00f3 dif\u00edcil ignorarla con el paso del tiempo. Admito que fue dif\u00edcil completar mi \u00faltima gira, porque lo \u00fanico que quer\u00eda era empezar este cap\u00edtulo\u00bb, admiti\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAntes de la residencia, mi fantas\u00eda durante mucho tiempo era hacer un concierto masivo y gratuito en Puerto Rico, solo para locales. Y si fuera por m\u00ed, todos los conciertos para los locales ser\u00edan gratuitos, pero lo que tenemos planeado ahora es de otro nivel\u00bb, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, aclar\u00f3 que \u00abno soy Taylor Swift\u00bb, as\u00ed que no har\u00e1 una versi\u00f3n Eras de su tour,&nbsp;con segmentos dedicados a cada \u00e1lbum de su carrera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bad Bunny&nbsp;anunci\u00f3 su residencia de 30 funciones en Puerto Rico, 9 para locales y 21 para visitantes, tras&nbsp;casi un a\u00f1o de gira lejos de su isla natal, que se extender\u00e1 los fines de semana del 11 de julio al 14 de septiembre. Aunque dio a conocer que tambi\u00e9n iniciar\u00e1 un recorrido de conciertos que llegar\u00e1 a Latinoam\u00e9rica, Europa y Asia, el cantante puertorrique\u00f1o descart\u00f3 presentarse en vivo en Estados Unidos o llevar un documental de su espect\u00e1culo a ese pa\u00eds. \u00abEs innecesario\u00bb,&nbsp;dijo el artista, quien considera que sus fan\u00e1ticos en ese territorio han disfrutado lo suficiente de sus actuaciones. Despu\u00e9s de su espect\u00e1culo \u00abNo me quiero ir de aqu\u00ed\u00bb en el Coliseo Jos\u00e9 Miguel Agrelot de Puerto Rico, Bad Bunny tendr\u00e1 su gira mundial \u00abDeb\u00ed tirar m\u00e1s fotos\u00bb, que se desprende de su \u00e1lbum hom\u00f3nimo y que comenzar\u00e1 en noviembre en Rep\u00fablica Dominicana y concluir\u00e1 en B\u00e9lgica el 22 de julio de 2026. La estrella del trap revel\u00f3 que inicialmente pens\u00f3 hacer su residencia masiva en Puerto Rico de forma gratuita para sus compatriotas, sin embargo, promete un show innovador dedicado a su cultura y sus or\u00edgenes.&nbsp; \u00abLa idea de la residencia siempre estuvo ah\u00ed, desde que tengo memoria. Pero se volvi\u00f3 dif\u00edcil ignorarla con el paso del tiempo. Admito que fue dif\u00edcil completar mi \u00faltima gira, porque lo \u00fanico que quer\u00eda era empezar este cap\u00edtulo\u00bb, admiti\u00f3. \u00abAntes de la residencia, mi fantas\u00eda durante mucho tiempo era hacer un concierto masivo y gratuito en Puerto Rico, solo para locales. Y si fuera por m\u00ed, todos los conciertos para los locales ser\u00edan gratuitos, pero lo que tenemos planeado ahora es de otro nivel\u00bb, explic\u00f3. Asimismo, aclar\u00f3 que \u00abno soy Taylor Swift\u00bb, as\u00ed que no har\u00e1 una versi\u00f3n Eras de su tour,&nbsp;con segmentos dedicados a cada \u00e1lbum de su carrera.<\/p>\n","protected":false},"author":9,"featured_media":106062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-106061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=106061"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106061\/revisions"}],"predecessor-version":[{"id":106063,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106061\/revisions\/106063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/106062"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=106061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=106061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=106061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}