{"id":106098,"date":"2025-06-22T07:57:06","date_gmt":"2025-06-22T11:57:06","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=106098"},"modified":"2025-06-22T07:57:08","modified_gmt":"2025-06-22T11:57:08","slug":"trump-advierte-a-iran-si-la-paz-no-llega-rapido-iremos-por-otros-objetivos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/trump-advierte-a-iran-si-la-paz-no-llega-rapido-iremos-por-otros-objetivos\/","title":{"rendered":"Trump advierte a Ir\u00e1n: \u00absi la paz no llega r\u00e1pido, iremos por otros objetivos\u00bb"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"627\" height=\"300\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/68576ee30d88c.jpeg\" alt=\"\" class=\"wp-image-106099\" style=\"width:341px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/68576ee30d88c.jpeg 627w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/68576ee30d88c-300x144.jpeg 300w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El<strong>&nbsp;presidente de Estados Unidos, Donald Trump,<\/strong>&nbsp;avis\u00f3 a&nbsp;<strong>Ir\u00e1n&nbsp;<\/strong>que \u00absi la paz no llegar pronto\u00bb, tras el ataque estadounidense a sus principales instalaciones del&nbsp;<strong>programa nuclear<\/strong>, \u00abiremos por esos otros objetivos, con precisi\u00f3n, velocidad y destreza\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas<strong>&nbsp;declaraciones de Trump&nbsp;<\/strong>se produjeron durante un discurso en la<strong>&nbsp;Casa Blanca<\/strong>&nbsp;luego de que aeronaves del ej\u00e9rcito estadounidense llev\u00f3 a cabo un \u00abataque muy exitoso\u00bb contra tres<strong>&nbsp;instalaciones nucleares de Ir\u00e1n<\/strong>, incluida la planta subterr\u00e1nea de enriquecimiento de&nbsp;<strong>uranio de Fordo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su comparecencia,&nbsp;<strong>Trump&nbsp;<\/strong>expres\u00f3 que \u00abhabr\u00e1 paz o tragedia para Ir\u00e1n\u00bb tras el ataque estadounidense contra instalaciones nucleares en suelo iran\u00ed, por lo que llam\u00f3 a&nbsp;<strong>Teher\u00e1n&nbsp;<\/strong>a optar por la paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHabr\u00e1 paz o una&nbsp;<strong>tragedia&nbsp;<\/strong>para&nbsp;<strong>Ir\u00e1n&nbsp;<\/strong>mucho mayor que la que hemos presenciado en los \u00faltimos ocho d\u00edas. Recuerden, a\u00fan quedan muchos objetivos por alcanzar\u00bb, a\u00f1adi\u00f3 el presidente estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estados Unidos<\/strong>&nbsp;emple\u00f3 \u00abentre cinco y seis bombas&nbsp;<strong>antib\u00fanker<\/strong>\u00ab, lanzadas desde bombarderos B-2, adem\u00e1s de una treintena de<strong>&nbsp;misiles Tomahawk<\/strong>&nbsp;lanzados desde submarinos y destructores en el ataque contra tres instalaciones nucleares en Ir\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHemos completado nuestro ataque muy exitoso contra las tres instalaciones nucleares de Ir\u00e1n, incluidas&nbsp;<strong>Fordo<\/strong>,&nbsp;<strong>Natanz&nbsp;<\/strong>e&nbsp;<strong>Isfah\u00e1n<\/strong>\u00ab, declar\u00f3 Trump en su red Truth Social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSe lanz\u00f3 una carga completa de BOMBAS sobre la instalaci\u00f3n principal, Fordo\u00bb, a\u00f1adi\u00f3 el magnate republicano, al precisar que los aviones salieron sin da\u00f1os del&nbsp;<strong>espacio a\u00e9reo de Ir\u00e1n<\/strong>, que desde hace 10 d\u00edas enfrenta una&nbsp;<strong>guerra&nbsp;<\/strong>contra&nbsp;<strong>Israel<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump a\u00f1adi\u00f3 que \u00abtodos los aviones est\u00e1n de regreso\u00bb. \u00a1Felicitaciones a nuestros grandes guerreros estadounidenses!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">NETANYAHU FELICITA A TRUMP<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>primer ministro de Israel, Benjam\u00edn Netanyahu,<\/strong>&nbsp;felicit\u00f3 este s\u00e1bado al presidente de EE.UU., por su \u00abaudaz decisi\u00f3n\u00bb de bombardear tres instalaciones nucleares en Ir\u00e1n y agreg\u00f3: \u00abel&nbsp;<strong>presidente Trump<\/strong>&nbsp;y yo solemos decir: &#8216;La paz se logra con la fuerza'\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un video publicado en su cuenta de X, el l\u00edder israel\u00ed escribi\u00f3 que \u00abprimero viene la fuerza, luego la paz (&#8230;) Y esta noche, @realDonaldTrump y Estados Unidos actuaron con mucha fuerza\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo,&nbsp;<strong>congresistas republicanos&nbsp;<\/strong>y<strong>&nbsp;dem\u00f3cratas&nbsp;<\/strong>condenaron el<strong>&nbsp;ataque estadounidense<\/strong>&nbsp;contra tres instalaciones nucleares en&nbsp;<strong>Ir\u00e1n<\/strong>, al denunciar que la decisi\u00f3n era inconstitucional y deb\u00eda haber pasado por el Congreso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEsto no es constitucional\u00bb, escribi\u00f3 en redes sociales el congresista por el&nbsp;<strong>Partido Republicano Thomas Massie,<\/strong>&nbsp;al citar el mensaje en el que Trump anunci\u00f3 el ataque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dem\u00f3crata Jim Himes record\u00f3 que los congresistas como \u00e9l deben tener voz en este tipo de asuntos \u00abantes de que caigan las bombas\u00bb, algo que tambi\u00e9n asever\u00f3 su compa\u00f1era de partido Alexandria Ocasio-Cortez, al asegurar que \u00abla desastrosa decisi\u00f3n del Presidente de bombardear Ir\u00e1n sin autorizaci\u00f3n es una grave violaci\u00f3n de la Constituci\u00f3n y de los poderes de<strong>&nbsp;guerra del Congreso<\/strong>\u00ab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sean Casten, tambi\u00e9n representante del Partido Dem\u00f3crata, dijo que al margen \u00abde los m\u00e9ritos del&nbsp;<strong>programa nuclear iran\u00ed<\/strong>\u00ab, ni Trump ni otro presidente estadounidense tiene autoridad \u00abpara bombardear otro pa\u00eds que no represente una amenaza inminente para Estados Unidos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEsto constituye un delito inequ\u00edvoco que justifica un juicio pol\u00edtico\u00bb, advirti\u00f3 Casten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la legislaci\u00f3n estadounidense, es el&nbsp;<strong>Congreso<\/strong>&nbsp;quien tiene el poder para declarar la guerra a un pa\u00eds, con lo que equiparan el ataque contras las instalaciones iran\u00edes como un acto de guerra contra Ir\u00e1n, que hace una semana fue atacado directamente por Israel y desde entonces ambos pa\u00edses han intercambiado ataques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que Trump dej\u00f3 abierta la puerta a entrar en el conflicto entre Israel e Ir\u00e1n, los republicanos se han mostrado divididos sobre si Estados Unidos deb\u00eda intervenir y arriesgar a verse arrastrado a otro conflicto en Oriente Medio, algo que no hace tanto el presidente descartaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien Massie se mostraba contrario al bombardeo, el senador republicano por el estado de Texas, John Cornyn, asegur\u00f3 que el ataque hab\u00eda sido \u00abla decisi\u00f3n correcta\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;presidente de Estados Unidos, Donald Trump,&nbsp;avis\u00f3 a&nbsp;Ir\u00e1n&nbsp;que \u00absi la paz no llegar pronto\u00bb, tras el ataque estadounidense a sus principales instalaciones del&nbsp;programa nuclear, \u00abiremos por esos otros objetivos, con precisi\u00f3n, velocidad y destreza\u00bb. Estas&nbsp;declaraciones de Trump&nbsp;se produjeron durante un discurso en la&nbsp;Casa Blanca&nbsp;luego de que aeronaves del ej\u00e9rcito estadounidense llev\u00f3 a cabo un \u00abataque muy exitoso\u00bb contra tres&nbsp;instalaciones nucleares de Ir\u00e1n, incluida la planta subterr\u00e1nea de enriquecimiento de&nbsp;uranio de Fordo. Durante su comparecencia,&nbsp;Trump&nbsp;expres\u00f3 que \u00abhabr\u00e1 paz o tragedia para Ir\u00e1n\u00bb tras el ataque estadounidense contra instalaciones nucleares en suelo iran\u00ed, por lo que llam\u00f3 a&nbsp;Teher\u00e1n&nbsp;a optar por la paz. \u00abHabr\u00e1 paz o una&nbsp;tragedia&nbsp;para&nbsp;Ir\u00e1n&nbsp;mucho mayor que la que hemos presenciado en los \u00faltimos ocho d\u00edas. Recuerden, a\u00fan quedan muchos objetivos por alcanzar\u00bb, a\u00f1adi\u00f3 el presidente estadounidense. Estados Unidos&nbsp;emple\u00f3 \u00abentre cinco y seis bombas&nbsp;antib\u00fanker\u00ab, lanzadas desde bombarderos B-2, adem\u00e1s de una treintena de&nbsp;misiles Tomahawk&nbsp;lanzados desde submarinos y destructores en el ataque contra tres instalaciones nucleares en Ir\u00e1n. \u00abHemos completado nuestro ataque muy exitoso contra las tres instalaciones nucleares de Ir\u00e1n, incluidas&nbsp;Fordo,&nbsp;Natanz&nbsp;e&nbsp;Isfah\u00e1n\u00ab, declar\u00f3 Trump en su red Truth Social. \u00abSe lanz\u00f3 una carga completa de BOMBAS sobre la instalaci\u00f3n principal, Fordo\u00bb, a\u00f1adi\u00f3 el magnate republicano, al precisar que los aviones salieron sin da\u00f1os del&nbsp;espacio a\u00e9reo de Ir\u00e1n, que desde hace 10 d\u00edas enfrenta una&nbsp;guerra&nbsp;contra&nbsp;Israel. Trump a\u00f1adi\u00f3 que \u00abtodos los aviones est\u00e1n de regreso\u00bb. \u00a1Felicitaciones a nuestros grandes guerreros estadounidenses! NETANYAHU FELICITA A TRUMP El&nbsp;primer ministro de Israel, Benjam\u00edn Netanyahu,&nbsp;felicit\u00f3 este s\u00e1bado al presidente de EE.UU., por su \u00abaudaz decisi\u00f3n\u00bb de bombardear tres instalaciones nucleares en Ir\u00e1n y agreg\u00f3: \u00abel&nbsp;presidente Trump&nbsp;y yo solemos decir: &#8216;La paz se logra con la fuerza&#8217;\u00bb. En un video publicado en su cuenta de X, el l\u00edder israel\u00ed escribi\u00f3 que \u00abprimero viene la fuerza, luego la paz (&#8230;) Y esta noche, @realDonaldTrump y Estados Unidos actuaron con mucha fuerza\u00bb. Sin embargo,&nbsp;congresistas republicanos&nbsp;y&nbsp;dem\u00f3cratas&nbsp;condenaron el&nbsp;ataque estadounidense&nbsp;contra tres instalaciones nucleares en&nbsp;Ir\u00e1n, al denunciar que la decisi\u00f3n era inconstitucional y deb\u00eda haber pasado por el Congreso. \u00abEsto no es constitucional\u00bb, escribi\u00f3 en redes sociales el congresista por el&nbsp;Partido Republicano Thomas Massie,&nbsp;al citar el mensaje en el que Trump anunci\u00f3 el ataque. El dem\u00f3crata Jim Himes record\u00f3 que los congresistas como \u00e9l deben tener voz en este tipo de asuntos \u00abantes de que caigan las bombas\u00bb, algo que tambi\u00e9n asever\u00f3 su compa\u00f1era de partido Alexandria Ocasio-Cortez, al asegurar que \u00abla desastrosa decisi\u00f3n del Presidente de bombardear Ir\u00e1n sin autorizaci\u00f3n es una grave violaci\u00f3n de la Constituci\u00f3n y de los poderes de&nbsp;guerra del Congreso\u00ab. Sean Casten, tambi\u00e9n representante del Partido Dem\u00f3crata, dijo que al margen \u00abde los m\u00e9ritos del&nbsp;programa nuclear iran\u00ed\u00ab, ni Trump ni otro presidente estadounidense tiene autoridad \u00abpara bombardear otro pa\u00eds que no represente una amenaza inminente para Estados Unidos\u00bb. \u00abEsto constituye un delito inequ\u00edvoco que justifica un juicio pol\u00edtico\u00bb, advirti\u00f3 Casten. Seg\u00fan la legislaci\u00f3n estadounidense, es el&nbsp;Congreso&nbsp;quien tiene el poder para declarar la guerra a un pa\u00eds, con lo que equiparan el ataque contras las instalaciones iran\u00edes como un acto de guerra contra Ir\u00e1n, que hace una semana fue atacado directamente por Israel y desde entonces ambos pa\u00edses han intercambiado ataques. Desde que Trump dej\u00f3 abierta la puerta a entrar en el conflicto entre Israel e Ir\u00e1n, los republicanos se han mostrado divididos sobre si Estados Unidos deb\u00eda intervenir y arriesgar a verse arrastrado a otro conflicto en Oriente Medio, algo que no hace tanto el presidente descartaba. Si bien Massie se mostraba contrario al bombardeo, el senador republicano por el estado de Texas, John Cornyn, asegur\u00f3 que el ataque hab\u00eda sido \u00abla decisi\u00f3n correcta\u00bb.<\/p>\n","protected":false},"author":9,"featured_media":106099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-106098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=106098"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106098\/revisions"}],"predecessor-version":[{"id":106100,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106098\/revisions\/106100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/106099"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=106098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=106098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=106098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}