{"id":106150,"date":"2025-06-26T06:56:02","date_gmt":"2025-06-26T10:56:02","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=106150"},"modified":"2025-06-26T06:56:04","modified_gmt":"2025-06-26T10:56:04","slug":"analfabetismo-baja-en-rd-pero-persisten-brechas-dice-estudio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/analfabetismo-baja-en-rd-pero-persisten-brechas-dice-estudio\/","title":{"rendered":"Analfabetismo baja en RD; pero persisten brechas, dice estudio"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/06\/analfabetimso-300x200-1.jpg\" alt=\"\" class=\"wp-image-106151\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 25 jun (EFE).- El analfabetismo desciende en Rep\u00fablica Dominicana y su tasa se aproxima a los niveles previos a la pandemia, pero persisten las brechas en zonas rurales y entre grupos vulnerables, seg\u00fan un estudio del Instituto Dominicano de Evaluaci\u00f3n e Investigaci\u00f3n de la Calidad Educativa (Ideice) conocido este mi\u00e9rcoles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien la tasa de analfabetismo baj\u00f3 en 2024 al 6 % desde el 6,8 % de 2021, conforme a datos de la Encuesta Nacional de Hogares de Prop\u00f3sitos M\u00faltiples (Enhogar-2024), y se redujo al 5,6 desde el 6,3 por ciento en ese per\u00edodo de acuerdo con la Encuesta Nacional Continua de Fuerza de Trabajo (ENCFT), el informe alerta de que siguen registr\u00e1ndose \u00abbrechas significativas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>HOGARES DE MENORES INGRESOS M\u00c1S PROPENSO A NO LEER NI ESCRIBIR<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQuienes viven en zonas rurales, las personas mayores y los hogares de menores ingresos tienen m\u00e1s probabilidades de no saber leer ni escribir. Igualmente, las regiones del suroeste y el Cibao Nordeste presentan mayores tasas de analfabetismo en comparaci\u00f3n con la zona metropolitana\u00bb, indican datos preliminares del documento \u2018An\u00e1lisis integral del analfabetismo en la Rep\u00fablica Dominicana 2016-2024\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a diferencias por sexos, el escal\u00f3n entre hombres y mujeres tiende a reducirse cuando se consideran simult\u00e1neamente la edad, el lugar de residencia y el nivel socioecon\u00f3mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hombres, indica el estudio presentado por el Ideice (instituci\u00f3n p\u00fablica de car\u00e1cter t\u00e9cnico), tuvieron mayores tasas de analfabetismo en todos los a\u00f1os analizados, unos niveles que se redujeron en 2024 al 6,4 % frente al 8,3 % de 2016.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TASA DE MUJERES ILETRADAS BAJ\u00d3 DEL 7,2 AL 5,6 %<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese mismo per\u00edodo la tasa de mujeres iletradas baj\u00f3 del 7,2 al 5,6 %, una disminuci\u00f3n superior al 22 %.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por zonas geogr\u00e1ficas, en la poblaci\u00f3n de 15 a\u00f1os o m\u00e1s el \u00edndice de analfabetos en zonas urbanas pas\u00f3 del 6 al 4,7 % en 2024 (-21,7 %).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En \u00e1reas rurales, aunque la tasa en 2016 fue del 12,8 % y dos a\u00f1os despu\u00e9s decreci\u00f3 significativamente hasta el 2,1 % en 2018, en 2021 volvi\u00f3 a incrementarse hasta el 13,6 % para en 2024 situarse en el 13,2 %.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos datos, seg\u00fan el estudio, invitan a profundizar las estrategias diferenciadas, reforzar los programas en zonas rurales y adaptar las pol\u00edticas educativas a las realidades de g\u00e9nero y contexto territorial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">an\/am<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 25 jun (EFE).- El analfabetismo desciende en Rep\u00fablica Dominicana y su tasa se aproxima a los niveles previos a la pandemia, pero persisten las brechas en zonas rurales y entre grupos vulnerables, seg\u00fan un estudio del Instituto Dominicano de Evaluaci\u00f3n e Investigaci\u00f3n de la Calidad Educativa (Ideice) conocido este mi\u00e9rcoles. Si bien la tasa de analfabetismo baj\u00f3 en 2024 al 6 % desde el 6,8 % de 2021, conforme a datos de la Encuesta Nacional de Hogares de Prop\u00f3sitos M\u00faltiples (Enhogar-2024), y se redujo al 5,6 desde el 6,3 por ciento en ese per\u00edodo de acuerdo con la Encuesta Nacional Continua de Fuerza de Trabajo (ENCFT), el informe alerta de que siguen registr\u00e1ndose \u00abbrechas significativas\u00bb. HOGARES DE MENORES INGRESOS M\u00c1S PROPENSO A NO LEER NI ESCRIBIR \u00abQuienes viven en zonas rurales, las personas mayores y los hogares de menores ingresos tienen m\u00e1s probabilidades de no saber leer ni escribir. Igualmente, las regiones del suroeste y el Cibao Nordeste presentan mayores tasas de analfabetismo en comparaci\u00f3n con la zona metropolitana\u00bb, indican datos preliminares del documento \u2018An\u00e1lisis integral del analfabetismo en la Rep\u00fablica Dominicana 2016-2024\u2019. En cuanto a diferencias por sexos, el escal\u00f3n entre hombres y mujeres tiende a reducirse cuando se consideran simult\u00e1neamente la edad, el lugar de residencia y el nivel socioecon\u00f3mico. Los hombres, indica el estudio presentado por el Ideice (instituci\u00f3n p\u00fablica de car\u00e1cter t\u00e9cnico), tuvieron mayores tasas de analfabetismo en todos los a\u00f1os analizados, unos niveles que se redujeron en 2024 al 6,4 % frente al 8,3 % de 2016. TASA DE MUJERES ILETRADAS BAJ\u00d3 DEL 7,2 AL 5,6 % En ese mismo per\u00edodo la tasa de mujeres iletradas baj\u00f3 del 7,2 al 5,6 %, una disminuci\u00f3n superior al 22 %. Por zonas geogr\u00e1ficas, en la poblaci\u00f3n de 15 a\u00f1os o m\u00e1s el \u00edndice de analfabetos en zonas urbanas pas\u00f3 del 6 al 4,7 % en 2024 (-21,7 %). En \u00e1reas rurales, aunque la tasa en 2016 fue del 12,8 % y dos a\u00f1os despu\u00e9s decreci\u00f3 significativamente hasta el 2,1 % en 2018, en 2021 volvi\u00f3 a incrementarse hasta el 13,6 % para en 2024 situarse en el 13,2 %. Estos datos, seg\u00fan el estudio, invitan a profundizar las estrategias diferenciadas, reforzar los programas en zonas rurales y adaptar las pol\u00edticas educativas a las realidades de g\u00e9nero y contexto territorial. an\/am<\/p>\n","protected":false},"author":9,"featured_media":106151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-106150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=106150"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106150\/revisions"}],"predecessor-version":[{"id":106152,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/106150\/revisions\/106152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/106151"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=106150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=106150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=106150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}