{"id":10620,"date":"2014-11-15T22:50:00","date_gmt":"2014-11-16T02:50:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10620"},"modified":"2014-11-15T22:50:00","modified_gmt":"2014-11-16T02:50:00","slug":"cuidado-ingerir-licor-esta-contraindicado-con-el-chikungunya","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cuidado-ingerir-licor-esta-contraindicado-con-el-chikungunya\/","title":{"rendered":"\u00a1Cuidado! Ingerir licor est\u00e1 contraindicado con el chikungunya"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/cuidado-si-tienes-chukungunya.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10621 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/cuidado-si-tienes-chukungunya.jpg\" alt=\"cuidado si tienes chukungunya\" width=\"600\" height=\"450\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/cuidado-si-tienes-chukungunya.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/cuidado-si-tienes-chukungunya-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\n<\/a>\u00bfSe puede o no se puede ingerir <label>licor<\/label> con el chikungunya o despu\u00e9s que pase el virus? Sobre esta interrogante se han tejido muchas respuestas; sin embargo, los especialistas m\u00e9dicos aseguran que est\u00e1 contraindicado desde <label>todo<\/label> <label>punto<\/label> de vista tomar <label>bebidas<\/label> alcoh\u00f3licas mientras se tenga la fiebre Chikv.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>El director regional de <label>salud<\/label> Ambiental, Heraclio Moreno, explic\u00f3: \u201cEl licor est\u00e1 contraindicado con la enfermedad, y a\u00fan despu\u00e9s que se pasan los s\u00edntomas pueden quedar alteradas las c\u00e9lulas hep\u00e1ticas. Cuando decimos que el cuerpo ha cedido, es cuando las transaminasas se encuentran en niveles normales, hasta tanto no regresen a sus valores estables no decimos que la persona esta completamente sana, porque el h\u00edgado se mantiene inflamado\u201d.<\/p>\n<p>Seg\u00fan explican los especialistas, los pacientes deben esperar una semana despu\u00e9s que desaparecen los s\u00edntomas para hacerse ex\u00e1menes de sangre y verificar que los valores de las transaminasas est\u00e1n normales. El examen a realizarse es para transaminasas pir\u00favica y oxalac\u00e9tica.<\/p>\n<p>Moreno se\u00f1al\u00f3 que aquellos pacientes que ingieren bebidas alcoh\u00f3licas con el chikungunya se les prolonga su proceso de recuperaci\u00f3n.<\/p>\n<p>\u201cSi existen enfermedades de base como cirrosis, hepatitis, diabetes, hipertensi\u00f3n arterial el paciente pueden llevar agravar el cuadro\u201d, precis\u00f3.<\/p>\n<p>\u201cEl virus produce inflamaci\u00f3n de las c\u00e9dulas hep\u00e1ticas y por eso se indica tomar mucho l\u00edquido, incluso, hay especialistas que colocan complejo B para que ayude a recuperar la funcionabilidad del h\u00edgado. Desde el punto de vista cl\u00ednico puede estar mejor, pero solo el examen de laboratorio dar\u00e1 la corroboraci\u00f3n que el \u00f3rgano est\u00e1 bien\u201d, indic\u00f3 el director de salud ambiental.<\/p>\n<p>Los doctores est\u00e1n recomendando comer alimentos libres en grasa, cereales, vegetales, frutas. Y llaman a los pacientes a sustituir las grasas de origen animal por las vegetales como los aceites extra\u00eddos por presi\u00f3n extra virgen.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/panorama.com.ve\/portal\/app\/push\/noticia133326.php\">Panorama<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSe puede o no se puede ingerir licor con el chikungunya o despu\u00e9s que pase el virus? Sobre esta interrogante se han tejido muchas respuestas; sin embargo, los especialistas m\u00e9dicos aseguran que est\u00e1 contraindicado desde todo punto de vista tomar bebidas alcoh\u00f3licas mientras se tenga la fiebre Chikv.<\/p>\n","protected":false},"author":3,"featured_media":10621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10620"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10620\/revisions"}],"predecessor-version":[{"id":10622,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10620\/revisions\/10622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10621"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}