{"id":107240,"date":"2025-08-31T08:13:18","date_gmt":"2025-08-31T12:13:18","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=107240"},"modified":"2025-08-31T08:13:19","modified_gmt":"2025-08-31T12:13:19","slug":"actor-argentino-benjamin-alfonso-revela-que-sufrio-acoso-durante-la-grabacion-de-valeria","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/actor-argentino-benjamin-alfonso-revela-que-sufrio-acoso-durante-la-grabacion-de-valeria\/","title":{"rendered":"Actor argentino Benjam\u00edn Alfonso revela que sufri\u00f3 acoso durante la grabaci\u00f3n de \u00abValeria\u00bb"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"466\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/08\/68b32ce285e50.jpeg\" alt=\"\" class=\"wp-image-107241\" style=\"width:268px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/08\/68b32ce285e50.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/08\/68b32ce285e50-300x175.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/08\/68b32ce285e50-768x447.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjam\u00edn Alfonso<\/strong>\u00a0cont\u00f3 el pasado domingo en el\u00a0<strong>Almorzando con Juana Viale<\/strong>\u00a0(eltrece) una de las situaciones m\u00e1s complejas de su carrera como actor, cuando, durante el rodaje de la\u00a0<strong>serie de Netflix, Valeria<\/strong>\u00a0-que tuvo lugar en Espa\u00f1a-, sufri\u00f3 acoso por parte del elenco y despu\u00e9s de nueve meses de trabajo, lo echaron por no tener \u201cpiel\u201d con una de las actrices. Luego de varios a\u00f1os se anim\u00f3 a relatar el\u00a0<strong>calvario que experiment\u00f3\u00a0<\/strong>durante su paso por el pa\u00eds europeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo empez\u00f3 cuando&nbsp;<strong>Juana Viale<\/strong>&nbsp;lo introdujo a hablar sobre su situaci\u00f3n laboral en el exterior, lo que decant\u00f3 de inmediato en el suceso que vivi\u00f3 antes de la pandemia. Con verg\u00fcenza, pero a\u00fan decidido, dio detalles de lo que pas\u00f3 detr\u00e1s de c\u00e1maras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFue b\u00e1sicamente acoso en mi contra, lamentablemente.<strong>&nbsp;Fue muy fuerte. Fue horrible.&nbsp;<\/strong>Me contrataron para hacer una serie. Era uno de los primeros equipos de trabajo en el cual eran todas mujeres, un<strong>&nbsp;equipo ultra feminista<\/strong>\u201d, inici\u00f3 Alfonso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el rodaje empezaron a pasar un mont\u00f3n de cosas.&nbsp;<strong>Grabo la serie entera<\/strong>, echan a la directora en la mitad, empiezan a echar a un mont\u00f3n de gente y las chicas estaban desesperadas y yo les daba tranquilidad. Yo, un argentino, reci\u00e9n llegado a Espa\u00f1a, dec\u00eda: \u2018Chicas, tranquilas, van a ver que va a andar todo bien. Ustedes tienen que confiar lo que est\u00e1n haciendo bien\u2019, que esto y que lo otro. A todo esto, yo no pod\u00eda decir nada. Ten\u00edamos un contrato de exclusividad y de silencio\u201d, se\u00f1al\u00f3 el actor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego entr\u00f3 en detalle sobre algunas escenas de sexo con una de las&nbsp;<strong>protagonistas<\/strong>, que lo describi\u00f3 como \u201cmuy fuerte\u201d, lo que le gener\u00f3 una&nbsp;<strong>incomodidad posterior<\/strong>. \u201cSe la cuida mucho a la mujer, pero al hombre no se lo cuida. Porque se da por sentado que el hombre tiene que bancar todo. Entonces recib\u00eda llamados a altas horas, estaba en pareja, no les importaba. Pero bueno, empezaron a pasar muchas cosas\u201d, lament\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfDespu\u00e9s de las escenas recib\u00edas llamados?\u201c, pregunt\u00f3 Juana Viale, a lo que \u00e9l respondi\u00f3: \u201dAntes, durante, despu\u00e9s. Y de gente de ah\u00ed adentro\u00bb. En ese instante reconoci\u00f3 que no quer\u00eda hablar dem\u00e1s porque podr\u00eda venir \u201cuna bola de cr\u00edticas\u201d con un sentido distorsionado de sus palabras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras aquello, el actor record\u00f3 el contexto en que lo&nbsp;<strong>echaron del proyecto<\/strong>. \u201cDespu\u00e9s de haber hecho todo esto y de que hayan autorizado escenas en las cuales yo no me enteraba de que ten\u00eda que besar o me ten\u00edan que hacer diferentes cosas, despu\u00e9s de haberme bancado todo,&nbsp;<strong>termino de grabar la serie<\/strong>&nbsp;&#8211;que fueron 9 meses de yo haber descartado un mont\u00f3n de proyectos en&nbsp;<strong>Argentina<\/strong>-, y me llaman y me dicen: \u2018No hay piel entre esta persona -por la cual yo estaba sufriendo acosos-, y vos\u2019. Resulta que la quisieron bajar a ella y ella dijo que el problema era yo y consigui\u00f3 convencer al resto de las directoras y me bajaron. Me dijeron: \u2018Mir\u00e1, Benjam\u00edn, vamos a rodar todo lo que hiciste de vuelta con otro actor [<strong>Maximiliano Iglesias<\/strong>]\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Benjam\u00edn Alfonso se trat\u00f3 de una reacci\u00f3n personal que tuvo la actriz para con \u00e9l, en medio del acoso que recibi\u00f3. Es por ello que manifest\u00f3 que luego de perder su trabajo, empez\u00f3 a desconfiar de su talento. Se separ\u00f3 de su entonces pareja y el amigo que lo intent\u00f3 ayudar a salir adelante, muri\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComenc\u00e9 a tapar emociones que se me empezaron a imprimir en el cuerpo.&nbsp;<strong>Dej\u00e9 de procesar la comida, el mate, baj\u00e9 13 kg.&nbsp;<\/strong>En el medio me agarr\u00f3 la pandemia en Espa\u00f1a, gastando todo lo que hab\u00eda ganado en euros. Perd\u00ed seguridad en m\u00ed mismo, alej\u00e9 a mi pareja, a mis amigos, me empec\u00e9 a quedar solo pr\u00e1cticamente\u201d, mencion\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al finalizar el tema, con una sonrisa, reconoci\u00f3: \u201cSon cosas que reci\u00e9n ahora las puedo contar. El mi\u00e9rcoles tuve una muy buena clase de teatro, que le mando un beso grande a Santi y mi profe y maestro amigo. Y ah\u00ed saqu\u00e9 mucho de todo esto, por eso ahora tambi\u00e9n lo puedo contar tanto\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Benjam\u00edn Alfonso\u00a0cont\u00f3 el pasado domingo en el\u00a0Almorzando con Juana Viale\u00a0(eltrece) una de las situaciones m\u00e1s complejas de su carrera como actor, cuando, durante el rodaje de la\u00a0serie de Netflix, Valeria\u00a0-que tuvo lugar en Espa\u00f1a-, sufri\u00f3 acoso por parte del elenco y despu\u00e9s de nueve meses de trabajo, lo echaron por no tener \u201cpiel\u201d con una de las actrices. Luego de varios a\u00f1os se anim\u00f3 a relatar el\u00a0calvario que experiment\u00f3\u00a0durante su paso por el pa\u00eds europeo. Todo empez\u00f3 cuando&nbsp;Juana Viale&nbsp;lo introdujo a hablar sobre su situaci\u00f3n laboral en el exterior, lo que decant\u00f3 de inmediato en el suceso que vivi\u00f3 antes de la pandemia. Con verg\u00fcenza, pero a\u00fan decidido, dio detalles de lo que pas\u00f3 detr\u00e1s de c\u00e1maras. \u201cFue b\u00e1sicamente acoso en mi contra, lamentablemente.&nbsp;Fue muy fuerte. Fue horrible.&nbsp;Me contrataron para hacer una serie. Era uno de los primeros equipos de trabajo en el cual eran todas mujeres, un&nbsp;equipo ultra feminista\u201d, inici\u00f3 Alfonso. Durante el rodaje empezaron a pasar un mont\u00f3n de cosas.&nbsp;Grabo la serie entera, echan a la directora en la mitad, empiezan a echar a un mont\u00f3n de gente y las chicas estaban desesperadas y yo les daba tranquilidad. Yo, un argentino, reci\u00e9n llegado a Espa\u00f1a, dec\u00eda: \u2018Chicas, tranquilas, van a ver que va a andar todo bien. Ustedes tienen que confiar lo que est\u00e1n haciendo bien\u2019, que esto y que lo otro. A todo esto, yo no pod\u00eda decir nada. Ten\u00edamos un contrato de exclusividad y de silencio\u201d, se\u00f1al\u00f3 el actor. Luego entr\u00f3 en detalle sobre algunas escenas de sexo con una de las&nbsp;protagonistas, que lo describi\u00f3 como \u201cmuy fuerte\u201d, lo que le gener\u00f3 una&nbsp;incomodidad posterior. \u201cSe la cuida mucho a la mujer, pero al hombre no se lo cuida. Porque se da por sentado que el hombre tiene que bancar todo. Entonces recib\u00eda llamados a altas horas, estaba en pareja, no les importaba. Pero bueno, empezaron a pasar muchas cosas\u201d, lament\u00f3. \u201c\u00bfDespu\u00e9s de las escenas recib\u00edas llamados?\u201c, pregunt\u00f3 Juana Viale, a lo que \u00e9l respondi\u00f3: \u201dAntes, durante, despu\u00e9s. Y de gente de ah\u00ed adentro\u00bb. En ese instante reconoci\u00f3 que no quer\u00eda hablar dem\u00e1s porque podr\u00eda venir \u201cuna bola de cr\u00edticas\u201d con un sentido distorsionado de sus palabras. Tras aquello, el actor record\u00f3 el contexto en que lo&nbsp;echaron del proyecto. \u201cDespu\u00e9s de haber hecho todo esto y de que hayan autorizado escenas en las cuales yo no me enteraba de que ten\u00eda que besar o me ten\u00edan que hacer diferentes cosas, despu\u00e9s de haberme bancado todo,&nbsp;termino de grabar la serie&nbsp;&#8211;que fueron 9 meses de yo haber descartado un mont\u00f3n de proyectos en&nbsp;Argentina-, y me llaman y me dicen: \u2018No hay piel entre esta persona -por la cual yo estaba sufriendo acosos-, y vos\u2019. Resulta que la quisieron bajar a ella y ella dijo que el problema era yo y consigui\u00f3 convencer al resto de las directoras y me bajaron. Me dijeron: \u2018Mir\u00e1, Benjam\u00edn, vamos a rodar todo lo que hiciste de vuelta con otro actor [Maximiliano Iglesias]\u00bb. Para Benjam\u00edn Alfonso se trat\u00f3 de una reacci\u00f3n personal que tuvo la actriz para con \u00e9l, en medio del acoso que recibi\u00f3. Es por ello que manifest\u00f3 que luego de perder su trabajo, empez\u00f3 a desconfiar de su talento. Se separ\u00f3 de su entonces pareja y el amigo que lo intent\u00f3 ayudar a salir adelante, muri\u00f3. \u201cComenc\u00e9 a tapar emociones que se me empezaron a imprimir en el cuerpo.&nbsp;Dej\u00e9 de procesar la comida, el mate, baj\u00e9 13 kg.&nbsp;En el medio me agarr\u00f3 la pandemia en Espa\u00f1a, gastando todo lo que hab\u00eda ganado en euros. Perd\u00ed seguridad en m\u00ed mismo, alej\u00e9 a mi pareja, a mis amigos, me empec\u00e9 a quedar solo pr\u00e1cticamente\u201d, mencion\u00f3. Al finalizar el tema, con una sonrisa, reconoci\u00f3: \u201cSon cosas que reci\u00e9n ahora las puedo contar. El mi\u00e9rcoles tuve una muy buena clase de teatro, que le mando un beso grande a Santi y mi profe y maestro amigo. Y ah\u00ed saqu\u00e9 mucho de todo esto, por eso ahora tambi\u00e9n lo puedo contar tanto\u201d.<\/p>\n","protected":false},"author":9,"featured_media":107241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-107240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=107240"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107240\/revisions"}],"predecessor-version":[{"id":107242,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107240\/revisions\/107242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/107241"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=107240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=107240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=107240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}