{"id":107527,"date":"2025-09-12T15:38:35","date_gmt":"2025-09-12T19:38:35","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=107527"},"modified":"2025-09-12T15:39:56","modified_gmt":"2025-09-12T19:39:56","slug":"tribunal-dicta-prision-preventiva-contra-implicados-en-violacion-grupal-en-villa-gonzalez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tribunal-dicta-prision-preventiva-contra-implicados-en-violacion-grupal-en-villa-gonzalez\/","title":{"rendered":"Tribunal dicta prisi\u00f3n preventiva contra implicados en violaci\u00f3n grupal en Villa Gonz\u00e1lez"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"465\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/09\/preso.jpeg\" alt=\"\" class=\"wp-image-107528\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/09\/preso.jpeg 950w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/09\/preso-300x147.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/09\/preso-768x376.jpeg 768w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Tribunal de Atenci\u00f3n Permanente de Santiago impuso hoy tres meses de prisi\u00f3n preventiva, como medida de coerci\u00f3n, a seis implicados en el de abuso grupal a una joven de 21 a\u00f1os, en el municipio de Villa Gonz\u00e1lez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jueza Yaritza Cabral envi\u00f3 a prisi\u00f3n a Jos\u00e9 Alfonso Rubiera Rodr\u00edguez (Fonso), Delfri de Jes\u00fas Rodr\u00edguez (Yiyo), Edwin Manuel Castro Guzm\u00e1n (el Guaro), Javier Eduardo N\u00fa\u00f1ez Toribio y\/o Javier N\u00fa\u00f1ez (Beb\u00e9), Oniel Rafael Pichardo Mart\u00ednez (Contreras) y Yamir Fernando P\u00e9rez Toribio (Ferrere).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los acusados deber\u00e1n cumplir la medida impuesta en un Centro Correccional de Mao, en la provincia Valverde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gladisleny N\u00fa\u00f1ez, directora de la unidad de atenci\u00f3n integral a v\u00edctimas de violencia de g\u00e9nero, intrafamiliar y delitos sexuales de la fiscal\u00eda de Santiago solicit\u00f3 la prisi\u00f3n preventiva como medida de coerci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/listindiario.com\/la-republica\/20250912\/tribunal-dicta-prision-preventiva-implicados-violacion-grupal-villa-gonzalez_874066.html\">FUENTE<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#sosua #sosuaonline.net #acusadosviolacion<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tribunal de Atenci\u00f3n Permanente de Santiago impuso hoy tres meses de prisi\u00f3n preventiva, como medida de coerci\u00f3n, a seis implicados en el de abuso grupal a una joven de 21 a\u00f1os, en el municipio de Villa Gonz\u00e1lez. La jueza Yaritza Cabral envi\u00f3 a prisi\u00f3n a Jos\u00e9 Alfonso Rubiera Rodr\u00edguez (Fonso), Delfri de Jes\u00fas Rodr\u00edguez (Yiyo), Edwin Manuel Castro Guzm\u00e1n (el Guaro), Javier Eduardo N\u00fa\u00f1ez Toribio y\/o Javier N\u00fa\u00f1ez (Beb\u00e9), Oniel Rafael Pichardo Mart\u00ednez (Contreras) y Yamir Fernando P\u00e9rez Toribio (Ferrere). Los acusados deber\u00e1n cumplir la medida impuesta en un Centro Correccional de Mao, en la provincia Valverde. Gladisleny N\u00fa\u00f1ez, directora de la unidad de atenci\u00f3n integral a v\u00edctimas de violencia de g\u00e9nero, intrafamiliar y delitos sexuales de la fiscal\u00eda de Santiago solicit\u00f3 la prisi\u00f3n preventiva como medida de coerci\u00f3n. FUENTE #sosua #sosuaonline.net #acusadosviolacion<\/p>\n","protected":false},"author":12,"featured_media":107528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-107527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=107527"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107527\/revisions"}],"predecessor-version":[{"id":107532,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107527\/revisions\/107532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/107528"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=107527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=107527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=107527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}