{"id":107868,"date":"2025-09-26T10:35:39","date_gmt":"2025-09-26T14:35:39","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=107868"},"modified":"2025-09-26T10:36:36","modified_gmt":"2025-09-26T14:36:36","slug":"el-coe-declara-en-alerta-roja-al-gran-santo-domingo-y-otras-cuatro-provincias-por-onda-tropical","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-coe-declara-en-alerta-roja-al-gran-santo-domingo-y-otras-cuatro-provincias-por-onda-tropical\/","title":{"rendered":"El COE declara en alerta roja al Gran Santo Domingo y otras cuatro provincias por onda tropical"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"896\" height=\"504\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/09\/alertas-en-RD.jpg\" alt=\"\" class=\"wp-image-107869\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/09\/alertas-en-RD.jpg 896w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/09\/alertas-en-RD-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/09\/alertas-en-RD-768x432.jpg 768w\" sizes=\"auto, (max-width: 896px) 100vw, 896px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro de Operaciones de Emergencias (<strong>COE<\/strong>) declar\u00f3 este viernes en&nbsp;<strong>alerta roja<\/strong>&nbsp;al Gran Santo Domingo y a otras cuatro&nbsp;<strong>provincias<\/strong>&nbsp;debido a los&nbsp;<strong>fuertes aguaceros<\/strong>, tormentas el\u00e9ctricas y r\u00e1fagas de viento provocados por la combinaci\u00f3n de una onda tropical activa y una&nbsp;<strong>vaguada<\/strong>&nbsp;en altura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el bolet\u00edn emitido a las 8:00 de la ma\u00f1ana, las&nbsp;<strong>provincias<\/strong>&nbsp;en&nbsp;<strong>alerta roja<\/strong>&nbsp;son: Santo Domingo, Distrito Nacional, San Crist\u00f3bal, San Jos\u00e9 de Ocoa y Azua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El organismo advirti\u00f3 que en estas demarcaciones la situaci\u00f3n representa un&nbsp;<strong>riesgo inminente<\/strong>&nbsp;por las posibles&nbsp;<strong>crecidas de r\u00edos<\/strong>, arroyos y ca\u00f1adas, adem\u00e1s de&nbsp;<strong>inundaciones urbanas<\/strong>&nbsp;repentinas que podr\u00edan comprometer la&nbsp;<strong>seguridad<\/strong>&nbsp;de la poblaci\u00f3n y de infraestructuras p\u00fablicas y privadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, nueve&nbsp;<strong>provincias<\/strong>&nbsp;fueron colocadas en&nbsp;<strong>alerta amarilla<\/strong>: Mar\u00eda Trinidad S\u00e1nchez, San Pedro de Macor\u00eds, La Romana, El Seibo, Saman\u00e1, San Juan, Hato Mayor, Monte Plata y Peravia. Asimismo, permanecen en&nbsp;<strong>alerta verde<\/strong>&nbsp;Barahona, Pedernales, S\u00e1nchez Ram\u00edrez y Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#COE<br \/>#lluviaInuncaciones<br \/>#Sosuaaonline<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.diariolibre.com\/planeta\/clima\/2025\/09\/26\/el-gran-santo-domingo-y-otras-provincias-bajo-alerta-roja-por-lluvias\/3258227\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centro de Operaciones de Emergencias (COE) declar\u00f3 este viernes en&nbsp;alerta roja&nbsp;al Gran Santo Domingo y a otras cuatro&nbsp;provincias&nbsp;debido a los&nbsp;fuertes aguaceros, tormentas el\u00e9ctricas y r\u00e1fagas de viento provocados por la combinaci\u00f3n de una onda tropical activa y una&nbsp;vaguada&nbsp;en altura. De acuerdo con el bolet\u00edn emitido a las 8:00 de la ma\u00f1ana, las&nbsp;provincias&nbsp;en&nbsp;alerta roja&nbsp;son: Santo Domingo, Distrito Nacional, San Crist\u00f3bal, San Jos\u00e9 de Ocoa y Azua. El organismo advirti\u00f3 que en estas demarcaciones la situaci\u00f3n representa un&nbsp;riesgo inminente&nbsp;por las posibles&nbsp;crecidas de r\u00edos, arroyos y ca\u00f1adas, adem\u00e1s de&nbsp;inundaciones urbanas&nbsp;repentinas que podr\u00edan comprometer la&nbsp;seguridad&nbsp;de la poblaci\u00f3n y de infraestructuras p\u00fablicas y privadas. En tanto, nueve&nbsp;provincias&nbsp;fueron colocadas en&nbsp;alerta amarilla: Mar\u00eda Trinidad S\u00e1nchez, San Pedro de Macor\u00eds, La Romana, El Seibo, Saman\u00e1, San Juan, Hato Mayor, Monte Plata y Peravia. Asimismo, permanecen en&nbsp;alerta verde&nbsp;Barahona, Pedernales, S\u00e1nchez Ram\u00edrez y Puerto Plata. #COE#lluviaInuncaciones#Sosuaaonline FUENTE<\/p>\n","protected":false},"author":12,"featured_media":107869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-107868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=107868"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107868\/revisions"}],"predecessor-version":[{"id":107870,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/107868\/revisions\/107870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/107869"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=107868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=107868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=107868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}