{"id":10850,"date":"2014-11-21T11:32:45","date_gmt":"2014-11-21T15:32:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10850"},"modified":"2014-11-25T23:17:18","modified_gmt":"2014-11-26T03:17:18","slug":"un-grammy-latino-sin-romeo-con-luces-y-sombras","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-grammy-latino-sin-romeo-con-luces-y-sombras\/","title":{"rendered":"Un Grammy Latino sin Romeo con luces y sombras"},"content":{"rendered":"<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/grammy-latinos-2014.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-10925 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/grammy-latinos-2014.jpg\" alt=\"grammy latinos 2014\" width=\"393\" height=\"393\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/grammy-latinos-2014.jpg 480w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/grammy-latinos-2014-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/grammy-latinos-2014-300x300.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/grammy-latinos-2014-120x120.jpg 120w\" sizes=\"auto, (max-width: 393px) 100vw, 393px\" \/><\/a>Tras desfilar anoche por la alfombra verdedel Grammy Latino con su ahora esposa, la modelo Shannon de Lima, el cantante Marc Anthony no permiti\u00f3 que un presentador de Univisi\u00f3n lo entrevistara.<\/div>\n<p><!--more--><\/p>\n<div>\n<div>Sigui\u00f3 caminando y lleg\u00f3 a decir que \u00abha sido un a\u00f1o incre\u00edble\u00bb.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>Sin embargo, el animador no pudo ocultar su cara de asombro por el desplante y la prisa del puertorrique\u00f1o en medio de la transmisi\u00f3n en vivo.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>El d\u00fao entre Carlos Vives y Marc Anthony fue desastroso. Los cantantes se unieron en el tema \u00abCuando nos volvamos a encontrar\u00bb y el p\u00fablico no pod\u00eda creer lo que estaba escuchando.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>Parec\u00eda que no ensayaron, puesto que se escuchaban asfixiados, desafinados y hasta roncos.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>La m\u00fasica estaba demasiado alta y Vives, opacado por el registro de Marc, termin\u00f3 riendo de forma desesperada en medio de la presentaci\u00f3n. De inmediato, el desfile de burlas invadi\u00f3 las redes sociales mientras varios cibernautas consideraron que se trat\u00f3 de un d\u00fao de gatos en karaoke.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>A juicio de cibernautas, cosas que compartimos, el Grammy Latino se desarroll\u00f3 en el marco de un espect\u00e1culo que no super\u00f3 al pasado, pese a brillantes actuaciones de Ricky Martin, Pitbull y Camila.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>Lo nunca visto sucedi\u00f3 al cierre y fue la colocaci\u00f3n de un VTR con la actuaci\u00f3n de Enrique Iglesias y el grupo Gente de Zona en un concierto en Madrid, que se mezclaba con la irrupci\u00f3n de bailarinas en el escenario del Grammy Latino, en el Metro Goldwyn Mayer (MGM) Gran Garden Arena en Las Vegas.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>Si hacen eso en un premio como El Soberano, se comen vivo a los organizadores, pues se puede admitir que algunos artistas hagan playback mientras simulan cantar en eventos como este, pero de ah\u00ed a incluir un n\u00famero musical grabado, de verdad que se pasaron.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>El gui\u00f3n fue otro punto que no favoreci\u00f3 a la edici\u00f3n n\u00famero 15 del Grammy Latino, rutinas desabridas de los anfitriones de la gala no lograron provocar la gracia en la audiencia.<\/div>\n<div><\/div>\n<div>Es evidente que a la premiaci\u00f3n tanto en su show como en el rubro de nominados le hizo falta un Romeo Santos, el artista de mayor popularidad en estos momentos pero la academia ignor\u00f3 por segundo a\u00f1o sus propuestas discogr\u00e1ficas.<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div><b>Los triunfadores<\/b><\/div>\n<\/div>\n<div>\n<div>Le tom\u00f3 m\u00e1s de una d\u00e9cada volver a ganar pero lo hizo por partida triple: Enrique Iglesias arras\u00f3 el jueves en los Latin Grammy con tres premios que incluyeron canci\u00f3n del a\u00f1o por el mega\u00e9xito \u00abBailando\u00bb, mientras Calle 13 rompi\u00f3 el r\u00e9cord y se impuso como el artista m\u00e1s premiado en la historia de los galardones, con 21.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>Junto con los cubanos Descemer Bueno y Gente de Zona, Iglesias conquist\u00f3 tambi\u00e9n los rubros de mejor canci\u00f3n urbana y mejor interpretaci\u00f3n urbana, categor\u00edas en las que tambi\u00e9n se med\u00eda Calle 13.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>Pese a sus numerosos \u00e9xitos en la radio el superastro espa\u00f1ol, quien agradeci\u00f3 sus premios en un video transmitido en vivo desde Par\u00eds, s\u00f3lo hab\u00eda ganado un Latin Grammy en 2003, hace m\u00e1s de una d\u00e9cada.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>\u00abQu\u00e9 noche, ya dos Latin Grammys. Estoy aqu\u00ed en Par\u00eds esperando m\u00e1s noticia\u00bb, escribi\u00f3 en Twitter desde la capital francesa, donde se encontraba de gira, antes de enterarse del tercero, que agradeci\u00f3 en vivo v\u00eda sat\u00e9lite.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>Calle 13, que hist\u00f3ricamente ha arrasado en los Latin Grammy con cada uno de sus discos, se tuvo que conformar con dos de los nueve gram\u00f3fonos a los que aspiraba: mejor \u00e1lbum de m\u00fasica urbana por \u00abMultiViral\u00bb y mejor canci\u00f3n alternativa por \u00abEl aguante\u00bb.<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>Aun as\u00ed rompi\u00f3 la marca previa de 19 premios que compart\u00eda con Juanes.<\/div>\n<\/div>\n<div><\/div>\n<div><b><a href=\"http:\/\/www.latingrammy.com\/es\/nominees\/search\">Lista de ganadores<\/a><\/b><\/div>\n<div><\/div>\n<div>Fuente: Fuegoalalata.net<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tras desfilar anoche por la alfombra verdedel Grammy Latino con su ahora esposa, la modelo Shannon de Lima, el cantante Marc Anthony no permiti\u00f3 que un presentador de Univisi\u00f3n lo entrevistara.<\/p>\n","protected":false},"author":3,"featured_media":10925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10850"}],"version-history":[{"count":4,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10850\/revisions"}],"predecessor-version":[{"id":10927,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10850\/revisions\/10927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10925"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}