{"id":108611,"date":"2025-10-28T07:38:49","date_gmt":"2025-10-28T11:38:49","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=108611"},"modified":"2025-10-28T07:38:51","modified_gmt":"2025-10-28T11:38:51","slug":"presidente-dominicano-llama-a-rezar-por-jamaica-ante-huracan","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/presidente-dominicano-llama-a-rezar-por-jamaica-ante-huracan\/","title":{"rendered":"Presidente dominicano llama a rezar por Jamaica ante hurac\u00e1n"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"867\" height=\"552\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/10\/Abinader-2.jpg\" alt=\"\" class=\"wp-image-108612\" style=\"width:337px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/10\/Abinader-2.jpg 867w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/10\/Abinader-2-300x191.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/10\/Abinader-2-768x489.jpg 768w\" sizes=\"auto, (max-width: 867px) 100vw, 867px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 27 oct (EFE).- El presidente de la Rep\u00fablica Dominicana, Luis Abinader, llam\u00f3 este lunes a \u00abrezar por los jamaiquinos, por Cuba y Hait\u00ed\u00bb ante el paso del hurac\u00e1n Melissa, que se encuentra actualmente a unos 200 kil\u00f3metros al suroeste de Jamaica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHay que rezar por los jamaiquinos, por esa rep\u00fablica hermana, y tambi\u00e9n por Cuba que va a ser afectada en la zona este, y tambi\u00e9n por Hait\u00ed que puede ser afectada. Que Dios los ayude y que est\u00e9n en las oraciones de todos los dominicanos\u00bb, se\u00f1al\u00f3 Abinader.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el Centro Nacional de Huracanes (NHC, en ingl\u00e9s) de Estados Unidos, se espera que Melissa golpee Jamaica entre la noche de este lunes y el martes \u00abcomo un hurac\u00e1n de gran potencia\u00bb, en base a su \u00faltimo bolet\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hurac\u00e1n, que actualmente avanza a unos 6 kil\u00f3metros por hora y experimenta vientos m\u00e1ximos sostenidos de hasta 270 kil\u00f3metros por hora, alcanzar\u00eda a Cuba el martes, al sur de Bahamas el mi\u00e9rcoles y causar\u00eda lluvias en Hait\u00ed y en la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, el presidente dominicano llam\u00f3 a la precauci\u00f3n a la poblaci\u00f3n de cuatro provincias de su pa\u00eds, situadas en el suroeste, debido a que en ellas \u00abel evento no ha terminado\u00bb, indic\u00f3 Abinader en una rueda conjunta con el director del Centro de Operaciones de Emergencias (COE), Juan Manuel M\u00e9ndez, y la directora del Instituto Dominicano de Meteorolog\u00eda (Indomet), Gloria Ceballos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El COE declar\u00f3 este domingo la alerta roja para las provincias de Pedernales, Independencia, Bahoruco y Barahona, todas ellas ubicadas en el suroeste del pa\u00eds, donde todav\u00eda se pueden producir acumulados de lluvias importantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLes pido a las provincias que est\u00e1n en rojo que tengan las precauciones de lugar\u00bb, advirti\u00f3 Abinader.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, ocho provincias se sit\u00faan en alerta amarilla y doce en verde, entre las que se encuentra la capital del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La directora del Indomet, Gloria Ceballos, destac\u00f3 que \u00abtodav\u00eda las lluvias no han pasado\u00bb y que el pa\u00eds va a tener lluvias vinculadas con el hurac\u00e1n hasta el jueves pero de menor intensidad que la que se ha producido en d\u00edas anteriores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLos acumulados de lluvia que se sigan registrando en estos d\u00edas van a ser precisamente por campos nubosos asociados al hurac\u00e1n\u00bb, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Ceballos, Melissa es un \u00abhurac\u00e1n catastr\u00f3fico\u00bb y a su formaci\u00f3n ha contribuido que las \u00abtemperaturas en el mar caribe estaban por encima de 30 grados, muy caliente para estos meses\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEra una olla de presi\u00f3n para este sistema\u00bb, afirm\u00f3 la meteor\u00f3loga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la directora del Indomet advirti\u00f3 que Hait\u00ed se mantiene \u00aben vigilancia por tormenta tropical\u00bb y que cuando Melissa se dirija hacia el sureste de Cuba, \u00abva a seguir provocando lluvias importantes\u00bb en el pa\u00eds vecino a la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, el presidente dominicano actualiz\u00f3 la cifra de da\u00f1os en el pa\u00eds, que ha reducido a 287,782 el n\u00famero de usuarios que est\u00e1n sin agua potable debido a las lluvias. Este fin de semana el n\u00famero de afectados se situaba en 1.4 millones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el director del COE, M\u00e9ndez, se\u00f1al\u00f3 en un balance de da\u00f1os que, debido al hurac\u00e1n, 757 viviendas fueron afectadas por las lluvias, 18 con da\u00f1os parciales y dos destruidas, asimismo hubo 3.785 personas afectadas que han sido distribuidas en cuatro albergues oficiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 27 oct (EFE).- El presidente de la Rep\u00fablica Dominicana, Luis Abinader, llam\u00f3 este lunes a \u00abrezar por los jamaiquinos, por Cuba y Hait\u00ed\u00bb ante el paso del hurac\u00e1n Melissa, que se encuentra actualmente a unos 200 kil\u00f3metros al suroeste de Jamaica. \u00abHay que rezar por los jamaiquinos, por esa rep\u00fablica hermana, y tambi\u00e9n por Cuba que va a ser afectada en la zona este, y tambi\u00e9n por Hait\u00ed que puede ser afectada. Que Dios los ayude y que est\u00e9n en las oraciones de todos los dominicanos\u00bb, se\u00f1al\u00f3 Abinader. Seg\u00fan el Centro Nacional de Huracanes (NHC, en ingl\u00e9s) de Estados Unidos, se espera que Melissa golpee Jamaica entre la noche de este lunes y el martes \u00abcomo un hurac\u00e1n de gran potencia\u00bb, en base a su \u00faltimo bolet\u00edn. El hurac\u00e1n, que actualmente avanza a unos 6 kil\u00f3metros por hora y experimenta vientos m\u00e1ximos sostenidos de hasta 270 kil\u00f3metros por hora, alcanzar\u00eda a Cuba el martes, al sur de Bahamas el mi\u00e9rcoles y causar\u00eda lluvias en Hait\u00ed y en la Rep\u00fablica Dominicana. En ese sentido, el presidente dominicano llam\u00f3 a la precauci\u00f3n a la poblaci\u00f3n de cuatro provincias de su pa\u00eds, situadas en el suroeste, debido a que en ellas \u00abel evento no ha terminado\u00bb, indic\u00f3 Abinader en una rueda conjunta con el director del Centro de Operaciones de Emergencias (COE), Juan Manuel M\u00e9ndez, y la directora del Instituto Dominicano de Meteorolog\u00eda (Indomet), Gloria Ceballos. El COE declar\u00f3 este domingo la alerta roja para las provincias de Pedernales, Independencia, Bahoruco y Barahona, todas ellas ubicadas en el suroeste del pa\u00eds, donde todav\u00eda se pueden producir acumulados de lluvias importantes. \u00abLes pido a las provincias que est\u00e1n en rojo que tengan las precauciones de lugar\u00bb, advirti\u00f3 Abinader. Adem\u00e1s, ocho provincias se sit\u00faan en alerta amarilla y doce en verde, entre las que se encuentra la capital del pa\u00eds. La directora del Indomet, Gloria Ceballos, destac\u00f3 que \u00abtodav\u00eda las lluvias no han pasado\u00bb y que el pa\u00eds va a tener lluvias vinculadas con el hurac\u00e1n hasta el jueves pero de menor intensidad que la que se ha producido en d\u00edas anteriores. \u00abLos acumulados de lluvia que se sigan registrando en estos d\u00edas van a ser precisamente por campos nubosos asociados al hurac\u00e1n\u00bb, se\u00f1al\u00f3. Para Ceballos, Melissa es un \u00abhurac\u00e1n catastr\u00f3fico\u00bb y a su formaci\u00f3n ha contribuido que las \u00abtemperaturas en el mar caribe estaban por encima de 30 grados, muy caliente para estos meses\u00bb. \u00abEra una olla de presi\u00f3n para este sistema\u00bb, afirm\u00f3 la meteor\u00f3loga. Asimismo, la directora del Indomet advirti\u00f3 que Hait\u00ed se mantiene \u00aben vigilancia por tormenta tropical\u00bb y que cuando Melissa se dirija hacia el sureste de Cuba, \u00abva a seguir provocando lluvias importantes\u00bb en el pa\u00eds vecino a la Rep\u00fablica Dominicana. Por otro lado, el presidente dominicano actualiz\u00f3 la cifra de da\u00f1os en el pa\u00eds, que ha reducido a 287,782 el n\u00famero de usuarios que est\u00e1n sin agua potable debido a las lluvias. Este fin de semana el n\u00famero de afectados se situaba en 1.4 millones. Adem\u00e1s, el director del COE, M\u00e9ndez, se\u00f1al\u00f3 en un balance de da\u00f1os que, debido al hurac\u00e1n, 757 viviendas fueron afectadas por las lluvias, 18 con da\u00f1os parciales y dos destruidas, asimismo hubo 3.785 personas afectadas que han sido distribuidas en cuatro albergues oficiales.<\/p>\n","protected":false},"author":9,"featured_media":108612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-108611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=108611"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108611\/revisions"}],"predecessor-version":[{"id":108613,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108611\/revisions\/108613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/108612"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=108611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=108611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=108611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}