{"id":10869,"date":"2014-11-25T16:09:18","date_gmt":"2014-11-25T20:09:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=10869"},"modified":"2014-11-26T10:24:28","modified_gmt":"2014-11-26T14:24:28","slug":"ottt-y-choferes-acuerdan-bajar-pasajes-desde-manana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ottt-y-choferes-acuerdan-bajar-pasajes-desde-manana\/","title":{"rendered":"OTTT y choferes acuerdan bajar pasajes desde ma\u00f1ana"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/choferes_pasaje_fg_210_120.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10977 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/choferes_pasaje_fg_210_120.jpeg\" alt=\"choferes_pasaje_fg_210_120\" width=\"210\" height=\"120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/choferes_pasaje_fg_210_120.jpeg 210w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/11\/choferes_pasaje_fg_210_120-595x340.jpeg 595w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a>A partir de ma\u00f1ana se producir\u00e1n rebajas en las tarifas de los pasajes de las rutas urbanas e interurbanas, de entre 5 pesos en urbano, y 10 y 20 pesos interurbano, sobre todo en los veh\u00edculos del transporte p\u00fablico que utilizan gasoil.<!--more--><\/p>\n<p>No obstante, el director de la OTTT, H\u00e9ctor Mojica, sostuvo ayer que estas rebajas deber\u00e1n ser asimiladas por quienes son subsidiados por el Gobierno.<\/p>\n<p>La decisi\u00f3n fue consensuada entre la Oficina T\u00e9cnica de Transporte Terrestre (OTTT) y un importante grupo de dirigentes choferiles, encabezados por Antonio Marte, presidente de la Confederaci\u00f3n Nacional de Organizaciones del Transporte (Conatra); Alfredo Pulinario Linares, de la Central Nacional Movimiento Choferil de Transporte; y Juan Marte, del Sindicato Nacional de Trabajadores del Transporte (CNTT), de Santiago, entre otros.<\/p>\n<p>Aunque se quejaron de que las distintas rebajas aplicadas semanalmente por el Gobierno a los precios de los combustibles no compensan las p\u00e9rdidas que tiene el sector transporte, todos se mostraron de acuerdo en que la concertaci\u00f3n a la que se hab\u00eda arribado, es un inicio que busca disminuir los costos a la poblaci\u00f3n que paga pasajes.<\/p>\n<p>Todav\u00eda quedan muchos puntos por definir, adem\u00e1s del concurso de Juan Hubieres y la Federaci\u00f3n Nacional de Transporte la Nueva Opci\u00f3n (Fenatrano), que estuvo ausente de la reuni\u00f3n en la que se logr\u00f3 el acuerdo.<\/p>\n<p>Para Ram\u00f3n P\u00e9rez Figuereo, presidente de la Central Nacional de Transportistas Unificados (CNTU), lo importante es que se trat\u00f3 de un di\u00e1logo de acercamiento en el que se buscan salidas para beneficiar a la poblaci\u00f3n. Dijo, sin embargo, que en el transporte urbano 98% utiliza el Gas Licuado de Petr\u00f3leo (GLP), como combustible. \u201cEl caso del GLP hay que buscarle una soluci\u00f3n, pero en otro momento\u201d, dijo.<\/p>\n<p>Juan Marte, de Santiago, coincidi\u00f3 con P\u00e9rez Figuereo en que 98% de los veh\u00edculos del transporte urbano opera con el GLP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de ma\u00f1ana se producir\u00e1n rebajas en las tarifas de los pasajes de las rutas urbanas e interurbanas, de entre 5 pesos en urbano, y 10 y 20 pesos interurbano, sobre todo en los veh\u00edculos del transporte p\u00fablico que utilizan gasoil.<\/p>\n","protected":false},"author":3,"featured_media":10977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-10869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=10869"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10869\/revisions"}],"predecessor-version":[{"id":10979,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/10869\/revisions\/10979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/10977"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=10869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=10869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=10869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}