{"id":108700,"date":"2025-11-02T06:26:21","date_gmt":"2025-11-02T10:26:21","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=108700"},"modified":"2025-11-02T06:26:23","modified_gmt":"2025-11-02T10:26:23","slug":"autoridades-alertan-a-poblacion-de-posibles-inundaciones-urbanas-por-efectos-de-onda-tropical","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/autoridades-alertan-a-poblacion-de-posibles-inundaciones-urbanas-por-efectos-de-onda-tropical\/","title":{"rendered":"Autoridades alertan a poblaci\u00f3n de posibles inundaciones urbanas por efectos de onda tropical"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"627\" height=\"300\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/68fbd0cae496d.jpeg\" alt=\"\" class=\"wp-image-108701\" style=\"width:311px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/68fbd0cae496d.jpeg 627w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/68fbd0cae496d-300x144.jpeg 300w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" id=\"m73688-73687-73689\">Una vaguada pre frontal junto a una onda tropical continuar\u00e1 generando lluvias en parte del territorio nacional, por lo que el Centro de Operaciones de Emergencias (COE) llam\u00f3 a la poblaci\u00f3n a estar atenta ante posibles inundaciones urbanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m73693-73692-73694\">El director del COE, Juan Manuel M\u00e9ndez, dijo en una rueda de prensa que&nbsp;<strong>se esperan fuertes lluvias<\/strong>&nbsp;para este domingo, luego de que el eje de este fen\u00f3meno se establezca sobre el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m73698-73697-73699\">M\u00e9ndez indic\u00f3 que ante la saturaci\u00f3n del suelo por las lluvias que dej\u00f3 la tormenta Melissa y las inundaciones que ocurren en el Gran Santo Domingo, la ciudadan\u00eda debe permanecer en alerta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m73703-73702-73704\">\u201cA pesar de que habr\u00e1 menos movilidad porque es de noche y la madrugada, pero no obstante a ello,&nbsp;<strong>hay que tomar todas las precauciones del mundo<\/strong>. La poblaci\u00f3n no se puede descuidar. Ya las lluvias han provocado situaciones severas en algunas de las provincias que hemos tenido en alerta y en el caso del Gran Santo Domingo hay que estar bastante pendientes con las inundaciones urbanas y con los deslizamientos de tierra\u201d, explic\u00f3 el titular del COE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m73708-73707-73709\">Asimismo, manifest\u00f3 que el COE activ\u00f3 todos los protocolos<strong>&nbsp;\u201cen su m\u00e1xima expresi\u00f3n\u201d.<\/strong>&nbsp;Adem\u00e1s, llam\u00f3 a la poblaci\u00f3n a dar seguimiento a los alineamientos de la instituci\u00f3n y las instituciones competentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m73713-73712-73714\">Por su parte, la directora del Instituto Dominicano de Meteorolog\u00eda (Indomet) indic\u00f3 que la onda tropical se estar\u00eda desplazando r\u00e1pidamente, pero dejar\u00e1 acumulados de lluvia que podr\u00edan alcanzar los 100 mil\u00edmetros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m73718-73717-73719\">El COE elev\u00f3 a ocho provincias en alerta amarilla, y una en roja por la vaguada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m73723-73722-73724\">En amarilla est\u00e1n Santo Domingo, Monte Plata, San Pedro de Macor\u00eds, La Romana, La Altagracia, Peravia, San Crist\u00f3bal y el Distrito Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m73728-73727-73729\">Mientras que en verde est\u00e1n Duarte, Monse\u00f1or Nouel, Azua, San Juan, Puerto Plata, Bahoruco, Barahona, Pedernales, Independencia, Santiago, Valverde, Santiago Rodr\u00edguez, Dajab\u00f3n y Monte Cristi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una vaguada pre frontal junto a una onda tropical continuar\u00e1 generando lluvias en parte del territorio nacional, por lo que el Centro de Operaciones de Emergencias (COE) llam\u00f3 a la poblaci\u00f3n a estar atenta ante posibles inundaciones urbanas. El director del COE, Juan Manuel M\u00e9ndez, dijo en una rueda de prensa que&nbsp;se esperan fuertes lluvias&nbsp;para este domingo, luego de que el eje de este fen\u00f3meno se establezca sobre el pa\u00eds. M\u00e9ndez indic\u00f3 que ante la saturaci\u00f3n del suelo por las lluvias que dej\u00f3 la tormenta Melissa y las inundaciones que ocurren en el Gran Santo Domingo, la ciudadan\u00eda debe permanecer en alerta. \u201cA pesar de que habr\u00e1 menos movilidad porque es de noche y la madrugada, pero no obstante a ello,&nbsp;hay que tomar todas las precauciones del mundo. La poblaci\u00f3n no se puede descuidar. Ya las lluvias han provocado situaciones severas en algunas de las provincias que hemos tenido en alerta y en el caso del Gran Santo Domingo hay que estar bastante pendientes con las inundaciones urbanas y con los deslizamientos de tierra\u201d, explic\u00f3 el titular del COE. Asimismo, manifest\u00f3 que el COE activ\u00f3 todos los protocolos&nbsp;\u201cen su m\u00e1xima expresi\u00f3n\u201d.&nbsp;Adem\u00e1s, llam\u00f3 a la poblaci\u00f3n a dar seguimiento a los alineamientos de la instituci\u00f3n y las instituciones competentes. Por su parte, la directora del Instituto Dominicano de Meteorolog\u00eda (Indomet) indic\u00f3 que la onda tropical se estar\u00eda desplazando r\u00e1pidamente, pero dejar\u00e1 acumulados de lluvia que podr\u00edan alcanzar los 100 mil\u00edmetros.&nbsp; El COE elev\u00f3 a ocho provincias en alerta amarilla, y una en roja por la vaguada.&nbsp; En amarilla est\u00e1n Santo Domingo, Monte Plata, San Pedro de Macor\u00eds, La Romana, La Altagracia, Peravia, San Crist\u00f3bal y el Distrito Nacional. Mientras que en verde est\u00e1n Duarte, Monse\u00f1or Nouel, Azua, San Juan, Puerto Plata, Bahoruco, Barahona, Pedernales, Independencia, Santiago, Valverde, Santiago Rodr\u00edguez, Dajab\u00f3n y Monte Cristi.<\/p>\n","protected":false},"author":9,"featured_media":108701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-108700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=108700"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108700\/revisions"}],"predecessor-version":[{"id":108702,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108700\/revisions\/108702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/108701"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=108700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=108700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=108700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}