{"id":108709,"date":"2025-11-03T06:05:14","date_gmt":"2025-11-03T10:05:14","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=108709"},"modified":"2025-11-03T06:05:15","modified_gmt":"2025-11-03T10:05:15","slug":"inician-operativos-migratorios-nocturnos-en-toda-rep-dom","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/inician-operativos-migratorios-nocturnos-en-toda-rep-dom\/","title":{"rendered":"Inician \u00aboperativos migratorios nocturnos\u00bb en toda Rep. Dom."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1002\" height=\"680\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/Operativo-migratorio-nocturno-e1762161391182.jpeg\" alt=\"\" class=\"wp-image-108710\" style=\"width:285px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/Operativo-migratorio-nocturno-e1762161391182.jpeg 1002w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/Operativo-migratorio-nocturno-e1762161391182-300x204.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/Operativo-migratorio-nocturno-e1762161391182-768x521.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/Operativo-migratorio-nocturno-e1762161391182-75x52.jpeg 75w\" sizes=\"auto, (max-width: 1002px) 100vw, 1002px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 2 nov .- La Direcci\u00f3n General de Migraci\u00f3n (DGM) inform\u00f3 este domingo que ha iniciado operaciones nocturnas para \u00abfortalecer los controles migratorios en el territorio nacional y, al mismo tiempo, brindar apoyo a las autoridades en materia de seguridad ciudadana\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado, la DGM apunt\u00f3 que \u00abesto aumenta la ofensiva contra la presencia de extranjeros en condici\u00f3n irregular en las v\u00edas y lugares p\u00fablicos, principalmente en las avenidas, intersecciones y zonas de alta circulaci\u00f3n del Distrito Nacional y Santo Domingo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El organismo explic\u00f3 que la estrategia consiste en reforzar la presencia visible y operativa de agentes migratorios debidamente uniformados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada equipo operativo est\u00e1 conformado por siete miembros, distribuidos en una camioneta y un cami\u00f3n, con la supervisi\u00f3n de un oficial coordinador \u00abque vela por el cumplimiento de los protocolos institucionales y el respeto de los derechos humanos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>OPERACIONES DIARIAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las operaciones, explic\u00f3 la instituci\u00f3n, se desarrollan todos los d\u00edas, con una mayor intensidad los fines de semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De viernes a domingo, los agentes permanecer\u00e1n en las calles hasta la madrugada, verificando la presencia de extranjeros en situaci\u00f3n migratoria irregular, que son conducidos a los centros de procesamiento migratorio, a\u00f1adi\u00f3 Migraci\u00f3n en el comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se\u00f1al\u00f3, mantiene puntos de observaci\u00f3n fijos en esquinas de sem\u00e1foros, paradas de motoconchos y taxis, donde se ha reportado con mayor frecuencia la presencia de individuos dedicados a la mendicidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">RECIBEN \u00abSOLICITUDES DE INTERVENCI\u00d3N\u00bb A TRAV\u00c9S DE L\u00cdNEA 211<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La DGM revel\u00f3 que la l\u00ednea 311, de \u00abAtenci\u00f3n al Usuario\u00bb es uno de los principales canales por los cuales se est\u00e1n recibiendo denuncias y solicitudes de intervenci\u00f3n cuando se sospecha de extranjeros indocumentados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios de octubre de 2024, el Gobierno anunci\u00f3 el objetivo de repatriar hasta 10,000 indocumentados por semana para reducir el exceso de poblaci\u00f3n migrante que se percibe en las comunidades dominicanas, una medida que afecta especialmente a los haitianos, cuyo pa\u00eds enfrenta una aguda y prolongada crisis que solo en este a\u00f1o oblig\u00f3 a 1.4 millones de personas a abandonar sus hogares.EFE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">mf<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 2 nov .- La Direcci\u00f3n General de Migraci\u00f3n (DGM) inform\u00f3 este domingo que ha iniciado operaciones nocturnas para \u00abfortalecer los controles migratorios en el territorio nacional y, al mismo tiempo, brindar apoyo a las autoridades en materia de seguridad ciudadana\u00bb. En un comunicado, la DGM apunt\u00f3 que \u00abesto aumenta la ofensiva contra la presencia de extranjeros en condici\u00f3n irregular en las v\u00edas y lugares p\u00fablicos, principalmente en las avenidas, intersecciones y zonas de alta circulaci\u00f3n del Distrito Nacional y Santo Domingo\u00bb. El organismo explic\u00f3 que la estrategia consiste en reforzar la presencia visible y operativa de agentes migratorios debidamente uniformados. Cada equipo operativo est\u00e1 conformado por siete miembros, distribuidos en una camioneta y un cami\u00f3n, con la supervisi\u00f3n de un oficial coordinador \u00abque vela por el cumplimiento de los protocolos institucionales y el respeto de los derechos humanos\u00bb. OPERACIONES DIARIAS Las operaciones, explic\u00f3 la instituci\u00f3n, se desarrollan todos los d\u00edas, con una mayor intensidad los fines de semana. De viernes a domingo, los agentes permanecer\u00e1n en las calles hasta la madrugada, verificando la presencia de extranjeros en situaci\u00f3n migratoria irregular, que son conducidos a los centros de procesamiento migratorio, a\u00f1adi\u00f3 Migraci\u00f3n en el comunicado. Adem\u00e1s, se\u00f1al\u00f3, mantiene puntos de observaci\u00f3n fijos en esquinas de sem\u00e1foros, paradas de motoconchos y taxis, donde se ha reportado con mayor frecuencia la presencia de individuos dedicados a la mendicidad. RECIBEN \u00abSOLICITUDES DE INTERVENCI\u00d3N\u00bb A TRAV\u00c9S DE L\u00cdNEA 211 La DGM revel\u00f3 que la l\u00ednea 311, de \u00abAtenci\u00f3n al Usuario\u00bb es uno de los principales canales por los cuales se est\u00e1n recibiendo denuncias y solicitudes de intervenci\u00f3n cuando se sospecha de extranjeros indocumentados. A principios de octubre de 2024, el Gobierno anunci\u00f3 el objetivo de repatriar hasta 10,000 indocumentados por semana para reducir el exceso de poblaci\u00f3n migrante que se percibe en las comunidades dominicanas, una medida que afecta especialmente a los haitianos, cuyo pa\u00eds enfrenta una aguda y prolongada crisis que solo en este a\u00f1o oblig\u00f3 a 1.4 millones de personas a abandonar sus hogares.EFE mf<\/p>\n","protected":false},"author":9,"featured_media":108710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-108709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=108709"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108709\/revisions"}],"predecessor-version":[{"id":108711,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108709\/revisions\/108711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/108710"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=108709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=108709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=108709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}