{"id":108891,"date":"2025-11-10T06:59:17","date_gmt":"2025-11-10T10:59:17","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=108891"},"modified":"2025-11-10T06:59:19","modified_gmt":"2025-11-10T10:59:19","slug":"gobierno-registra-devengado-el-88-de-sus-gastos-corrientes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gobierno-registra-devengado-el-88-de-sus-gastos-corrientes\/","title":{"rendered":"Gobierno registra devengado el 88% de sus gastos corrientes"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/642ea41cbf76c.jpeg\" alt=\"\" class=\"wp-image-108892\" style=\"width:268px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/642ea41cbf76c.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/642ea41cbf76c-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/642ea41cbf76c-768x513.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" id=\"m141723-141722-141724\">Del presupuesto general a la fecha, el Gobierno ha ejecutado el 75% como gasto y, en el caso de los gastos corrientes que son aquellos destinados a n\u00f3mina (remuneraciones), consumo y transferencias, entre otros, registra egresos del 88%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141728-141727-141729\">De acuerdo a los datos oficiales, del 1 de enero al 31 de octubre de este a\u00f1o 2025, el Gobierno ha devengado RD$1,184,187.2 millones como gastos y de estos RD$1,043.223.0 son gastos corrientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141733-141732-141734\">Un gasto devengado es cuando se asume el compromiso de pago y se registra en t\u00e9rminos contables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141738-141737-141739\">Del total de gastos corrientes, se han fijado compromisos de gastos por RD$394,259.7 millones que han sido destinados solamente para consumo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141743-141742-141744\">Por ejemplo, en remuneraciones y contrataciones se registran RD$98,837.0 millones, RD$78,538.2 millones para sobresueldos y RD$10,286.4 millones para gastos de representaci\u00f3n. Otros gastos se destinan a consumo mediante gratificaciones y bonificaciones, contrataciones de servicios, materiales y suministros, seguros, alquileres y renta y gastos financieros, as\u00ed como para obras edificadas, y muebles e inmuebles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141748-141747-141749\">El gasto corriente de 2025 supera por mucho la asignaci\u00f3n presupuestaria orientada a gasto de capital. En el reporte, publicado en el portal oficial de la Direcci\u00f3n General de Presupuesto (Digepres) el monto registrado como devengado es de RD$10,964.2 millones del 1 de enero al 31 de octubre 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141753-141752-141754\">Para este a\u00f1o 2025 el presupuesto nacional vigente asciende a RD$1,664,251.1 millones. A esa fecha se han devengado RD$1,253.080.3 millones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141758-141757-141759\">Como parte de los compromisos se incluyen RD$228,633.9 millones destinados al pago de los intereses de la deuda p\u00fablica, RD$108,120.5 millones para aplicaciones financieras, y RD$207,835.3 millones para gastos de capital, de los cuales se han comprometido a pagar los RD$140,964.2 millones registrados como devengados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141763-141762-141764\">Adem\u00e1s de los gastos de consumo, prestaciones a la seguridad social, intereses de deuda, subvenciones a las empresas, entre otros, los egresos corrientes incluyen transferencias corrientes, b\u00e1sicamente al sector p\u00fablico, como el es caso de las transferencias que realiza el Gobierno para subsidiar las deficiencias de las Empresas Distribuidoras de Electricidad (EDES).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141768-141767-141769\">A agosto de este mismo a\u00f1o, las transferencias a la Empresa Distribuidora del Este (Edeeste) ascendi\u00f3 a RD$8,439 millones; a Edenorte RD$7,288.2 millones, mientras que a Eedsur el monto transferido fue de RD$4,418.2 millones. Hasta ahora, las justificaciones que se han dado es de que se transfieren esos fondos a las Edes para evitar afectar m\u00e1s a los sectores m\u00e1s vulnerables con el precio de la electricidad, pero las quejas de altas facturaciones no cesan, como tampoco las interrupciones del suministro de energ\u00eda, situaci\u00f3n que sectores especializados en temas energ\u00e9ticos atribuyen a falta de inversiones en medidores y en plantas de menor costo y a problemas de gesti\u00f3n que data de a\u00f1os, adem\u00e1s del hurto de energ\u00eda y la falta de pago en distintos sectores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">EJECUCI\u00d3N PRESUPUESTARIA<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141773-141772-141774\">Actualizada al 6 de noviembre, la data del Sistema de Gesti\u00f3n Financiera de la Informaci\u00f3n (Sigef) muestra que los ingresos alcanzaron esa fecha RD$1,044,618.4 millones y los gastos RD$1,219,627.2 millones. De estos, se ejecutaron RD$265,627.9 millones para el pago de intereses de la deuda, equivalentes a un 21.8% del total de ingresos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141778-141777-141779\">El financiamiento neto registrado fue de RD$177,930.00 millones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141783-141782-141784\">En t\u00e9rminos de inversiones en las 32 provincias, la data arroja mayores inversiones en el Distrito Nacional y Santiago, seguidos de Azua, San Crist\u00f3bal, Duarte, La Altagracia y Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141788-141787-141789\">Las provincias con menores montos de inversi\u00f3n p\u00fablica son Santiago Rodr\u00edguez, Hermanas Mirabal, Valverde, El Seibo, La Romana y Pedernales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SEPA M\u00c1S<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">OFICINAS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141793-141792-141794\">Las principales oficinas recaudadoras como son Impuestos Internos (DGII), Aduanas (DGA)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141798-141797-141799\">y la Tesorer\u00eda Nacional aportaron al fisco el 75.9%, 21.9% y 2.2%, respectivamente, al 6 de este noviembre 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141803-141802-141804\">La DGII aporta RD$898,746.1 millones, la Aduanas RD$280,623.4 millones, y la Tesorer\u00eda RD$48,104.00 millones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m141808-141807-141809\">El impuesto de mayor aporte al fisco es el ITBIS, seguido del ISR (Impuesto Sobre la Renta), impuestos a los salarios, aranceles, y a los hidrocarburos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del presupuesto general a la fecha, el Gobierno ha ejecutado el 75% como gasto y, en el caso de los gastos corrientes que son aquellos destinados a n\u00f3mina (remuneraciones), consumo y transferencias, entre otros, registra egresos del 88%. De acuerdo a los datos oficiales, del 1 de enero al 31 de octubre de este a\u00f1o 2025, el Gobierno ha devengado RD$1,184,187.2 millones como gastos y de estos RD$1,043.223.0 son gastos corrientes. Un gasto devengado es cuando se asume el compromiso de pago y se registra en t\u00e9rminos contables. Del total de gastos corrientes, se han fijado compromisos de gastos por RD$394,259.7 millones que han sido destinados solamente para consumo. Por ejemplo, en remuneraciones y contrataciones se registran RD$98,837.0 millones, RD$78,538.2 millones para sobresueldos y RD$10,286.4 millones para gastos de representaci\u00f3n. Otros gastos se destinan a consumo mediante gratificaciones y bonificaciones, contrataciones de servicios, materiales y suministros, seguros, alquileres y renta y gastos financieros, as\u00ed como para obras edificadas, y muebles e inmuebles. El gasto corriente de 2025 supera por mucho la asignaci\u00f3n presupuestaria orientada a gasto de capital. En el reporte, publicado en el portal oficial de la Direcci\u00f3n General de Presupuesto (Digepres) el monto registrado como devengado es de RD$10,964.2 millones del 1 de enero al 31 de octubre 2025. Para este a\u00f1o 2025 el presupuesto nacional vigente asciende a RD$1,664,251.1 millones. A esa fecha se han devengado RD$1,253.080.3 millones. Como parte de los compromisos se incluyen RD$228,633.9 millones destinados al pago de los intereses de la deuda p\u00fablica, RD$108,120.5 millones para aplicaciones financieras, y RD$207,835.3 millones para gastos de capital, de los cuales se han comprometido a pagar los RD$140,964.2 millones registrados como devengados. Adem\u00e1s de los gastos de consumo, prestaciones a la seguridad social, intereses de deuda, subvenciones a las empresas, entre otros, los egresos corrientes incluyen transferencias corrientes, b\u00e1sicamente al sector p\u00fablico, como el es caso de las transferencias que realiza el Gobierno para subsidiar las deficiencias de las Empresas Distribuidoras de Electricidad (EDES). A agosto de este mismo a\u00f1o, las transferencias a la Empresa Distribuidora del Este (Edeeste) ascendi\u00f3 a RD$8,439 millones; a Edenorte RD$7,288.2 millones, mientras que a Eedsur el monto transferido fue de RD$4,418.2 millones. Hasta ahora, las justificaciones que se han dado es de que se transfieren esos fondos a las Edes para evitar afectar m\u00e1s a los sectores m\u00e1s vulnerables con el precio de la electricidad, pero las quejas de altas facturaciones no cesan, como tampoco las interrupciones del suministro de energ\u00eda, situaci\u00f3n que sectores especializados en temas energ\u00e9ticos atribuyen a falta de inversiones en medidores y en plantas de menor costo y a problemas de gesti\u00f3n que data de a\u00f1os, adem\u00e1s del hurto de energ\u00eda y la falta de pago en distintos sectores. EJECUCI\u00d3N PRESUPUESTARIA Actualizada al 6 de noviembre, la data del Sistema de Gesti\u00f3n Financiera de la Informaci\u00f3n (Sigef) muestra que los ingresos alcanzaron esa fecha RD$1,044,618.4 millones y los gastos RD$1,219,627.2 millones. De estos, se ejecutaron RD$265,627.9 millones para el pago de intereses de la deuda, equivalentes a un 21.8% del total de ingresos. El financiamiento neto registrado fue de RD$177,930.00 millones. En t\u00e9rminos de inversiones en las 32 provincias, la data arroja mayores inversiones en el Distrito Nacional y Santiago, seguidos de Azua, San Crist\u00f3bal, Duarte, La Altagracia y Puerto Plata. Las provincias con menores montos de inversi\u00f3n p\u00fablica son Santiago Rodr\u00edguez, Hermanas Mirabal, Valverde, El Seibo, La Romana y Pedernales. SEPA M\u00c1S OFICINAS Las principales oficinas recaudadoras como son Impuestos Internos (DGII), Aduanas (DGA) y la Tesorer\u00eda Nacional aportaron al fisco el 75.9%, 21.9% y 2.2%, respectivamente, al 6 de este noviembre 2025. La DGII aporta RD$898,746.1 millones, la Aduanas RD$280,623.4 millones, y la Tesorer\u00eda RD$48,104.00 millones. El impuesto de mayor aporte al fisco es el ITBIS, seguido del ISR (Impuesto Sobre la Renta), impuestos a los salarios, aranceles, y a los hidrocarburos.<\/p>\n","protected":false},"author":9,"featured_media":108892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-108891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=108891"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108891\/revisions"}],"predecessor-version":[{"id":108893,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/108891\/revisions\/108893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/108892"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=108891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=108891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=108891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}