{"id":109091,"date":"2025-11-21T16:16:43","date_gmt":"2025-11-21T20:16:43","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=109091"},"modified":"2025-11-21T16:16:45","modified_gmt":"2025-11-21T20:16:45","slug":"torneo-de-softbol-de-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/torneo-de-softbol-de-sosua\/","title":{"rendered":"Torneo de Softbol de Sos\u00faa"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"606\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/torneo-de-softbal-de-sosua-1024x606.jpg\" alt=\"\" class=\"wp-image-109092\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/torneo-de-softbal-de-sosua-1024x606.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/torneo-de-softbal-de-sosua-300x178.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/torneo-de-softbal-de-sosua-768x454.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/torneo-de-softbal-de-sosua.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Batey, Sos\u00faa.-<\/strong> Con el apoyo del Ayuntamiento de Sos\u00faa, la comunidad deportiva se prepar\u00f3 para el Gran Torneo Interbarrial de Softbol Sos\u00faa 2025, un evento que busca fortalecer la integraci\u00f3n social, el deporte y el entretenimiento sano en los barrios del municipio.<br \/><br \/>La ceremonia de inauguraci\u00f3n tuvo lugar el mi\u00e9rcoles 12 de noviembre a las 6:45 p. m. en el campo de b\u00e9isbol El Batey, con una gran asistencia de aficionados, atletas y familias de toda la regi\u00f3n. Cinco equipos de Sos\u00faa, representantes de los barrios de Los Castillos, La Uni\u00f3n, Sos\u00faa Abajo Maranatha, Cabarete, Los Charamicos y El Batey, participar\u00e1n en el torneo.<br \/><br \/>El evento deportivo estar\u00e1 dirigido por Juan Rosario (Pachuli), Director de Deportes de la Alcald\u00eda de Sos\u00faa, quien destac\u00f3 la importancia de estas actividades para promover el esp\u00edritu comunitario y la deportividad en el municipio. Diario Papeleta represent\u00f3 al Ayuntamiento de Sos\u00faa y reafirm\u00f3 el compromiso del gobierno local con la promoci\u00f3n del deporte y el apoyo a las iniciativas comunitarias que fomentan una sociedad saludable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edwin Carela represent\u00f3 a Cabarete. El Torneo Vecinal de Softbol de Sos\u00faa reafirma la posici\u00f3n de Sos\u00faa como una comunidad activa y comprometida con el desarrollo deportivo.<br \/><br \/>Los organizadores invitan a residentes y visitantes a disfrutar de este fant\u00e1stico evento lleno de emoci\u00f3n, compa\u00f1erismo y deportividad junto a sus familias.<br \/>A\u00fan no se ha publicado el calendario de partidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Batey, Sos\u00faa.- Con el apoyo del Ayuntamiento de Sos\u00faa, la comunidad deportiva se prepar\u00f3 para el Gran Torneo Interbarrial de Softbol Sos\u00faa 2025, un evento que busca fortalecer la integraci\u00f3n social, el deporte y el entretenimiento sano en los barrios del municipio. La ceremonia de inauguraci\u00f3n tuvo lugar el mi\u00e9rcoles 12 de noviembre a las 6:45 p. m. en el campo de b\u00e9isbol El Batey, con una gran asistencia de aficionados, atletas y familias de toda la regi\u00f3n. Cinco equipos de Sos\u00faa, representantes de los barrios de Los Castillos, La Uni\u00f3n, Sos\u00faa Abajo Maranatha, Cabarete, Los Charamicos y El Batey, participar\u00e1n en el torneo. El evento deportivo estar\u00e1 dirigido por Juan Rosario (Pachuli), Director de Deportes de la Alcald\u00eda de Sos\u00faa, quien destac\u00f3 la importancia de estas actividades para promover el esp\u00edritu comunitario y la deportividad en el municipio. Diario Papeleta represent\u00f3 al Ayuntamiento de Sos\u00faa y reafirm\u00f3 el compromiso del gobierno local con la promoci\u00f3n del deporte y el apoyo a las iniciativas comunitarias que fomentan una sociedad saludable. Edwin Carela represent\u00f3 a Cabarete. El Torneo Vecinal de Softbol de Sos\u00faa reafirma la posici\u00f3n de Sos\u00faa como una comunidad activa y comprometida con el desarrollo deportivo. Los organizadores invitan a residentes y visitantes a disfrutar de este fant\u00e1stico evento lleno de emoci\u00f3n, compa\u00f1erismo y deportividad junto a sus familias.A\u00fan no se ha publicado el calendario de partidos.<\/p>\n","protected":false},"author":12,"featured_media":109092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,3],"tags":[],"class_list":["post-109091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=109091"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109091\/revisions"}],"predecessor-version":[{"id":109093,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109091\/revisions\/109093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/109092"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=109091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=109091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=109091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}