{"id":109146,"date":"2025-11-25T06:21:08","date_gmt":"2025-11-25T10:21:08","guid":{"rendered":"https:\/\/sosuaonline.net\/inicio\/?p=109146"},"modified":"2025-11-25T06:21:10","modified_gmt":"2025-11-25T10:21:10","slug":"abinader-dice-hay-cosas-de-las-que-danilo-no-deberia-hablar","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/abinader-dice-hay-cosas-de-las-que-danilo-no-deberia-hablar\/","title":{"rendered":"Abinader dice hay cosas de las que Danilo no deber\u00eda hablar"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"813\" height=\"548\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/lA-sEMANAL-NAVIDENA.jpg\" alt=\"\" class=\"wp-image-109147\" style=\"width:309px;height:auto\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/lA-sEMANAL-NAVIDENA.jpg 813w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/lA-sEMANAL-NAVIDENA-300x202.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/lA-sEMANAL-NAVIDENA-768x518.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2025\/11\/lA-sEMANAL-NAVIDENA-75x52.jpg 75w\" sizes=\"auto, (max-width: 813px) 100vw, 813px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.-&nbsp;El presidente Luis Abinader&nbsp;refut\u00f3&nbsp;este lunes&nbsp;lo dicho por el&nbsp;&nbsp;expresidente Danilo Medina&nbsp;de&nbsp;que la actual administraci\u00f3n \u201csolo pint\u00f3\u201d la c\u00e1rcel Las Parras porque el gobierno del Partido de la Liberaci\u00f3n Dominicana (PLD) la&nbsp;&nbsp;hab\u00eda inaugurado en 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSobre Las Parras, yo pienso que hay temas que no deber\u00edan hablar ciertas personas, eso est\u00e1 muy claro. Roberto Santana, siendo asesor de la reforma penitenciaria y ahora director de Prisiones, es quien se encarg\u00f3 de todo ese proceso\u00bb, manifest\u00f3&nbsp;en la rueda de prensa \u201cLa Semanal\u201d &nbsp;que ofrece todos los&nbsp;lunes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abinader sostuvo que el proceso de terminaci\u00f3n del recinto penitenciario&nbsp;fue&nbsp;dirigido&nbsp;durante la actual administraci\u00f3n&nbsp;&nbsp;por el propio Santana, asesor de la reforma penitenciaria y actual director de Prisiones, en coordinaci\u00f3n con una comisi\u00f3n especializada, integrada por muchas personalidades, entre ellas decanos de universidades, quienes&nbsp; determinaron c\u00f3mo deb\u00eda concluirse esa c\u00e1rcel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que dicha comisi\u00f3n \u201cbien extensa\u201d conoce en detalle el presupuesto y la ejecuci\u00f3n de la obra bajo criterios t\u00e9cnicos,&nbsp; no pol\u00edticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CAPACIDAD PARA M\u00c1S DE 7 MIL RECLUSOS&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La c\u00e1rcel fue levantada en el municipio de San Antonio de Guerra, provincia de Santo Domingo y, seg\u00fan las autoridades, tiene capacidad para&nbsp;m\u00e1s de 7,000 reclusos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su construcci\u00f3n fue paralizada&nbsp;<strong>en el \u00f1o 2020&nbsp;<\/strong>en los inicios del primer per\u00edodo del Presidente Abinader,&nbsp;<strong>luego&nbsp;<\/strong>&nbsp;de que el exprocurador Jean Alain Rodr\u00edguez fuese acusado de presunta corrupci\u00f3n. Esto dio lugar a que el Ministerio P\u00fablico considerara la c\u00e1rcel de Las Parras como una de las presuntas pruebas de corrupci\u00f3n contra Rodr\u00edguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">an\/am\/sp<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-&nbsp;El presidente Luis Abinader&nbsp;refut\u00f3&nbsp;este lunes&nbsp;lo dicho por el&nbsp;&nbsp;expresidente Danilo Medina&nbsp;de&nbsp;que la actual administraci\u00f3n \u201csolo pint\u00f3\u201d la c\u00e1rcel Las Parras porque el gobierno del Partido de la Liberaci\u00f3n Dominicana (PLD) la&nbsp;&nbsp;hab\u00eda inaugurado en 2020. \u201cSobre Las Parras, yo pienso que hay temas que no deber\u00edan hablar ciertas personas, eso est\u00e1 muy claro. Roberto Santana, siendo asesor de la reforma penitenciaria y ahora director de Prisiones, es quien se encarg\u00f3 de todo ese proceso\u00bb, manifest\u00f3&nbsp;en la rueda de prensa \u201cLa Semanal\u201d &nbsp;que ofrece todos los&nbsp;lunes Abinader sostuvo que el proceso de terminaci\u00f3n del recinto penitenciario&nbsp;fue&nbsp;dirigido&nbsp;durante la actual administraci\u00f3n&nbsp;&nbsp;por el propio Santana, asesor de la reforma penitenciaria y actual director de Prisiones, en coordinaci\u00f3n con una comisi\u00f3n especializada, integrada por muchas personalidades, entre ellas decanos de universidades, quienes&nbsp; determinaron c\u00f3mo deb\u00eda concluirse esa c\u00e1rcel. A\u00f1adi\u00f3 que dicha comisi\u00f3n \u201cbien extensa\u201d conoce en detalle el presupuesto y la ejecuci\u00f3n de la obra bajo criterios t\u00e9cnicos,&nbsp; no pol\u00edticos. CAPACIDAD PARA M\u00c1S DE 7 MIL RECLUSOS&nbsp; La c\u00e1rcel fue levantada en el municipio de San Antonio de Guerra, provincia de Santo Domingo y, seg\u00fan las autoridades, tiene capacidad para&nbsp;m\u00e1s de 7,000 reclusos. Su construcci\u00f3n fue paralizada&nbsp;en el \u00f1o 2020&nbsp;en los inicios del primer per\u00edodo del Presidente Abinader,&nbsp;luego&nbsp;&nbsp;de que el exprocurador Jean Alain Rodr\u00edguez fuese acusado de presunta corrupci\u00f3n. Esto dio lugar a que el Ministerio P\u00fablico considerara la c\u00e1rcel de Las Parras como una de las presuntas pruebas de corrupci\u00f3n contra Rodr\u00edguez. an\/am\/sp<\/p>\n","protected":false},"author":9,"featured_media":109147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-109146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=109146"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109146\/revisions"}],"predecessor-version":[{"id":109148,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/109146\/revisions\/109148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/109147"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=109146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=109146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=109146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}